
{"id":1121,"date":"2019-09-19T19:19:33","date_gmt":"2019-09-19T22:19:33","guid":{"rendered":"http:\/\/kennedyadminisiones.com\/?page_id=2"},"modified":"2026-02-02T20:48:34","modified_gmt":"2026-02-02T20:48:34","slug":"inicio","status":"publish","type":"page","link":"https:\/\/sic.nodscloud.com\/nodsglobal\/","title":{"rendered":"Neotel"},"content":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbyes\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][rev_slider_vc alias=\u00bbhome\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb el_class=\u00bbfirst-row-home\u00bb][vc_column width=\u00bb1\/2&#8243;]<div class='blog_slider_holder clearfix '><div class='blog_slider blog_slider_carousel' data-blogs_shown='3' data-auto_start='false'><ul class='blog_slides'><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >06<\/span><span class=\"blog_slider_month\" style= \"\">Jun<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2025\/06\/06\/7061\/\" ><\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >06<\/span><span class=\"blog_slider_month\" style= \"\">Nov<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2024\/11\/06\/tecnologia-en-regencia-de-farmacia\/\" >Tecnolog\u00eda en Regencia de Farmacia<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2024\/10\/02\/ppt-presentacion-2\/\" >PPT &#8211; Presentaci\u00f3n<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2024\/10\/02\/ppt-presentacion\/\" >PPT Presentaci\u00f3n<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2024\/10\/02\/anahuac\/\" >AN\u00c1HUAC<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">May<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2023\/05\/02\/medio-de-pago\/\" >Medio de pago<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >14<\/span><span class=\"blog_slider_month\" style= \"\">Feb<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2023\/02\/14\/capacitaciones\/\" >Capacitaciones<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >12<\/span><span class=\"blog_slider_month\" style= \"\">Ago<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2022\/08\/12\/simulador-lead\/\" >Simulador LEAD<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/plantillas\/\">Plantillas <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"318\" height=\"159\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2022\/08\/descarga-1.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2022\/08\/descarga-1.jpeg 318w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2022\/08\/descarga-1-300x150.jpeg 300w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >12<\/span><span class=\"blog_slider_month\" style= \"\">May<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2022\/05\/12\/promociones-de-mayo-impulsa\/\" >Promociones de mayo &#8211; Impulsa<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1200\" height=\"512\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png 1200w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-300x128.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-1024x437.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-768x328.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-700x299.png 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >08<\/span><span class=\"blog_slider_month\" style= \"\">Abr<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2022\/04\/08\/descuentos-para-panamenos\/\" >Descuentos para Paname\u00f1os<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1038\" height=\"576\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png 1038w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-300x166.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-1024x568.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-768x426.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-700x388.png 700w\" sizes=\"(max-width: 1038px) 100vw, 1038px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >10<\/span><span class=\"blog_slider_month\" style= \"\">Mar<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2022\/03\/10\/promocion-hasta-inicio-de-clases-marzo-abril\/\" >Promoci\u00f3n\u00a0hasta inicio de clases marzo \u2013 abril<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03.jpg 1920w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-300x169.jpg 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-1024x576.jpg 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-768x432.jpg 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-1536x864.jpg 1536w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-700x394.jpg 700w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-539x303.jpg 539w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >17<\/span><span class=\"blog_slider_month\" style= \"\">Dic<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/12\/17\/eobs-proxima-convocatoria-febrero-2022\/\" >EOBS &#8211; Proxima convocatoria Febrero 2022<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"4084\" height=\"984\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM.png 4084w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-300x72.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-1024x247.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-768x185.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-1536x370.png 1536w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-2048x493.png 2048w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/12\/EOBS-UCAM-700x169.png 700w\" sizes=\"(max-width: 4084px) 100vw, 4084px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >28<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/10\/28\/eobs-nuevos-requisitos-para-master-profesionales\/\" >EOBS &#8211; Nuevos requisitos para Master Profesionales<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"600\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png 980w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-300x184.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-768x470.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-700x429.png 700w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >25<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/10\/25\/americana-matricula-por-bloque\/\" >AMERICANA &#8211; Matricula por bloque<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1038\" height=\"576\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png 1038w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-300x166.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-1024x568.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-768x426.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-700x388.png 700w\" sizes=\"(max-width: 1038px) 100vw, 1038px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >12<\/span><span class=\"blog_slider_month\" style= \"\">Oct<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/10\/12\/impulsa-curso-de-inseminacion-en-bovinos-plan-referido\/\" >IMPULSA &#8211; curso de inseminaci\u00f3n en bovinos + plan referido<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1200\" height=\"512\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png 1200w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-300x128.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-1024x437.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-768x328.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-700x299.png 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >28<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/28\/americana-nuevos-bloques\/\" >AMERICANA &#8211; Nuevos Bloques<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1038\" height=\"576\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1.png 1038w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-300x166.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-1024x568.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-768x426.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/unnamed-1-700x388.png 700w\" sizes=\"(max-width: 1038px) 100vw, 1038px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >23<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/23\/plan-referido-impulsa\/\" >PLAN REFERIDO &#8211; IMPULSA<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1200\" height=\"512\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png 1200w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-300x128.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-1024x437.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-768x328.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-700x299.png 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >17<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/17\/eobs-nueva-fecha-en-noviembre\/\" >EOBS &#8211; Nueva fecha en Noviembre<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"600\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png 980w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-300x184.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-768x470.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-700x429.png 700w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >16<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/16\/ue-programas-sin-plazas\/\" >UE &#8211; Programas sin plazas<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo.png 1280w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-300x169.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-1024x576.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-768x432.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-700x394.png 700w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-539x303.png 539w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >13<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/13\/impulsa-presentacion-speech-estructura\/\" >IMPULSA &#8211; PRESENTACI\u00d3N \/ SPEECH \/ ESTRUCTURA<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/plantillas\/\">Plantillas \/  <\/a> <a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/sin-categoria\/\">Sin categor\u00eda <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1200\" height=\"512\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png 1200w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-300x128.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-1024x437.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-768x328.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-700x299.png 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >03<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/03\/ue-descuentos-de-septiembre\/\" >UE &#8211; Descuentos de Septiembre<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo.png 1280w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-300x169.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-1024x576.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-768x432.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-700x394.png 700w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/UEM-Logo-539x303.png 539w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">Sep<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/09\/02\/impulsa-descuentos-y-promo-2x1\/\" >IMPULSA &#8211; descuentos y promo 2&#215;1<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img decoding=\"async\" width=\"1200\" height=\"512\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa.png 1200w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-300x128.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-1024x437.png 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-768x328.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/09\/impulsa-700x299.png 700w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >25<\/span><span class=\"blog_slider_month\" style= \"\">Ago<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/08\/25\/eobs-master-oficial-ucav\/\" >EOBS &#8211; M\u00e1ster Oficial UCAV<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"600\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16.png 980w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-300x184.png 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-768x470.png 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/08\/Disen\u0303o-sin-ti\u0301tulo-16-700x429.png 700w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >02<\/span><span class=\"blog_slider_month\" style= \"\">Ago<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/08\/02\/ue-descuentos-agosto\/\" >UE &#8211; Descuentos Agosto<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles \/  <\/a> <a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso.png 600w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso-300x150.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >09<\/span><span class=\"blog_slider_month\" style= \"\">Jun<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/06\/09\/eobs-becas-y-promociones\/\" >EOBS &#8211; Becas y Promociones<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/eobs_Mesa-de-trabajo-1-copia-5.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/eobs_Mesa-de-trabajo-1-copia-5.png 600w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/eobs_Mesa-de-trabajo-1-copia-5-300x150.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >04<\/span><span class=\"blog_slider_month\" style= \"\">Jun<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/06\/04\/universidad-europea-descuentos\/\" >UE &#8211; Descuentos de Julio<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/aranceles\/\">Aranceles \/  <\/a> <a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/matricula\/\">Matricula <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso.png 600w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/06\/UE-Esta\u0301saunsolopaso-300x150.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/span><\/div><\/div><\/li><li class='item'><div class=\"item_holder\"><div class=\"blog_text_holder info_bottom\" ><div class=\"blog_text_holder_outer\"><div class=\"blog_text_date_holder\"><div itemprop=\"dateCreated\" class=\"blog_slider_date_holder entry_date updated\"><span class=\"blog_slider_day\" style= \"\" >07<\/span><span class=\"blog_slider_month\" style= \"\">May<\/span><meta itemprop=\"interactionCount\" content=\"UserComments:0\"\/><\/div><\/div><div class=\"blog_text_holder_inner\"><h3 itemprop=\"name\" class=\"blog_slider_title entry_title\" ><a itemprop=\"url\" href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/05\/07\/estructura-de-llamada\/\" >Estructura de llamada<\/a><\/h3><div class=\"blog_slider_categories\"><a itemprop=\"url\" class=\"blog_project_category\"  href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/category\/plantillas\/\">Plantillas <\/a> <\/div><\/div><\/div><\/div><div class=\"blog_image_holder\"><span class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03.jpg 1920w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-300x169.jpg 300w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-1024x576.jpg 1024w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-768x432.jpg 768w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-1536x864.jpg 1536w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-700x394.jpg 700w, https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2021\/05\/MKT-Y-COMUNICACION03-539x303.jpg 539w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/span><\/div><\/div><\/li><\/ul><\/div><\/div>[\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][vc_column_text]<\/p>\n<h3><span style=\"color: #f2cb4d;\"><strong>INFORMACI\u00d3N<\/strong><\/span><\/h3>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_widget_sidebar sidebar_id=\u00bbsidearea\u00bb][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbyes\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][rev_slider_vc alias=\u00bbhome\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb el_class=\u00bbfirst-row-home\u00bb][vc_column width=\u00bb1\/2&#8243;][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_row_inner row_type=\u00bbrow\u00bb type=\u00bbfull_width\u00bb text_align=\u00bbleft\u00bb css_animation=\u00bb\u00bb][vc_column_inner][vc_column_text] INFORMACI\u00d3N [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_widget_sidebar sidebar_id=\u00bbsidearea\u00bb][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1121","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/comments?post=1121"}],"version-history":[{"count":8,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1121\/revisions"}],"predecessor-version":[{"id":7508,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1121\/revisions\/7508"}],"wp:attachment":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media?parent=1121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}