
{"id":1263,"date":"2021-05-07T16:28:21","date_gmt":"2021-05-07T16:28:21","guid":{"rendered":"http:\/\/sic.nodscloud.com\/nodsglobal\/?page_id=1263"},"modified":"2021-06-18T17:36:49","modified_gmt":"2021-06-18T17:36:49","slug":"requisitos-lssi","status":"publish","type":"page","link":"https:\/\/sic.nodscloud.com\/nodsglobal\/requisitos-lssi\/","title":{"rendered":"Requisitos de admisi\u00f3n &#8211; LSSI"},"content":{"rendered":"<h3 align=\"left\"><b>REQUISITOS DE ADMISI\u00d3N\u00a0<\/b><\/h3>\n<p>&nbsp;<\/p>\n<p align=\"left\">Documentaci\u00f3n a presentar:<\/p>\n<p align=\"left\">1- Deben de llenar la ficha de inscripci\u00f3n:<\/p>\n<p align=\"left\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdID3ZGhxFb-C05OUwH8W-kBwwwtVf3razw6UTXlO8OjloJCw\/viewform\">FORMULARIO DE ADMISION<\/a><\/p>\n<p align=\"left\">2- <b>Si quiere tomar un curso intermedio, deben presentar su certificado del anterior. <\/b>Los cursos son seriados: nivel 1, nivel 2, etc.<\/p>\n<p align=\"left\">3- Realizar su pago para acceder al curso (el link de pago lo env\u00eda el instituto de lean)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REQUISITOS DE ADMISI\u00d3N\u00a0 &nbsp; Documentaci\u00f3n a presentar: 1- Deben de llenar la ficha de inscripci\u00f3n: FORMULARIO DE ADMISION 2- Si quiere tomar un curso intermedio, deben presentar su certificado del anterior. Los cursos son seriados: nivel 1, nivel 2, etc. 3- Realizar su pago para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1263","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/comments?post=1263"}],"version-history":[{"count":9,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1263\/revisions"}],"predecessor-version":[{"id":1749,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1263\/revisions\/1749"}],"wp:attachment":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media?parent=1263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}