
{"id":1464,"date":"2021-05-12T15:03:25","date_gmt":"2021-05-12T15:03:25","guid":{"rendered":"https:\/\/sic.nodscloud.com\/nodsglobal\/?page_id=1464"},"modified":"2023-05-09T17:55:47","modified_gmt":"2023-05-09T17:55:47","slug":"portfolio-academico-ue","status":"publish","type":"page","link":"https:\/\/sic.nodscloud.com\/nodsglobal\/portfolio-academico-ue\/","title":{"rendered":"Portfolio acad\u00e9mico &#8211; UE"},"content":{"rendered":"<p align=\"center\"><span style=\"font-size: xx-large;\"><b>PORTAFOLIO<\/b><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: xx-large;\"><b>UNIVERSIDAD EUROPEA<\/b><\/span><\/p>\n<h3 align=\"center\"><\/h3>\n<h3 align=\"center\"><\/h3>\n<h3 align=\"center\"><\/h3>\n<h3 style=\"text-align: left;\" align=\"center\"><span style=\"font-size: medium;\"><b>\u00bfPor qu\u00e9 estudiar en la Universidad Europea?<\/b><\/span><\/h3>\n<ul>\n<li><span style=\"font-size: medium;\">Universidad referente en Europa con m\u00e1s prestigio.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Tercera mejor universidad privada de Espa\u00f1a seg\u00fan THE World University Rankings 2021.<\/span><\/li>\n<li><span style=\"font-size: medium;\">M\u00e1s de 20 a\u00f1os ofertando los Programas de educaci\u00f3n superior.<\/span><\/li>\n<li><span style=\"font-size: medium;\">M\u00e1sters con gran experiencia y alto nivel acad\u00e9mico.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Estudiantes internacionales, permiten un alto grado de intercambio cultural.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Programas acad\u00e9micos de alta calidad con grandes est\u00e1ndares de educaci\u00f3n.<\/span><\/li>\n<li><span style=\"font-size: medium;\">Diferentes campus de estudio: Madrid, Valencia, Canarias, Escuela Universitaria Real Madrid<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"western\" align=\"justify\"><\/h2>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-size: medium;\"><b>MISI\u00d3N<\/b><\/span><\/h2>\n<ul>\n<li><span style=\"font-size: medium;\">Proporcionar a nuestros estudiantes una educaci\u00f3n integral, formando l\u00edderes y profesionales preparados para dar respuesta a las necesidades de un mundo global, para aportar valor en sus profesiones y contribuir al progreso social desde un esp\u00edritu emprendedor y de compromiso \u00e9tico. Generar y transferir conocimiento a trav\u00e9s de la investigaci\u00f3n aplicada, contribuyendo igualmente al progreso y situ\u00e1ndonos en la vanguardia del desarrollo intelectual y t\u00e9cnico.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 class=\"western\" align=\"justify\"><\/h2>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-size: medium;\"><b>VISI\u00d3N<\/b><\/span><\/h2>\n<ul>\n<li><span style=\"font-size: medium;\">La Universidad Europea considera la excelencia acad\u00e9mica como uno de sus pilares estrat\u00e9gicos. As\u00ed, nuestro modelo educativo ha hecho suyos los principios del Espacio Europeo de Educaci\u00f3n Superior basado en el aprendizaje hol\u00edstico de la persona. En este modelo, el profesor es un referente y tambi\u00e9n un orientador que acompa\u00f1a al estudiante durante toda su vida universitaria. El estudiante, por su parte, traza su propio recorrido formativo desarrollando los conocimientos, competencias, destrezas y valores que demanda la sociedad actual. Nuestro modelo pone especial \u00e9nfasis en la madurez y autonom\u00eda del estudiante, de forma que \u00e9ste aprenda a adaptarse a un mundo cada vez m\u00e1s complejo y en perpetuo cambio.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2 class=\"western\" align=\"justify\"><\/h2>\n<h2 class=\"western\" align=\"justify\"><span style=\"font-size: medium;\"><b>VALORES<\/b><\/span><\/h2>\n<ul>\n<li><span style=\"font-size: medium;\"><b>Colaborativos<\/b><\/span><span style=\"font-size: medium;\">. Conservamos el sello que nos distingue por nuestro esp\u00edritu emprendedor: somos resueltos y audaces, y colocamos al estudiante en primer lugar. Colaboramos y trabajamos juntos para implantar las mejores pr\u00e1cticas en nuestra instituci\u00f3n.<\/span><\/li>\n<li><span style=\"font-size: medium;\"><b>Internacionales<\/b><\/span><span style=\"font-size: medium;\">. Tenemos una vocaci\u00f3n y un alcance mundial al tiempo que conservamos unas profundas ra\u00edces locales. Ofrecemos recursos internacionales para apoyar y fortalecer la educaci\u00f3n local. Somos una organizaci\u00f3n inclusiva y multicultural que valora la diversidad y respeta todos los puntos de vista y rasgos culturales. <\/span><\/li>\n<li><span style=\"font-size: medium;\"><b>Anal\u00edticos<\/b><\/span><span style=\"font-size: medium;\">. Mediante una rigurosa autoevaluaci\u00f3n procuramos ampliar constantemente nuestra informaci\u00f3n y conocimiento para mejorar nuestro desempe\u00f1o. Este enfoque reflexivo, basado en el an\u00e1lisis de los datos, nos distingue como instituci\u00f3n. <\/span><\/li>\n<li><span style=\"font-size: medium;\"><b>Confiables<\/b><\/span><span style=\"font-size: medium;\">. Si queremos estar \u201caqu\u00ed para siempre\u201d, debemos ganarnos la confianza de nuestros alumnos y sus familias, los empleadores y las comunidades en las que operamos. En todos los niveles de nuestra organizaci\u00f3n estamos sujetos a las m\u00e1s altas exigencias, actuamos con integridad y asumimos la responsabilidad pertinente por nuestras acciones. <\/span><\/li>\n<li><span style=\"font-size: medium;\"><b>Audaces<\/b><\/span><span style=\"font-size: medium;\">. Somos emprendedores, y estamos dispuestos a actuar de manera audaz y correr riesgos calculados al tiempo que nuestras decisiones est\u00e1n basadas en una planificaci\u00f3n racional y reflexiva. Nos movemos con rapidez para aprovechar las oportunidades y producir cambios positivos con el fin de enriquecer la experiencia de nuestros alumnos. Buscamos nuevas formas de mejorar el aprendizaje sin fronteras y transformar el modelo educativo tradicional. Tenemos mentalidad innovadora y facilitamos a los miembros de la comunidad universitaria la oportunidad de cuestionar el status quo. Aplicamos enfoques creativos en el campo de la educaci\u00f3n y en la empresa. Nunca dejamos de explorar nuevos enfoques, nuevas tecnolog\u00edas, nuevos modelos de negocio y nuevas teor\u00edas. Somos l\u00edderes, no seguidores. <\/span><\/li>\n<li><span style=\"font-size: medium;\"><b>Responsables<\/b><\/span><span style=\"font-size: medium;\">. Asumir la responsabilidad por los resultados de los alumnos es el pilar de la revoluci\u00f3n que estamos llevando a cabo en materia de educaci\u00f3n. Nos centramos en los alumnos y los empleadores para adaptar nuestros programas a sus necesidades. Nos esforzamos por mantener altos \u00edndices de retenci\u00f3n, graduaci\u00f3n y empleabilidad, para que nuestros alumnos se incorporen al mercado generando un impacto social positivo.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #ff0000;\"><strong>La segunda mejor universidad privada en Espa\u00f1a en los Rankings<\/strong><\/span><\/h2>\n<p><strong>La universidad privada m\u00e1s grande de Espa\u00f1a con m\u00e1s 40.000 estudiantes al a\u00f1o en 5 campuses (2 en Madrid, 1 en Valencia, 2 en la isla de Tenerife). Vamos a tener nuestro campus en Alicante el a\u00f1o que viene, y en pr\u00f3ximos a\u00f1os vamos a abrir en otras 3 ciudades m\u00e1s nuestro campus.<\/strong><\/p>\n<ul>\n<li>40% de estudiantes internacionales (M\u00e9xico, Francia, Pa\u00edses Escandinavos, Italia, Peru, Alemania\u2026 etc).<\/li>\n<li>30% de los programas ofrecidos en ingles y 10% en franc\u00e9s (en los pr\u00f3ximos a\u00f1os habr\u00e1 programas en italiano tambi\u00e9n).<\/li>\n<li>\u00danica universidad de toda Espa\u00f1a que tiene un hospital simulado grande con las \u00faltimas tecnolog\u00edas. (Otras tienen sus hospitales simulados pero muy peque\u00f1os y limitados).<\/li>\n<li>Arquitectura tiene reconocimientos NAAB y RIBA (son reconocimientos en EEUU y Reino Unido).<\/li>\n<li>Comunicaci\u00f3n Audiovisual el la numero 1 de Espa\u00f1a en instalaciones y equipamiento. Colaboramos con el grupo Mediaset que es la empresa de la televisi\u00f3n y radio mas grande de Espa\u00f1a.<\/li>\n<li>Dise\u00f1o tiene una de las instalaciones mas modernas de toda Espa\u00f1a.<\/li>\n<li>La Universidad de Real Madrid es la numero 1 en toda Europa en todo lo que esta relacionado con el deporte (Gesti\u00f3n deportiva, Fisioterapia deportiva, Rendimiento f\u00edsico\u2026etc). En esta universidad los estudiantes tendr\u00e1n oportunidad de escuchar los deportistas mas conocidos, como se gestionan los entrenamientos, fisioterapia, marketing, contratos, nutrici\u00f3n\u2026etc).<\/li>\n<li>Tenemos laboratorio de Formula 1 donde los estudiantes desarrollan el coche de formula 1 y en 2019 la formula 1 que se ha desarrollado en la universidad ha ganado el 3 puesto en la competici\u00f3n de las universidades de f\u00f3rmula 1.<\/li>\n<li>Veterinaria (ofrecemos en ingl\u00e9s, espa\u00f1ol y franc\u00e9s) tiene uno de los laboratorios mas modernos en toda Europa.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En nivel europeo destacamos con Arquitectura, Dise\u00f1o, Comunicaci\u00f3n Audiovisual, Fisioterapia, Medicina, Veterinaria, Odontolog\u00eda, Psicolog\u00eda, Business, Big Data y todos los programas relacionados con el Deporte. Por cierto, hay que aplicar con antelaci\u00f3n en Medicina, Psicolog\u00eda, Veterinaria, y algunos programas de Deporte porque en junio ya hay una larga lista de espera.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/sic.nodscloud.com\/universidad-europea\/wp-content\/uploads\/sites\/12\/2022\/03\/Presentacion-Gene\u0301rica-1.pdf\" target=\"_blank\" rel=\"noopener\"><strong>PRESENTACION GENERICA DE UNIVERSIDAD EUROPEA (ver archivo)<\/strong><\/a><\/span><\/h2>\n<h2><a href=\"https:\/\/sic.nodscloud.com\/universidad-europea\/wp-content\/uploads\/sites\/12\/2022\/07\/Ranking-UE_act_2022.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>RANKING Universidad Europea 2022<\/strong><\/span><\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1226px;\" border=\"1\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"394\" \/>\n<col width=\"206\" \/>\n<col width=\"123\" \/>\n<col width=\"106\" \/>\n<col width=\"123\" \/>\n<col width=\"162\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas Presenciales&quot;}\"><span style=\"color: #ff0000;\"><strong>Programas Presenciales<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\"><span style=\"color: #ff0000;\"><strong>\u00c1rea de Estudio<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\"><span style=\"color: #ff0000;\"><strong>T\u00edtulos Propios u Oficiales<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital&quot;}\">M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs)&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Marketing&quot;}\">Master Universitario en Marketing<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Marketing Deportivo&quot;}\">M\u00e1ster Universitario en Marketing Deportivo<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44856}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Marketing Digital y Big Data&quot;}\">M\u00e1ster en Marketing Digital y Big Data<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Madrid)&quot;}\">Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Madrid)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses (intensivo)&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Valencia)&quot;}\">Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Valencia)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses (incluye presencialidad cada 30-40 d\u00edas para hacer la parte pr\u00e1ctica.)&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales&quot;}\">M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos&quot;}\">M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Business Analytics&quot;}\">M\u00e1ster en Business Analytics<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones&quot;}\">M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\">Programas en Ciencia de Datos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos - MBI \/ Big Data Analytics - MBI&quot;}\">M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos &#8211; MBI \/ Big Data Analytics &#8211; MBI<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\">Programas en Ciencia de Datos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n Deportiva&quot;}\">M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n Deportiva<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Nutrici\u00f3n Cl\u00ednica&quot;}\">M\u00e1ster Universitario en Nutrici\u00f3n Cl\u00ednica<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Fisioterapia Deportiva&quot;}\">M\u00e1ster Universitario en Fisioterapia Deportiva<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Actividad F\u00edsica y Salud&quot;}\">M\u00e1ster Universitario en Actividad F\u00edsica y Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad&quot;}\">M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Terapia Manual Ortopedica y Tratamiento del Dolor&quot;}\">M\u00e1ster Universitario en Terapia Manual Ortopedica y Tratamiento del Dolor<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1134px;\" border=\"1\" width=\"923\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"394\" \/>\n<col width=\"206\" \/>\n<col width=\"123\" \/>\n<col width=\"112\" \/>\n<col width=\"106\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas Online&quot;}\"><strong><span style=\"color: #ff0000;\">Programas Online<\/span><\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\"><strong><span style=\"color: #ff0000;\">\u00c1rea de Estudio<\/span><\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;T\u00edtulos Propios u Oficiales&quot;}\"><strong><span style=\"color: #ff0000;\">T\u00edtulos Propios u Oficiales<\/span><\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\"><strong><span style=\"color: #ff0000;\">Fecha de inicio<\/span><\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n del Programa&quot;}\"><strong><span style=\"color: #ff0000;\">Duraci\u00f3n del Programa<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Marketing&quot;}\">Master Universitario en Marketing<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Marketing&quot;}\">Marketing<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Direcci\u00f3n de Protocolo y Organizacion de Eventos&quot;}\">Master en Direcci\u00f3n de Protocolo y Organizacion de Eventos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n y Deporte&quot;}\">Gesti\u00f3n y Deporte<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44543}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">13\/12\/2021<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\">Gesti\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Business Analytics&quot;}\">M\u00e1ster en Business Analytics<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\">8 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Industria 4.0&quot;}\">Master Universitario en Industria 4.0<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\">8 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion y Gesti\u00f3n de Tecnologias de la Informacion. MBA TIC.&quot;}\">Master Universitario en Direccion y Gesti\u00f3n de Tecnologias de la Informacion. MBA TIC.<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44881}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">16\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Inteligencia Artificial&quot;}\">Master en Inteligencia Artificial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\">Programas en Gesti\u00f3n y Comercio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44881}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">16\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\">6 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones&quot;}\">M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inform\u00e1tica&quot;}\">Inform\u00e1tica<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">21\/10\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Gestion de Negocios Internacionales &quot;}\">Master Universitario en Gestion de Negocios Internacionales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\">Programas en Ciencia de Datos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Fintech y Blockchain&quot;}\">Master en Fintech y Blockchain<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\">Programas en Ciencia de Datos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;entre el 9 y 20 de noviembre cada a\u00f1o&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">entre el 9 y 20 de noviembre cada a\u00f1o<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\">6 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion Comercial y Ventas&quot;}\">Master Universitario en Direccion Comercial y Ventas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\">Programas en Ciencia de Datos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion y Gestion Financiera&quot;}\">Master Universitario en Direccion y Gestion Financiera<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\">Gesti\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos&quot;}\">M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\">Gesti\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\">11 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Nutrici\u00f3n Clinica&quot;}\">M\u00e1ster Universitario en Nutrici\u00f3n Clinica<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\">Programas en Ciencias de la Salud<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Prevenci\u00f3n Riesgos Laborales&quot;}\">Ma\u0301ster Universitario Prevenci\u00f3n Riesgos Laborales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\">Arquitectura<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Organizaci\u00f3n Direcci\u00f3n Centros Docentes&quot;}\">Ma\u0301ster Universitario Organizaci\u00f3n Direcci\u00f3n Centros Docentes<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\">Educaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Gesti\u00f3n del Negocio Mar\u00edtimo y el Derecho Mar\u00edtimo&quot;}\">\n<div>\n<div>Ma\u0301ster Universitario en Gesti\u00f3n del Negocio Mar\u00edtimo y el Derecho Mar\u00edtimo<\/div>\n<\/div>\n<\/td>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\">11 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Sistemas Integrados de Gestio\u0301n&quot;}\">Ma\u0301ster Universitario en Sistemas Integrados de Gestio\u0301n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\">Ingenier\u00eda<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Psicopedagogi\u0301a&quot;}\">Ma\u0301ster Universitario en Psicopedagogi\u0301a<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\">Educaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Logi\u0301stica&quot;}\">Ma\u0301ster Universitario en Logi\u0301stica<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\">Ingenier\u00eda<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Ingenieri\u0301a de Organizacio\u0301n, Direccio\u0301n de Proyectos y Empresas&quot;}\">Ma\u0301ster Universitario en Ingenieri\u0301a de Organizacio\u0301n, Direccio\u0301n de Proyectos y Empresas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\">Ingenier\u00eda<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Energi\u0301as Renovables&quot;}\">Ma\u0301ster Universitario en Energi\u0301as Renovables<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\">Arquitectura<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Derechos Humanos&quot;}\">Ma\u0301ster Universitario en Derechos Humanos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Derecho&quot;}\">Derecho<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">11 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Atencio\u0301n Temprana&quot;}\">Ma\u0301ster Universitario en Atencio\u0301n Temprana<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\">Educaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">26\/04\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Educaci\u00f3n Especial &quot;}\">Ma\u0301ster Universitario Educaci\u00f3n Especial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\">Educaci\u00f3n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\">oficial<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">15\/11\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol&quot;}\">Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Deporte&quot;}\">Deporte<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44543}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">24\/10\/2022<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster en Arquitectura Sostenible y Bioconstruccio\u0301n&quot;}\">Ma\u0301ster en Arquitectura Sostenible y Bioconstruccio\u0301n<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\">Arquitectura<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\">propio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;entre el 9 y 20 de noviembre cada a\u00f1o&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\">entre el 9 y 20 de noviembre cada a\u00f1o<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\">6 meses<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>.<\/p>\n<h4>ARANCELES PRESENCIAL 2023<\/h4>\n<h4><a href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2023\/05\/Tarifario-RM-2023.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\"> Tarifario-RM-2023<\/span><\/a><\/h4>\n<p><a href=\"Tarifario-Postgrado2023_Madrid\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #ff0000;\">Tarifario-Postgrado2023_Madrid<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-content\/uploads\/sites\/3\/2023\/05\/Tarifario-Posgrado-Valencia-comprimido.pdf\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #ff0000;\">Tarifario Posgrado Valencia<\/span><\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>ARGUMENTOS DE VENTA POSTGRADO UNIVERSIDAD EUROPEA<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><strong>SALUD<\/strong><\/p>\n<ul>\n<li>FORMACI\u00d3N PR\u00c1CTICA \u2013 Realizaci\u00f3n de horas pr\u00e1cticas sobre pacientes utilizando las \u00faltimas tecnolog\u00edas del sector, tanto en el diagn\u00f3stico como en el tratamiento. Los alumnos de nuestros M\u00e1steres en Salud llevan a cabo much\u00edsimos tratamientos anuales, como los 4.300 en el caso de Ortodoncia.<\/li>\n<li>\u00daLTIMA TECNOLOG\u00cdA &#8211; Te introducir\u00e1s en los \u00faltimos avances en el campo experimental e investigador, contando con las t\u00e9cnicas y materiales m\u00e1s avanzados dentro de nuestras instalaciones como el Hospital Simulado presente en nuestros campus de Madrid, Valencia y Canarias.<\/li>\n<li>CLAUSTRO RECONOCIDO &#8211; Trabajar\u00e1s con un equipo de profesionales dedicado exclusivamente a la pr\u00e1ctica cl\u00ednica con una labor docente contrastada y actividad investigadora de referencia, reconocida internacionalmente.<\/li>\n<li>FORMACI\u00d3N CL\u00cdNICA E INVESTIGADORA \u2013 Combinaci\u00f3n de una s\u00f3lida formaci\u00f3n cl\u00ednica con un importante componente de investigaci\u00f3n.<\/li>\n<li>ACTIVIDADES HANDS-ON Peri\u00f3dicamente organizaremos hands-on sobre las \u00faltimas tendencias, t\u00e9cnicas y materiales en los distintos sectores del mundo de la salud.<\/li>\n<li>SIMPLIFICA Y MEJORA TU CAPACIDAD DE COMUNICACI\u00d3N: Mejorar\u00e1s tu capacidad de comunicaci\u00f3n no s\u00f3lo con el resto del equipo cl\u00ednico si no como herramienta de aceptaci\u00f3n y v\u00eda de comunicaci\u00f3n del tratamiento con tus pacientes.<\/li>\n<li>TRASFERENCIA DE CONOCIMIENTO ENTRE ESTUDIANTES Llevar\u00e1s a cabo las pr\u00e1cticas cl\u00ednicas en parejas formadas por un estudiante de segundo con uno de tercero. De esta forma, fomentamos la transferencia de conocimientos entre estudiantes.<\/li>\n<li>SUPERVISI\u00d3N DE TU PR\u00c1CTICA CL\u00cdNICA Expertos en el \u00e1rea llevar\u00e1n a cabo una supervisi\u00f3n constante de las pr\u00e1cticas de los estudiantes, con el objetivo de guiar el aprendizaje de los estudiantes.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>STEAM<\/strong><\/p>\n<ul>\n<li>EXPERIENCIA INNOVADORA Alcanzar\u00e1s las competencias digitales y habilidades personales para desarrollar la estrategia y ejecutar la transformaci\u00f3n digital de cualquier organizaci\u00f3n y\/o industria.<\/li>\n<li>EMPLEABILIDAD Participar\u00e1s en encuentros peri\u00f3dicos con empresas del sector para facilitar el networking y la conexi\u00f3n con el mundo profesional.<\/li>\n<li>PLAN DE ESTUDIOS Los M\u00e1steres Universitarios en el \u00e1rea de STEAM aportan conocimientos en la Transformaci\u00f3n y Estrategia Digital con una orientaci\u00f3n profesionalizante. Su objetivo es formar profesionales altamente cualificados en las nuevas tecnolog\u00edas de transformaci\u00f3n digital.<\/li>\n<li>CLAUSTRO DE PROFESIONALES DEL SECTOR El claustro del m\u00e1ster cuenta con docentes que son profesionales en activo en empresas referentes y l\u00edderes del sector, que trabajan d\u00eda a d\u00eda con las tecnolog\u00edas.<\/li>\n<li>APRENDIZAJE BASADO EN PROYECTOS La modalidad de ense\u00f1anza est\u00e1 basada en trabajar por proyectos con las herramientas hardware y software m\u00e1s innovadoras de los fabricantes referentes y la exposici\u00f3n de casos reales de uso.<\/li>\n<li>CHALLENGE BASED LEARNING Aprender\u00e1s a trav\u00e9s de casos reales adaptados.<\/li>\n<li>EXPERIENCIA 4.0 Los estudiantes estar\u00e1n listos para entrar en el nuevo mercado 4.0 gracias a los proyectos, a las actividades y a los cursos de nuestros M\u00e1steres del \u00e1rea STEAM<\/li>\n<li>LAS MEJORES INSTALACIONES IN CAMPUS Talleres, laboratorios y salas de dise\u00f1o propios: laboratorio de motores, t\u00fanel de viento, laboratorio de ensayos, FabLab, taller de rob\u00f3tica, etc.<\/li>\n<li>COMPLETO Tratar\u00e1s de forma integrada todas las materias involucradas en la redacci\u00f3n del proyecto, su construcci\u00f3n y posterior explotaci\u00f3n con profesionales en activo en las principales empresas del sector.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>TECNOLOG\u00cdA<\/strong><\/p>\n<ul>\n<li>CHALLENGE BASED LEARNING aprender\u00e1s qu\u00e9 es la inteligencia artificial, aplicaciones pr\u00e1cticas, t\u00e9cnicas y profundizar\u00e1s en muchos otros aspectos para formarte a trav\u00e9s de casos reales de multinacionales de primer nivel, usando las herramientas m\u00e1s innovadoras que se manejan en el sector<\/li>\n<li>TECH EXPERIENCE Podr\u00e1s conocer de primera mano y hacer networking con profesionales de reconocidas empresas que te presentar\u00e1n casos reales<\/li>\n<li>EL MEJOR CLAUSTRO Porque tus profesores son investigadores de la universidad y en su mayor\u00eda profesionales de empresas nacionales e internacionales de todos los sectores, como el de consultor\u00eda, el sector Sanidad (QuironSalud) o las startups (Clarity AI), que est\u00e1n en contacto diariamente con esta tecnolog\u00eda.<\/li>\n<li>ENFOQUE PR\u00c1CTICO Aprender\u00e1s de forma pr\u00e1ctica a desplegar soluciones Big Data utilizando tecnolog\u00edas como Hadoop, HDFS, NoSQL, Yarn, Kafka, Hive o Pig, y el desarrollo de soluciones de miner\u00eda de datos y aprendizaje autom\u00e1tico usando las herramientas y tecnolog\u00edas m\u00e1s actuales del mercado.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CIENCIAS SOCIALES<\/strong><\/p>\n<ul>\n<li>CHALLENGE BASED LEARNING Aprender\u00e1s a proponer soluciones que supongan una alternativa a problemas planteados por la empresa en el aula, trabajando en grupos con metolog\u00edas activas, design thinking. Se seleccionar\u00e1n las mejores propuestas para presentar en la empresa. Es una oportunidad p\u00e0ra demostrar tu potencial en los futuros empleadores.<\/li>\n<li>TECH EXPERIENCE Dominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad diaria, modelos anal\u00edticos para medir el resultado de la inversi\u00f3n y de comportamiento del cliente para optimizar campa\u00f1as. Estar\u00e1s preparado para responder a las necesidades del negocio. Adem\u00e1s, tendr\u00e1s masterclass impartidas por profesionales del sector.<\/li>\n<li>CLAUSTRO DE PROFESIONALES Tus profesores son profesionales en activo de grandes multinacionales como; T\u00e9cnicas Reunidas, Praxair, ING, BBVA, Sopra y Fujitsu.<\/li>\n<li>ESPECIALIZACI\u00d3N EN TODAS LAS RAMAS DE NEGOCIO Los estudiantes ser\u00e1n capaces de liderar y coordinar distintas \u00e1reas de negocio: finanzas, marketing, ventas, contabilidad, recursos humanos, operaciones, Project Management, tecnolog\u00eda e innovaci\u00f3n.<\/li>\n<li>APRENDIZAJE PR\u00c1CTICO En la Universidad Europea apostamos por la creatividad, la tecnolog\u00eda y la comunicaci\u00f3n. Y solo es posible alcanzar las m\u00e1s altas cotas de profesionalizaci\u00f3n afianzando los contenidos te\u00f3ricos a trav\u00e9s de ejercicios pr\u00e1cticos reales.<\/li>\n<li>LABORATORIOS Nuestro M\u00e1steres de \u00e1rea ciencias sociales ofrecen a los estudiantes la posibilidad de disfrutar de todos los laboratorios. Adem\u00e1s de las instalaciones propias de la Universidad, la titulaci\u00f3n cuenta con las instalaciones de estudios profesionales.<\/li>\n<li>FORMACI\u00d3N PR\u00c1CTICA, \u00daTIL, REAL Aprende experimentando, trabajando con casos reales y compartiendo situaciones que vivir\u00e1s en tu entorno profesional.<\/li>\n<li>COMPATIBLE CON TU ACTIVIDAD PROFESIONAL Si ya estudias o trabajas, puedes adaptar los horarios seg\u00fan tus necesidades.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1><strong>M\u00e1ster\u00a0 &#8211; Presenciales<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1048px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital&quot;}\" data-sheets-formula=\"='UE - presencial'!R[1]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:847.7777777777778}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">847,78 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:7630}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">7.630,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8730}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">8.730,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formamos a comunicadores interdisciplinares en un entorno de innovaci\u00f3n y emprendimiento.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Formamos a comunicadores interdisciplinares en un entorno de innovaci\u00f3n y emprendimiento.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripcion del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital te preparar\u00e1 para la demanda del mercado como profesional con conocimientos de Inbound Marketing, Big Data, Storytelling o Transmedia para trabajar en un medio, una productora, o comunicando para una marca. En el M\u00e1ster Comunicaci\u00f3n y Emprendimiento Digital recibir\u00e1s una formaci\u00f3n integral en marketing, gesti\u00f3n de bases de datos, narrativa, programaci\u00f3n, tecnolog\u00eda y dise\u00f1o.\\nDeber\u00e1s disponer habilidades comunicativas tanto orales como escritas, y estar acostumbrado al uso de las tecnolog\u00edas aplicadas a la comunicaci\u00f3n.\\nNuestro modelo de Aprendizaje Experiencial HYFLEX integra el aula presencial y virtual. Aulas 100% digitalizadas, con c\u00e1maras, micr\u00f3fonos 360 y pizarras inteligentes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Comunicaci\u00f3n y Emprendimiento Digital te preparar\u00e1 para la demanda del mercado como profesional con conocimientos de Inbound Marketing, Big Data, Storytelling o Transmedia para trabajar en un medio, una productora, o comunicando para una marca. En el M\u00e1ster Comunicaci\u00f3n y Emprendimiento Digital recibir\u00e1s una formaci\u00f3n integral en marketing, gesti\u00f3n de bases de datos, narrativa, programaci\u00f3n, tecnolog\u00eda y dise\u00f1o.<br \/>\nDeber\u00e1s disponer habilidades comunicativas tanto orales como escritas, y estar acostumbrado al uso de las tecnolog\u00edas aplicadas a la comunicaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a quienes est\u00e9n interesados en convertir su pasi\u00f3n en profesi\u00f3n y adquirir una formaci\u00f3n de alta calidad en las \u00faltimas tendencias, canales, herramientas y tecnolog\u00edas aplicadas a la comunicaci\u00f3n digital.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a quienes est\u00e9n interesados en convertir su pasi\u00f3n en profesi\u00f3n y adquirir una formaci\u00f3n de alta calidad en las \u00faltimas tendencias, canales, herramientas y tecnolog\u00edas aplicadas a la comunicaci\u00f3n digital.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 889px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs)&quot;}\" data-sheets-formula=\"='UE - presencial'!R[2]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs)<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:905.5555555555555}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">905,56 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8150}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">8.150,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9250}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.250,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dirige la comunicaci\u00f3n y reputaci\u00f3n de una empresa o instituci\u00f3n, con un programa 360\u00ba que te especializa en todas las \u00e1reas de la Comunicaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Dirige la comunicaci\u00f3n y reputaci\u00f3n de una empresa o instituci\u00f3n, con un programa 360\u00ba que te especializa en todas las \u00e1reas de la Comunicaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripcion del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs) es el \u00fanico m\u00e1ster que te ofrece la especializaci\u00f3n en Asuntos P\u00fablicos. Aplicar\u00e1s estrategias corporativas de comunicaci\u00f3n en entornos digitales y su gesti\u00f3n en el \u00e1mbito de la comunicaci\u00f3n 3.0 y 4.0, en plataformas digitales y redes sociales.\\n\\nGestionar\u00e1s la identidad, cultura, imagen, reputaci\u00f3n y comunicaci\u00f3n de una empresa o instituci\u00f3n.\\nFormar\u00e1s parte de la Asociaci\u00f3n DIRCOM, con acceso a una red profesional de m\u00e1s de 1000 directivos.\\nNuestro modelo de Aprendizaje Experiencial HYFLEX integra el aula presencial y virtual. Aulas 100% digitalizadas, con c\u00e1maras, micr\u00f3fonos 360 y pizarras inteligentes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">\n<p style=\"text-align: left;\">El M\u00e1ster Universitario en Direcci\u00f3n de Comunicaci\u00f3n y Asuntos P\u00fablicos (Public Affairs) es el \u00fanico m\u00e1ster que te ofrece la especializaci\u00f3n en Asuntos P\u00fablicos. Aplicar\u00e1s estrategias corporativas de comunicaci\u00f3n en entornos digitales y su gesti\u00f3n en el \u00e1mbito de la comunicaci\u00f3n 3.0 y 4.0, en plataformas digitales y redes sociales.<\/p>\n<p style=\"text-align: left;\">Gestionar\u00e1s la identidad, cultura, imagen, reputaci\u00f3n y comunicaci\u00f3n de una empresa o instituci\u00f3n.<br \/>\nFormar\u00e1s parte de la Asociaci\u00f3n DIRCOM, con acceso a una red profesional de m\u00e1s de 1000 directivos.<br \/>\nNuestro modelo de Aprendizaje Experiencial HYFLEX integra el aula presencial y virtual. Aulas 100% digitalizadas, con c\u00e1maras, micr\u00f3fonos 360 y pizarras inteligentes.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1230px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Marketing&quot;}\" data-sheets-formula=\"='UE - presencial'!R[3]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Marketing<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial (consultar por modalidad Online a distancia)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial (consultar por modalidad Online a distancia)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duracion de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1055.5555555555557}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.055,56 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">9.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:10600}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">10.600,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p>Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Impulsa tu carrera profesional en los puestos de trabajo que demanda la nueva Econom\u00eda Digital. &quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Impulsa tu carrera profesional en los puestos de trabajo que demanda la nueva Econom\u00eda Digital.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripcion del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripcion del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Marketing propone soluciones que supongan una alternativa a problemas planteados por la empresa en el aula, trabajando en grupos con metolog\u00edas activas y design thinking.\\nTe convertir\u00e1s en el profesional del marketing que buscan las empresas, porque ser\u00e1s capaz de elaborar una estrategia de marketing en un plan de marketing integral, combinando pensamiento creativo con el anal\u00edtico. Tambien estar\u00e1s capacitado para desarrollarte como director comercial, asaaegurando el logro de los objetivos de la empresa.\\nAprender\u00e1s a realizar investigaciones de mercado para detectar oportunidades de negocio, utilizando herramientas de an\u00e1lisis complejas para predecir, optimizar o testar resultados: t\u00e9cnicas para segmentaci\u00f3n de mercado, posicionamiento de productos, CRM, Google Analytics, etc.\\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio. Adem\u00e1s, tendr\u00e1s masterclass impartidas por profesionales de empresas innovadoras.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Marketing propone soluciones que supongan una alternativa a problemas planteados por la empresa en el aula, trabajando en grupos con metolog\u00edas activas y design thinking.<br \/>\nTe convertir\u00e1s en el profesional del marketing que buscan las empresas, porque ser\u00e1s capaz de elaborar una estrategia de marketing en un plan de marketing integral, combinando pensamiento creativo con el anal\u00edtico. Tambien estar\u00e1s capacitado para desarrollarte como director comercial, asaaegurando el logro de los objetivos de la empresa.<br \/>\nAprender\u00e1s a realizar investigaciones de mercado para detectar oportunidades de negocio, utilizando herramientas de an\u00e1lisis complejas para predecir, optimizar o testar resultados: t\u00e9cnicas para segmentaci\u00f3n de mercado, posicionamiento de productos, CRM, Google Analytics, etc.<br \/>\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio. Adem\u00e1s, tendr\u00e1s masterclass impartidas por profesionales de empresas innovadoras.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Si sientes pasi\u00f3n por el Marketing que se hace hoy y las nuevas t\u00e9cnicas de captaci\u00f3n comercial, este es tu M\u00e1ster.\\n\\nEl m\u00e1ster est\u00e1 dirigido a graduados en el \u00e1rea de empresa, marketing, turismo y comunicaci\u00f3n, as\u00ed como, en otras \u00e1reas de las Ciencias Sociales como sociolog\u00eda o psicolog\u00eda, sin descartar la posibilidad de acceso a graduados en otras \u00e1reas con inquietudes profesionales dirigidas hacia el campo de los negocios y la comunicaci\u00f3n. Profesionales del \u00e1mbito del Marketing con al menos un a\u00f1o de experiencia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Si sientes pasi\u00f3n por el Marketing que se hace hoy y las nuevas t\u00e9cnicas de captaci\u00f3n comercial, este es tu M\u00e1ster.<\/p>\n<p>El m\u00e1ster est\u00e1 dirigido a graduados en el \u00e1rea de empresa, marketing, turismo y comunicaci\u00f3n, as\u00ed como, en otras \u00e1reas de las Ciencias Sociales como sociolog\u00eda o psicolog\u00eda, sin descartar la posibilidad de acceso a graduados en otras \u00e1reas con inquietudes profesionales dirigidas hacia el campo de los negocios y la comunicaci\u00f3n. Profesionales del \u00e1mbito del Marketing con al menos un a\u00f1o de experiencia.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 870px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Marketing Deportivo&quot;}\" data-sheets-formula=\"='UE - presencial'!R[4]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Marketing Deportivo<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44856}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">22\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duracion de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1977.7777777777778}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.977,78 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:17800}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">17.800,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:19300}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">19.300,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Viernes de 17.00 a 22.00 h., s\u00e1bados de 9.00 a 14.00 h.\\ny de 16.00 a 21.00 h., y domingos de 9.00 a 14.00 h.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">Viernes de 17.00 a 22.00 h., s\u00e1bados de 9.00 a 14.00 h.<br \/>\ny de 16.00 a 21.00 h., y domingos de 9.00 a 14.00 h.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p>Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Un M\u00e1ster Global con el que especializarte en las herramientas para conocer, dominar y aportar valor en la gesti\u00f3n de marcas deportivas, instituciones, equipos, e incluso deportistas.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Un M\u00e1ster Global con el que especializarte en las herramientas para conocer, dominar y aportar valor en la gesti\u00f3n de marcas deportivas, instituciones, equipos, e incluso deportistas.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripcion del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripcion del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Marketing Deportivo forma profesionales l\u00edderes en el mercado deportivo en las tendencias y las herramientas m\u00e1s utilizadas en el Marketing Deportivo a nivel global, una oportunidad \u00fanica para convertir tu pasi\u00f3n en una carrera profesional de \u00e9xito.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster en Marketing Deportivo forma profesionales l\u00edderes en el mercado deportivo en las tendencias y las herramientas m\u00e1s utilizadas en el Marketing Deportivo a nivel global, una oportunidad \u00fanica para convertir tu pasi\u00f3n en una carrera profesional de \u00e9xito.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 788px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Marketing Digital y Big Data&quot;}\" data-sheets-formula=\"='UE - presencial'!R[5]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster en Marketing Digital y Big Data<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Valencia<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duracion de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duracion de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">12 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:685}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">685,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8220}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">8.220,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.000,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9220}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.220,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p>Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Conoce todas las posibilidades de una estrategia global online. Los departamentos de m\u00e1rketing precisan de un nuevo enfoque digital imprescindible.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Conoce todas las posibilidades de una estrategia global online. Los departamentos de m\u00e1rketing precisan de un nuevo enfoque digital imprescindible.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripcion del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripcion del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Marketing Digital y Big Data (Business Analytics) de la Escuela de Postgrado de la Universidad Europea de Valencia proporciona a todos los profesiona\u00adles las habilidades necesarias para dirigir e implantar proyectos de Marketing estrat\u00e9gicos, que permitan dar respuesta a los nuevos modelos de negocios y a las empresas, en un entorno donde el cambio es continuo y la informaci\u00f3n debe ser relevante e inmediata para definir e implantar los planes de marketing.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster en Marketing Digital y Big Data (Business Analytics) de la Escuela de Postgrado de la Universidad Europea de Valencia proporciona a todos los profesiona\u00adles las habilidades necesarias para dirigir e implantar proyectos de Marketing estrat\u00e9gicos, que permitan dar respuesta a los nuevos modelos de negocios y a las empresas, en un entorno donde el cambio es continuo y la informaci\u00f3n debe ser relevante e inmediata para definir e implantar los planes de marketing.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 894px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA&quot;}\" data-sheets-formula=\"='UE - presencial'!R[6]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial (consultar por modalidad Online a distancia)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial (consultar por modalidad Online a distancia)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">24\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:2600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">2.600,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:23400}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">23.400,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:24900}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">24.900,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dos grupos seg\u00fan asignaci\u00f3n por parte de la direcci\u00f3n del M\u00e1ster en funci\u00f3n de la experiencia y habilidades:\\n\u2022 Lunes - Jueves de 16:30 a 20:30 h.\\n\u2022 Lunes - Jueves de 17:00 a 21:00 h.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">Dos grupos seg\u00fan asignaci\u00f3n por parte de la direcci\u00f3n del M\u00e1ster en funci\u00f3n de la experiencia y habilidades:<br \/>\n\u2022 Lunes &#8211; Jueves de 16:30 a 20:30 h.<br \/>\n\u2022 Lunes &#8211; Jueves de 17:00 a 21:00 h.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Elegido entre los 10 mejores MBA en Gesti\u00f3n Deportiva a Nivel Mundial por SportBusiness Postgraduate Rankings 2020, TOP 3 en Europa y N\u00famero 1 en Espa\u00f1a.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Elegido entre los 10 mejores MBA en Gesti\u00f3n Deportiva a Nivel Mundial por SportBusiness Postgraduate Rankings 2020, TOP 3 en Europa y N\u00famero 1 en Espa\u00f1a.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas (MBA) es un programa pionero en Espa\u00f1a, desde 2006, en el que aprender\u00e1s los modelos de negocio m\u00e1s exitosos en la Industria Deportiva a Nivel Mundial gracias a un claustro compuesto por profesionales de reconocido prestigio y experiencias \u00fanicas (viajes internacionales, Networking, pr\u00e1cticas...)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas (MBA) es un programa pionero en Espa\u00f1a, desde 2006, en el que aprender\u00e1s los modelos de negocio m\u00e1s exitosos en la Industria Deportiva a Nivel Mundial gracias a un claustro compuesto por profesionales de reconocido prestigio y experiencias \u00fanicas (viajes internacionales, Networking, pr\u00e1cticas&#8230;)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 995px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Valencia)&quot;}\" data-sheets-formula=\"='UE - presencial'!R[8]C[0]\"><span style=\"color: #ff0000;\"><strong>Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager (Valencia)<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Semipresencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Semipresencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Valencia<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses (incluye presencialidad cada 30-40 d\u00edas para hacer la parte pr\u00e1ctica.)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">12 meses (incluye presencialidad cada 30-40 d\u00edas para hacer la parte pr\u00e1ctica.)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">12 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:277.5}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">277,50 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:3330}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">3.330,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:3830}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">3.830,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Estudia el postgrado m\u00e1s completo en una de las mejores universidades para arquitectos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Estudia el postgrado m\u00e1s completo en una de las mejores universidades para arquitectos.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager aprende una metodolog\u00eda de trabajo en la que todos los agentes comparten informaci\u00f3n en tiempo real. \\nLa mayor\u00eda del claustro son profesores de Valencia, miembros del Grupo de usuarios Revit de Valencia y miembros del Comit\u00e9 de organizaci\u00f3n del EUBIM (Encuentro de Usuarios BIM) uno de los congresos BIM m\u00e1s importantes de Espa\u00f1a y Latinoam\u00e9rica.\\nLos talleres presenciales son impartidos por expertos que utilizan estas herramientas desde hace a\u00f1os, tanto en Espa\u00f1a como en el extranjero, combinando proyectos grandes con peque\u00f1os.\\nContenidos exclusivos para soporte online desarrollados por BIM Managers experimentados en proyectos reales\\nAl ser semipresencial permite compaginar el programa con la actividad laboral.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">Con el Postgrado de Experto en Gesti\u00f3n de Proyectos, BIM Manager aprende una metodolog\u00eda de trabajo en la que todos los agentes comparten informaci\u00f3n en tiempo real.<br \/>\nLa mayor\u00eda del claustro son profesores de Valencia, miembros del Grupo de usuarios Revit de Valencia y miembros del Comit\u00e9 de organizaci\u00f3n del EUBIM (Encuentro de Usuarios BIM) uno de los congresos BIM m\u00e1s importantes de Espa\u00f1a y Latinoam\u00e9rica.<br \/>\nLos talleres presenciales son impartidos por expertos que utilizan estas herramientas desde hace a\u00f1os, tanto en Espa\u00f1a como en el extranjero, combinando proyectos grandes con peque\u00f1os.<br \/>\nContenidos exclusivos para soporte online desarrollados por BIM Managers experimentados en proyectos reales<br \/>\nAl ser semipresencial permite compaginar el programa con la actividad laboral.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 884px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales&quot;}\" data-sheets-formula=\"='UE - presencial'!R[9]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1099.4444444444443}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.099,44 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9895}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">9.895,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:10995}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">10.995,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales esta enfocado a crear expertos en negocios internacionales, en relaciones econ\u00f3micas internacionales y en gesti\u00f3n de comercio exterior con una visi\u00f3n pr\u00e1ctica y operativa del sector.\\n\\nTe formar\u00e1s para gestionar procesos de fusi\u00f3n, expansi\u00f3n y alianzas estrat\u00e9gicas a nivel internacional.\\nProfundizar\u00e1s en las claves pol\u00edtico-econ\u00f3micas, geoestrat\u00e9gicas y de diplomacia corporativa en mercados globales.\\nObtendr\u00e1s un t\u00edtulo oficial de M\u00e1ster homologado por el Ministerio de Educaci\u00f3n espa\u00f1ol, convalidable internacionalmente y reconocido en el Espacio Europeo de Educaci\u00f3n Superior.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">\n<p style=\"text-align: left;\">El M\u00e1ster Universitario en Comercio y Relaciones Econ\u00f3micas Internacionales esta enfocado a crear expertos en negocios internacionales, en relaciones econ\u00f3micas internacionales y en gesti\u00f3n de comercio exterior con una visi\u00f3n pr\u00e1ctica y operativa del sector.<\/p>\n<p style=\"text-align: left;\">Te formar\u00e1s para gestionar procesos de fusi\u00f3n, expansi\u00f3n y alianzas estrat\u00e9gicas a nivel internacional.<br \/>\nProfundizar\u00e1s en las claves pol\u00edtico-econ\u00f3micas, geoestrat\u00e9gicas y de diplomacia corporativa en mercados globales.<br \/>\nObtendr\u00e1s un t\u00edtulo oficial de M\u00e1ster homologado por el Ministerio de Educaci\u00f3n espa\u00f1ol, convalidable internacionalmente y reconocido en el Espacio Europeo de Educaci\u00f3n Superior.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1210px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[10]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1099.4444444444443}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.099,44 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9895}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">9.895,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:10995}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">10.995,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Desarrolla tus capacidades profesionales y de liderazgo, para lograr una influencia significativa en la direcci\u00f3n de personas y la gesti\u00f3n del cambio en las organizaciones.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Desarrolla tus capacidades profesionales y de liderazgo, para lograr una influencia significativa en la direcci\u00f3n de personas y la gesti\u00f3n del cambio en las organizaciones.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos proporciona las estrategias y las t\u00e9cnicas avanzadas para la funci\u00f3n de recursos humanos, y los elementos clave que marcar\u00e1n el futuro, basados en las organizaciones 2.0 y la tecnolog\u00eda digital.\\n\\nAdquirir\u00e1s habilidades y competencias para satisfacer la demanda de perfiles altamente cualificados en funciones relacionadas con el dise\u00f1o, desarrollo e implementaci\u00f3n de pol\u00edticas innovadoras de RR.HH.\\nAprende haciendo, una metodolog\u00eda basada en la resoluci\u00f3n de casos reales desde el primer d\u00eda con la gu\u00eda de un claustro compuesto por docentes expertos en el \u00e1rea y reputados profesionales en activo.\\nNuestro programa mejorar\u00e1 tu empleabilidad al participar en el aprendizaje de las \u00faltimas tendencias en gesti\u00f3n de los RR.HH. En colaboraci\u00f3n con Meta4, compa\u00f1\u00eda dedicada a ofrecer Soluciones Globales para la gesti\u00f3n de la N\u00f3mina y los RR.HH.; recibir\u00e1s formaci\u00f3n impartida por la propia empresa y obtendr\u00e1s la certificaci\u00f3n de \u201cUsuario en Gesti\u00f3n de RR.HH. en Meta4\u201d. Meta4 cuenta con una penetraci\u00f3n de mercado nacional del 55%, siendo referente entre las principales empresas y una penetraci\u00f3n del 25% en Latinoam\u00e9rica.\\nHorario en fin de semana compatible con tu actividad: Viernes de 17:30 a 21:30 y S\u00e1bados de 10:00 a 14:00 y de 15:00 a 19:00.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">\n<p style=\"text-align: left;\">El M\u00e1ster en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos proporciona las estrategias y las t\u00e9cnicas avanzadas para la funci\u00f3n de recursos humanos, y los elementos clave que marcar\u00e1n el futuro, basados en las organizaciones 2.0 y la tecnolog\u00eda digital.<\/p>\n<p style=\"text-align: left;\">Adquirir\u00e1s habilidades y competencias para satisfacer la demanda de perfiles altamente cualificados en funciones relacionadas con el dise\u00f1o, desarrollo e implementaci\u00f3n de pol\u00edticas innovadoras de RR.HH.<br \/>\nAprende haciendo, una metodolog\u00eda basada en la resoluci\u00f3n de casos reales desde el primer d\u00eda con la gu\u00eda de un claustro compuesto por docentes expertos en el \u00e1rea y reputados profesionales en activo.<br \/>\nNuestro programa mejorar\u00e1 tu empleabilidad al participar en el aprendizaje de las \u00faltimas tendencias en gesti\u00f3n de los RR.HH. En colaboraci\u00f3n con Meta4, compa\u00f1\u00eda dedicada a ofrecer Soluciones Globales para la gesti\u00f3n de la N\u00f3mina y los RR.HH.; recibir\u00e1s formaci\u00f3n impartida por la propia empresa y obtendr\u00e1s la certificaci\u00f3n de \u201cUsuario en Gesti\u00f3n de RR.HH. en Meta4\u201d. Meta4 cuenta con una penetraci\u00f3n de mercado nacional del 55%, siendo referente entre las principales empresas y una penetraci\u00f3n del 25% en Latinoam\u00e9rica.<br \/>\nHorario en fin de semana compatible con tu actividad: Viernes de 17:30 a 21:30 y S\u00e1bados de 10:00 a 14:00 y de 15:00 a 19:00.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Titulados universitarios que recientemente han finalizado su formaci\u00f3n que tienen inter\u00e9s por desarrollar su carrera profesional en el \u00e1mbito de la direcci\u00f3n y\/o gesti\u00f3n de recursos humanos. Titulados en Administraci\u00f3n y Direcci\u00f3n de Empresas, Derecho, Psicolog\u00eda, Ciencias Pol\u00edticas, Sociolog\u00eda o estudios afines del \u00e1mbito.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Titulados universitarios que recientemente han finalizado su formaci\u00f3n que tienen inter\u00e9s por desarrollar su carrera profesional en el \u00e1mbito de la direcci\u00f3n y\/o gesti\u00f3n de recursos humanos. Titulados en Administraci\u00f3n y Direcci\u00f3n de Empresas, Derecho, Psicolog\u00eda, Ciencias Pol\u00edticas, Sociolog\u00eda o estudios afines del \u00e1mbito.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 997px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[11]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valencia&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Valencia<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:606.6666666666666}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">606,67 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5460}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">5.460,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.000,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6460}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">6.460,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Adquiere los conocimientos y habilidades para gestionar y dirigir a las personas.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Adquiere los conocimientos y habilidades para gestionar y dirigir a las personas.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos de la Universidad Europea de Valencia (UEV) y el Colegio Oficial de Graduados Sociales de Valencia (COGRASOVA), es una herramienta formativa dirigida a titulados y profesionales con inquietudes en este \u00e1mbito, el cual tal y como indican recientes estudios e informes de prestigiosas consultoras, se encuentra entre las \u00e1reas de conocimiento y formaci\u00f3n m\u00e1s demandadas y valoradas por los estudiantes y los profesionales del mundo empresarial.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster en Gesti\u00f3n Global de Recursos Humanos de la Universidad Europea de Valencia (UEV) y el Colegio Oficial de Graduados Sociales de Valencia (COGRASOVA), es una herramienta formativa dirigida a titulados y profesionales con inquietudes en este \u00e1mbito, el cual tal y como indican recientes estudios e informes de prestigiosas consultoras, se encuentra entre las \u00e1reas de conocimiento y formaci\u00f3n m\u00e1s demandadas y valoradas por los estudiantes y los profesionales del mundo empresarial.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Directivos y responsables del \u00e1rea de los recursos humanos principalmente o de otras \u00e1reas de las empresas e instituciones como son las ventas, el marketing o las relaciones externas.\\n\\nBusiness partners.\\n\\nConsultores con experiencia en este \u00e1mbito o inquietud por el mismo.\\n\\nAlumnos que tras finalizar sus estudios de Grado quieren completar su formaci\u00f3n y activar su b\u00fasqueda de empleo en una de las \u00e1reas m\u00e1s solicitadas actualmente.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\n<p style=\"text-align: left;\">Directivos y responsables del \u00e1rea de los recursos humanos principalmente o de otras \u00e1reas de las empresas e instituciones como son las ventas, el marketing o las relaciones externas.<\/p>\n<p style=\"text-align: left;\">Business partners.<\/p>\n<p style=\"text-align: left;\">Consultores con experiencia en este \u00e1mbito o inquietud por el mismo.<\/p>\n<p style=\"text-align: left;\">Alumnos que tras finalizar sus estudios de Grado quieren completar su formaci\u00f3n y activar su b\u00fasqueda de empleo en una de las \u00e1reas m\u00e1s solicitadas actualmente.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1499px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA&quot;}\" data-sheets-formula=\"='UE - presencial'!R[12]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial (consultar por modalidad Online a distancia)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial (consultar por modalidad Online a distancia)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1266.6666666666667}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.266,67 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:11400}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">11.400,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:12500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">12.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Conoce las diferentes \u00e1reas de una compa\u00f1\u00eda y entiende su gesti\u00f3n con una visi\u00f3n global.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Conoce las diferentes \u00e1reas de una compa\u00f1\u00eda y entiende su gesti\u00f3n con una visi\u00f3n global.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas como Cognos . Gracias a las simulaciones o role plays, visitas a empresas, materclasses y resoluci\u00f3n de casos, te preparar\u00e1s para ser un profesional global.\\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.\\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.\\nTe orientar\u00e1s hacia puestos de responsabilidad a trav\u00e9s de conocimientos t\u00e9cnicos s\u00f3lidos junto con el desarrollo de competencias y habilidades directivas, gracias a nuestra metodolog\u00eda orientada a asumir puestos de responsabilidad.\\nDominar\u00e1s herramientas como Planning Analytics, Design Thinking. Aprender\u00e1s habilidades comunicativas y directivas para liderar equipos como Neuromanagement &amp; Mindfulness.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">Con el M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas como Cognos . Gracias a las simulaciones o role plays, visitas a empresas, materclasses y resoluci\u00f3n de casos, te preparar\u00e1s para ser un profesional global.<br \/>\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.<br \/>\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.<br \/>\nTe orientar\u00e1s hacia puestos de responsabilidad a trav\u00e9s de conocimientos t\u00e9cnicos s\u00f3lidos junto con el desarrollo de competencias y habilidades directivas, gracias a nuestra metodolog\u00eda orientada a asumir puestos de responsabilidad.<br \/>\nDominar\u00e1s herramientas como Planning Analytics, Design Thinking. Aprender\u00e1s habilidades comunicativas y directivas para liderar equipos como Neuromanagement &amp; Mindfulness.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a profesionales que deseen completar su formaci\u00f3n con un conocimiento completo y pr\u00e1ctico de las distintas \u00e1reas que componen el funcionamiento de una empresa.\\n\\nEste programa est\u00e1 especialmente dirigido a titulados universitarios de diversos \u00e1mbitos que tienen inter\u00e9s en conocer la gesti\u00f3n empresarial desde un punto de vista te\u00f3rico-pr\u00e1ctico o quieren desarrollar su esp\u00edritu emprendedor en el mundo de los negocios.\\n\\nTambi\u00e9n a aquellos profesionales que tengan inter\u00e9s por asumir retos de innovaci\u00f3n y por la formaci\u00f3n continua a lo largo de su vida profesional.\\n\\nNuestros alumnos provienen de titulaciones universitarias en Ingenier\u00edas, Derecho, Ciencias de la Salud, Administraci\u00f3n de Empresas, Econom\u00eda, as\u00ed como de otras titulaciones; y que quieren completar su formaci\u00f3n y\/o experiencia profesional para adquirir una visi\u00f3n global, integrada y estrat\u00e9gica de la empresa.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\n<p style=\"text-align: left;\">Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a profesionales que deseen completar su formaci\u00f3n con un conocimiento completo y pr\u00e1ctico de las distintas \u00e1reas que componen el funcionamiento de una empresa.<\/p>\n<p style=\"text-align: left;\">Este programa est\u00e1 especialmente dirigido a titulados universitarios de diversos \u00e1mbitos que tienen inter\u00e9s en conocer la gesti\u00f3n empresarial desde un punto de vista te\u00f3rico-pr\u00e1ctico o quieren desarrollar su esp\u00edritu emprendedor en el mundo de los negocios.<\/p>\n<p style=\"text-align: left;\">Tambi\u00e9n a aquellos profesionales que tengan inter\u00e9s por asumir retos de innovaci\u00f3n y por la formaci\u00f3n continua a lo largo de su vida profesional.<\/p>\n<p style=\"text-align: left;\">Nuestros alumnos provienen de titulaciones universitarias en Ingenier\u00edas, Derecho, Ciencias de la Salud, Administraci\u00f3n de Empresas, Econom\u00eda, as\u00ed como de otras titulaciones; y que quieren completar su formaci\u00f3n y\/o experiencia profesional para adquirir una visi\u00f3n global, integrada y estrat\u00e9gica de la empresa.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1186px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Business Analytics&quot;}\" data-sheets-formula=\"='UE - presencial'!R[13]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster en Business Analytics<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial (consultar por modalidad Online a distancia)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial (consultar por modalidad Online a distancia)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">8 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">8 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1238.888888888889}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.238,89 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:11150}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">11.150,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:12250}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">12.250,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Un M\u00e1ster \u00fanico, profesional y pr\u00e1ctico enfocado a la toma de decisiones en la empresa basada en anal\u00edtica de datos.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Un M\u00e1ster \u00fanico, profesional y pr\u00e1ctico enfocado a la toma de decisiones en la empresa basada en anal\u00edtica de datos.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el M\u00e1ster Universitario en Business Analytics aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas anal\u00edticas como SQL, Power BI, SAS, BigML, Apache Hadoop, Spark, Python, R Cognos y Tableau. Tambi\u00e9n utilizar\u00e1s t\u00e9cnicas anal\u00edticas a trav\u00e9s de Machine Learning, Inteligencia Artificial, Deep Learning, Cognitive Computing y Geolocalizaci\u00f3n.\\nLa titulaci\u00f3n cuenta con formaci\u00f3n desde cero. Contar\u00e1s con una formaci\u00f3n completa y global, eminentemente pr\u00e1ctica aplicada a la toma de decisiones basadas en grandes cantidades de datos.\\nDominar\u00e1s herramientas de obtenci\u00f3n de datos y de visualizaci\u00f3n de los mismos que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.\\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">En el M\u00e1ster Universitario en Business Analytics aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas anal\u00edticas como SQL, Power BI, SAS, BigML, Apache Hadoop, Spark, Python, R Cognos y Tableau. Tambi\u00e9n utilizar\u00e1s t\u00e9cnicas anal\u00edticas a trav\u00e9s de Machine Learning, Inteligencia Artificial, Deep Learning, Cognitive Computing y Geolocalizaci\u00f3n.<br \/>\nLa titulaci\u00f3n cuenta con formaci\u00f3n desde cero. Contar\u00e1s con una formaci\u00f3n completa y global, eminentemente pr\u00e1ctica aplicada a la toma de decisiones basadas en grandes cantidades de datos.<br \/>\nDominar\u00e1s herramientas de obtenci\u00f3n de datos y de visualizaci\u00f3n de los mismos que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.<br \/>\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;A todo aquel profesional interesado en desarrollar unas competencias \u00fanicas y de gran demanda para el entorno empresarial actual y futuro. Los estudiantes del M\u00e1ster son:\\n\\nProfesionales graduados que desean profundizar y dar un salto cualitativo en su profesi\u00f3n, adentr\u00e1ndose en el mundo de Business Analytics. En algunos casos son profesionales que buscan obtener un M\u00e1ster y certificaciones para cambiar de empresa o sector, as\u00ed como para tambi\u00e9n obtener nuevas posiciones dentro de su empresa.\\nOtro perfil de nuestros estudiantes son reci\u00e9n graduados que quieren profundizar m\u00e1s en el \u00e1mbito de Business Analytics y mejorar su posicionamiento en el mercado laboral a trav\u00e9s del m\u00e1ster y las certificaciones profesionales que ofrecemos.\\nDirectivos de nivel medio que requieren de una formaci\u00f3n espec\u00edfica para dirigir a sus equipos en el entorno Big Data&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\n<p style=\"text-align: left;\">A todo aquel profesional interesado en desarrollar unas competencias \u00fanicas y de gran demanda para el entorno empresarial actual y futuro. Los estudiantes del M\u00e1ster son:<\/p>\n<p style=\"text-align: left;\">Profesionales graduados que desean profundizar y dar un salto cualitativo en su profesi\u00f3n, adentr\u00e1ndose en el mundo de Business Analytics. En algunos casos son profesionales que buscan obtener un M\u00e1ster y certificaciones para cambiar de empresa o sector, as\u00ed como para tambi\u00e9n obtener nuevas posiciones dentro de su empresa.<br \/>\nOtro perfil de nuestros estudiantes son reci\u00e9n graduados que quieren profundizar m\u00e1s en el \u00e1mbito de Business Analytics y mejorar su posicionamiento en el mercado laboral a trav\u00e9s del m\u00e1ster y las certificaciones profesionales que ofrecemos.<br \/>\nDirectivos de nivel medio que requieren de una formaci\u00f3n espec\u00edfica para dirigir a sus equipos en el entorno Big Data<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1454px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones&quot;}\" data-sheets-formula=\"='UE - presencial'!R[14]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencia de Datos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial (consultar por modalidad Online a distancia)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial (consultar por modalidad Online a distancia)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:922.2222222222222}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">922,22 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8300}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">8.300,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9400}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.400,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Estudia el m\u00e1ster online en Ciberseguridad que te especializar\u00e1 en seguridad inform\u00e1tica desde las vertientes t\u00e9cnica, t\u00e1ctica y estrat\u00e9gica.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Estudia el m\u00e1ster online en Ciberseguridad que te especializar\u00e1 en seguridad inform\u00e1tica desde las vertientes t\u00e9cnica, t\u00e1ctica y estrat\u00e9gica.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones otorga Certificaciones CISSP y CISM.\\nEste m\u00e1ster te prepara para la obtenci\u00f3n de dos de las certificaciones m\u00e1s importantes y reconocidas internacionalmente en el \u00e1mbito de la Seguridad Inform\u00e1tica, que muestran la madurez de los profesionales en seguridad digital. Dise\u00f1adas para alcanzar puestos de direcci\u00f3n.\\n\\nEl M\u00e1ster Oficial en Seguridad de las TIC de la Universidad Europea est\u00e1 considerado entre los 5 mejores m\u00e1steres en inform\u00e1tica, seg\u00fan el ranking de El Mundo.\\n\\nTus profesores ser\u00e1n profesionales de reconocida trayectoria en el mundo de la seguridad inform\u00e1tica de tecnolog\u00edas de la informaci\u00f3n y de las comunicaciones: El director del programa, Abel Lozoya, es Auditor Jefe ISO 27001 por AENOR y es Certified Ethical Hacker (CEH) por EC-Council.\\nEl claustro est\u00e1 formado por profesionales de prestigio que provienen de distintas \u00e1reas de la seguridad en las TIC, en empresas como ISDEFE, INTA, TELEF\u00d3NICA, BBVA o ISACA.\\n\\nAprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a las simulaciones o role plays, te preparar\u00e1s para ser un profesional global.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones otorga Certificaciones CISSP y CISM.<br \/>\nEste m\u00e1ster te prepara para la obtenci\u00f3n de dos de las certificaciones m\u00e1s importantes y reconocidas internacionalmente en el \u00e1mbito de la Seguridad Inform\u00e1tica, que muestran la madurez de los profesionales en seguridad digital. Dise\u00f1adas para alcanzar puestos de direcci\u00f3n.El M\u00e1ster Oficial en Seguridad de las TIC de la Universidad Europea est\u00e1 considerado entre los 5 mejores m\u00e1steres en inform\u00e1tica, seg\u00fan el ranking de El Mundo.Tus profesores ser\u00e1n profesionales de reconocida trayectoria en el mundo de la seguridad inform\u00e1tica de tecnolog\u00edas de la informaci\u00f3n y de las comunicaciones: El director del programa, Abel Lozoya, es Auditor Jefe ISO 27001 por AENOR y es Certified Ethical Hacker (CEH) por EC-Council.<br \/>\nEl claustro est\u00e1 formado por profesionales de prestigio que provienen de distintas \u00e1reas de la seguridad en las TIC, en empresas como ISDEFE, INTA, TELEF\u00d3NICA, BBVA o ISACA.Aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a las simulaciones o role plays, te preparar\u00e1s para ser un profesional global.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Este M\u00e1ster est\u00e1 especialmente dise\u00f1ado para graduados, ingenieros inform\u00e1ticos, ingenieros de telecomunicaciones e ingenieros t\u00e9cnicos del \u00e1rea TIC, as\u00ed como profesionales del \u00e1rea de TI en cualquiera de sus sectores que posean una titulaci\u00f3n oficial universitaria y experiencia demostrada en el \u00e1rea TIC cubriendo todos los aspectos t\u00e9cnicos necesarios para cursar el m\u00e1ster con \u00e9xito.\\n\\nRequisitos de acceso: Disponer de un t\u00edtulo oficial universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo oficial universitario en un \u00e1rea t\u00e9cnica y contar con experiencia en Tecnolog\u00edas de la Informaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\n<p style=\"text-align: left;\">Este M\u00e1ster est\u00e1 especialmente dise\u00f1ado para graduados, ingenieros inform\u00e1ticos, ingenieros de telecomunicaciones e ingenieros t\u00e9cnicos del \u00e1rea TIC, as\u00ed como profesionales del \u00e1rea de TI en cualquiera de sus sectores que posean una titulaci\u00f3n oficial universitaria y experiencia demostrada en el \u00e1rea TIC cubriendo todos los aspectos t\u00e9cnicos necesarios para cursar el m\u00e1ster con \u00e9xito.<\/p>\n<p style=\"text-align: left;\">Requisitos de acceso: Disponer de un t\u00edtulo oficial universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo oficial universitario en un \u00e1rea t\u00e9cnica y contar con experiencia en Tecnolog\u00edas de la Informaci\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo universitario en un \u00e1rea t\u00e9cnica y experiencia probada en Tecnolog\u00edas de la Informaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo universitario en un \u00e1rea t\u00e9cnica y experiencia probada en Tecnolog\u00edas de la Informaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1370px;\" width=\"918\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos - MBI \/ Big Data Analytics - MBI&quot;}\" data-sheets-formula=\"='UE - presencial'!R[15]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos &#8211; MBI \/ Big Data Analytics &#8211; MBI<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencia de Datos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1122.2222222222222}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.122,22 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:10100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">10.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:11200}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">11.200,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos - MBI \/ Big Data Analytics - MBI te prepara para convertirte en uno de los profesionales m\u00e1s buscados. Te formar\u00e1s con profesionales del dato que lideran los sectores de banca, salud, telecomunicaciones y consultor\u00eda.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">El M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos &#8211; MBI \/ Big Data Analytics &#8211; MBI te prepara para convertirte en uno de los profesionales m\u00e1s buscados. Te formar\u00e1s con profesionales del dato que lideran los sectores de banca, salud, telecomunicaciones y consultor\u00eda.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos - MBI \/ Big Data Analytics - MBI te permitir\u00e1 compatibilizar la actividad laboral con tu formaci\u00f3n de calidad en una de las profesiones de mayor proyecci\u00f3n.\\n\\nEn el M\u00e1ster Universitario dispondr\u00e1s de las mejores instalaciones: Dos clusters para procesamiento de grandes vol\u00famenes de datos: Uno principal con m\u00e1s de 25 nodos homog\u00e9neos de proceso y 2TB de memoria ram, y otro secundario formado por 4 m\u00e1quinas servidoras con alta capacidades de procesamiento y memoria (multicore, +64GB por nodo). Ambos cuentan con Apache Hadoop, HDFS, Apache Spark, y lenguajes\/herramientas de acceso a bases de datos noSQL Hive o Impala.\\nAprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a simulaciones y role plays, te preparar\u00e1s para ser un profesional global en Big Data.\\nPodr\u00e1s conocer de primera mano y hacer networking con profesionales de reconocidas empresas que te presentar\u00e1n casos reales. Adem\u00e1s, tendr\u00e1s masterclasses impartidas por profesionales que est\u00e1n en contacto con esta tecnolog\u00eda en su d\u00eda a d\u00eda.\\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">\n<p style=\"text-align: left;\">El M\u00e1ster Universitario en An\u00e1lisis de Grandes Cantidades de Datos &#8211; MBI \/ Big Data Analytics &#8211; MBI te permitir\u00e1 compatibilizar la actividad laboral con tu formaci\u00f3n de calidad en una de las profesiones de mayor proyecci\u00f3n.<\/p>\n<p style=\"text-align: left;\">En el M\u00e1ster Universitario dispondr\u00e1s de las mejores instalaciones: Dos clusters para procesamiento de grandes vol\u00famenes de datos: Uno principal con m\u00e1s de 25 nodos homog\u00e9neos de proceso y 2TB de memoria ram, y otro secundario formado por 4 m\u00e1quinas servidoras con alta capacidades de procesamiento y memoria (multicore, +64GB por nodo). Ambos cuentan con Apache Hadoop, HDFS, Apache Spark, y lenguajes\/herramientas de acceso a bases de datos noSQL Hive o Impala.<br \/>\nAprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a simulaciones y role plays, te preparar\u00e1s para ser un profesional global en Big Data.<br \/>\nPodr\u00e1s conocer de primera mano y hacer networking con profesionales de reconocidas empresas que te presentar\u00e1n casos reales. Adem\u00e1s, tendr\u00e1s masterclasses impartidas por profesionales que est\u00e1n en contacto con esta tecnolog\u00eda en su d\u00eda a d\u00eda.<br \/>\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Para acceder a este m\u00e1ster deber\u00e1s: estar en posesi\u00f3n de un t\u00edtulo universitario oficial espa\u00f1ol u otro expedido por una instituci\u00f3n de Educaci\u00f3n Superior perteneciente a otro estado integrante del Espacio Europeo de Educaci\u00f3n Superior que faculte en el mismo para el acceso a ense\u00f1anzas de M\u00e1ster.\\n\\nTener un t\u00edtulo en las \u00e1reas de Matem\u00e1ticas, Estad\u00edstica o Ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\n<p style=\"text-align: left;\">Para acceder a este m\u00e1ster deber\u00e1s: estar en posesi\u00f3n de un t\u00edtulo universitario oficial espa\u00f1ol u otro expedido por una instituci\u00f3n de Educaci\u00f3n Superior perteneciente a otro estado integrante del Espacio Europeo de Educaci\u00f3n Superior que faculte en el mismo para el acceso a ense\u00f1anzas de M\u00e1ster.<\/p>\n<p style=\"text-align: left;\">Tener un t\u00edtulo en las \u00e1reas de Matem\u00e1ticas, Estad\u00edstica o Ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo universitario sobre las \u00e1reas de matem\u00e1ticas, estad\u00edstica o ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo universitario sobre las \u00e1reas de matem\u00e1ticas, estad\u00edstica o ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1009px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n Deportiva&quot;}\" data-sheets-formula=\"='UE - presencial'!R[16]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n Deportiva<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1350}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.350,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:13700}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">13.700 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:15200}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">15.200,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Viernes y s\u00e1bados de 9.00 a 14.00 h. y de 15.00 a 20.00 h.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">Viernes y s\u00e1bados de 9.00 a 14.00 h. y de 15.00 a 20.00 h.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00danico m\u00e1ster oficial en Espa\u00f1a especializado en entrenamiento y nutrici\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">\u00danico m\u00e1ster oficial en Espa\u00f1a especializado en entrenamiento y nutrici\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n\\nDeportiva est\u00e1 dise\u00f1ado para dotar a los estudiantes\\nde conocimientos especializados sobre los m\u00e9todos\\nde entrenamiento m\u00e1s vanguardistas, las \u00faltimas\\ntendencias en nutrici\u00f3n deportiva y las ayudas\\nergog\u00e9nicas naturales para mejorar el rendimiento\\ndeportivo.\\nAl abarcar dos \u00e1mbitos de conocimiento diferentes\\npero complementarios entre s\u00ed, el del entrenamiento y\\nla nutrici\u00f3n, el futuro egresado estar\u00e1 en la capacidad\\nde desarrollar un diagn\u00f3stico integral acerca de los\\nh\u00e1bitos o estrategias nutricionales \u00f3ptimas para cada\\ntipo o necesidad de entrenamiento.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Entrenamiento y Nutrici\u00f3n<br \/>\nDeportiva est\u00e1 dise\u00f1ado para dotar a los estudiantes<br \/>\nde conocimientos especializados sobre los m\u00e9todos<br \/>\nde entrenamiento m\u00e1s vanguardistas, las \u00faltimas<br \/>\ntendencias en nutrici\u00f3n deportiva y las ayudas<br \/>\nergog\u00e9nicas naturales para mejorar el rendimiento<br \/>\ndeportivo.<br \/>\nAl abarcar dos \u00e1mbitos de conocimiento diferentes<br \/>\npero complementarios entre s\u00ed, el del entrenamiento y<br \/>\nla nutrici\u00f3n, el futuro egresado estar\u00e1 en la capacidad<br \/>\nde desarrollar un diagn\u00f3stico integral acerca de los<br \/>\nh\u00e1bitos o estrategias nutricionales \u00f3ptimas para cada<br \/>\ntipo o necesidad de entrenamiento.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dirigido a licenciados y\/o graduados en Ciencias de la\\nActividad F\u00edsica, diplomados en Nutrici\u00f3n, diplomados\\nen Magisterio de Educaci\u00f3n F\u00edsica, licenciados en\\nMedicina y diplomados en Fisioterapia o Enfermer\u00eda.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Dirigido a licenciados y\/o graduados en Ciencias de la<br \/>\nActividad F\u00edsica, diplomados en Nutrici\u00f3n, diplomados<br \/>\nen Magisterio de Educaci\u00f3n F\u00edsica, licenciados en<br \/>\nMedicina y diplomados en Fisioterapia o Enfermer\u00eda.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1060px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Nutrici\u00f3n Cl\u00ednica&quot;}\" data-sheets-formula=\"='UE - presencial'!R[17]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Nutrici\u00f3n Cl\u00ednica<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:568}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">568,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5890}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">5.890 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6990}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">6.990,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Te formar\u00e1s con un profesorado multidisciplinar compuesto por dietistas-nutricionistas, m\u00e9dicos dedicados a la Nutrici\u00f3n Cl\u00ednica, con los que se tendr\u00e1s una formaci\u00f3n completa y de calidad.\\nRealizar\u00e1s las pr\u00e1cticas en hospitales, residencias de mayores y centros de salud como son el Hospital Moncloa, el Hospital de especializaci\u00f3n en C\u00e1ncer MD ANDERSON INTERNACIONAL ESPA\u00d1A, hospitales del SERMAS y residencias del grupo GERIAVI.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Te formar\u00e1s con un profesorado multidisciplinar compuesto por dietistas-nutricionistas, m\u00e9dicos dedicados a la Nutrici\u00f3n Cl\u00ednica, con los que se tendr\u00e1s una formaci\u00f3n completa y de calidad.<br \/>\nRealizar\u00e1s las pr\u00e1cticas en hospitales, residencias de mayores y centros de salud como son el Hospital Moncloa, el Hospital de especializaci\u00f3n en C\u00e1ncer MD ANDERSON INTERNACIONAL ESPA\u00d1A, hospitales del SERMAS y residencias del grupo GERIAVI.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster universitario en nutrici\u00f3n cl\u00ednica tiene como\\nfinalidad formar y especializar a profesionales de ciencias\\nde la salud en el dise\u00f1o de programas nutricionales,\\nvaloraci\u00f3n y seguimiento nutricional de patolog\u00edas;\\ncontando para todo ello, con un profesorado multidisciplinar,\\ncompuesto por Dietistas-Nutricionistas, m\u00e9dicos dedicados\\na la nutrici\u00f3n cl\u00ednica, con los que se dar\u00e1 una formaci\u00f3n\\ncompleta y de calidad.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster universitario en nutrici\u00f3n cl\u00ednica tiene como<br \/>\nfinalidad formar y especializar a profesionales de ciencias<br \/>\nde la salud en el dise\u00f1o de programas nutricionales,<br \/>\nvaloraci\u00f3n y seguimiento nutricional de patolog\u00edas;<br \/>\ncontando para todo ello, con un profesorado multidisciplinar,<br \/>\ncompuesto por Dietistas-Nutricionistas, m\u00e9dicos dedicados<br \/>\na la nutrici\u00f3n cl\u00ednica, con los que se dar\u00e1 una formaci\u00f3n<br \/>\ncompleta y de calidad.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster est\u00e1 enfocado a estudiantes con el siguiente\\nperfil de ingreso:\\n\u2666 Graduados\/ Diplomados en Nutrici\u00f3n Humana y Diet\u00e9tica.\\n\u2666 Graduados\/ Diplomados en Enfermer\u00eda.\\n\u2666 Graduados\/ Licenciados en Medicina.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">El M\u00e1ster est\u00e1 enfocado a estudiantes con el siguiente<br \/>\nperfil de ingreso:<br \/>\n\u2666 Graduados\/ Diplomados en Nutrici\u00f3n Humana y Diet\u00e9tica.<br \/>\n\u2666 Graduados\/ Diplomados en Enfermer\u00eda.<br \/>\n\u2666 Graduados\/ Licenciados en Medicina.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1211px;\" width=\"917\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Fisioterapia Deportiva&quot;}\" data-sheets-formula=\"='UE - presencial'!R[18]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en Fisioterapia Deportiva<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">24\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1477.77}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">1.477,77 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:13300}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">13.300 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:14800}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">14.800,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 Viernes de 15.00 a 21.00 h.\\n\u2022 S\u00e1bados de 10.00 a 14.00 h. y de 15.00 a 21.00 h.\\n\u2022 Domingos de 10.00 a 14.00 h.\\nLas pr\u00e1cticas se desarrollar\u00e1n de lunes a viernes en los\\nhorarios de los entrenamientos seg\u00fan cada entidad\\ndeportiva.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">\u2022 Viernes de 15.00 a 21.00 h.<br \/>\n\u2022 S\u00e1bados de 10.00 a 14.00 h. y de 15.00 a 21.00 h.<br \/>\n\u2022 Domingos de 10.00 a 14.00 h.<br \/>\nLas pr\u00e1cticas se desarrollar\u00e1n de lunes a viernes en los<br \/>\nhorarios de los entrenamientos seg\u00fan cada entidad<br \/>\ndeportiva.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El objetivo del m\u00e1ster es desarrollar habilidades t\u00e9cnicas avanzadas que ayuden a los fisioterapeutas a afrontar el diagn\u00f3stico y la asistencia terap\u00e9utica de protocolo y de urgencia de deportistas.\\n- El 100% de los alumnos hacen pr\u00e1cticas en la CIudad Deportiva del Real Madrid C.F.\\n- La formaci\u00f3n esta respaldada por el equipo de fisioterapia del Real Madrid C.F. y de los servicios m\u00e9dicos y fisioterapia del deporte de \u00e9lite.\\n- Mejor M\u00e1ster especializado en el \u00e1rea de Fisioterapia, seg\u00fan Ranking del diario El Mundo 2019.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">El objetivo del m\u00e1ster es desarrollar habilidades t\u00e9cnicas avanzadas que ayuden a los fisioterapeutas a afrontar el diagn\u00f3stico y la asistencia terap\u00e9utica de protocolo y de urgencia de deportistas.<br \/>\n&#8211; El 100% de los alumnos hacen pr\u00e1cticas en la CIudad Deportiva del Real Madrid C.F.<br \/>\n&#8211; La formaci\u00f3n esta respaldada por el equipo de fisioterapia del Real Madrid C.F. y de los servicios m\u00e9dicos y fisioterapia del deporte de \u00e9lite.<br \/>\n&#8211; Mejor M\u00e1ster especializado en el \u00e1rea de Fisioterapia, seg\u00fan Ranking del diario El Mundo 2019.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Fisioterapia Deportiva tiene la intenci\u00f3n de\\ndotar a los fisioterapeutas de las habilidades y los recursos necesarios\\npara prevenir, tratar y conseguir una r\u00e1pida restauraci\u00f3n de la funci\u00f3n en\\nel deportista lesionado en el marco de un equipo multidisciplinar.\\nAsimismo, los estudiantes ser\u00e1n capaces de desarrollar el m\u00e1ximo\\npotencial preventivo y terap\u00e9utico inherente a su especialidad, y estar\u00e1n\\ncualificados para perfeccionar una pr\u00e1ctica basada en la evidencia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Fisioterapia Deportiva tiene la intenci\u00f3n de<br \/>\ndotar a los fisioterapeutas de las habilidades y los recursos necesarios<br \/>\npara prevenir, tratar y conseguir una r\u00e1pida restauraci\u00f3n de la funci\u00f3n en<br \/>\nel deportista lesionado en el marco de un equipo multidisciplinar.<br \/>\nAsimismo, los estudiantes ser\u00e1n capaces de desarrollar el m\u00e1ximo<br \/>\npotencial preventivo y terap\u00e9utico inherente a su especialidad, y estar\u00e1n<br \/>\ncualificados para perfeccionar una pr\u00e1ctica basada en la evidencia.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fisioterapeutas interesados en encaminar sus conocimientos de fisioterapia en la prevenci\u00f3n, rehabilitaci\u00f3n y recuperaci\u00f3n de lesiones derivadas de la pr\u00e1ctica deportiva a cualquier nivel de exigencia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Fisioterapeutas interesados en encaminar sus conocimientos de fisioterapia en la prevenci\u00f3n, rehabilitaci\u00f3n y recuperaci\u00f3n de lesiones derivadas de la pr\u00e1ctica deportiva a cualquier nivel de exigencia.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1201px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Actividad F\u00edsica y Salud&quot;}\" data-sheets-formula=\"='UE - presencial'!R[19]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Actividad F\u00edsica y Salud<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">24\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:866.66}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">866,66 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:7900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">7.900 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1500}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.500,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9400}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.400,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 Fines de semana alternos.\\n\u2022 Viernes de 16.30 a 21.30 h.\\n\u2022 S\u00e1bados de 9.30 a 14.30 h. y de 15.30 a 19.30 h.\\n\u2022 Domingos de 9.30 a 14.30 h.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">\u2022 Fines de semana alternos.<br \/>\n\u2022 Viernes de 16.30 a 21.30 h.<br \/>\n\u2022 S\u00e1bados de 9.30 a 14.30 h. y de 15.30 a 19.30 h.<br \/>\n\u2022 Domingos de 9.30 a 14.30 h.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Te formar\u00e1s en el centro l\u00edder en investigaci\u00f3n y aprender\u00e1s a planificar y programar entrenamientos orientados a la mejora de la salud y la calidad de vida.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Te formar\u00e1s en el centro l\u00edder en investigaci\u00f3n y aprender\u00e1s a planificar y programar entrenamientos orientados a la mejora de la salud y la calidad de vida.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Actividad F\u00edsica y Salud\\nde la Escuela Universitaria Real Madrid - Universidad\\nEuropea est\u00e1 dise\u00f1ado para aportar a los estudiantes los\\nconocimientos necesarios que les permitan planificar y\\nprogramar entrenamientos orientados a la mejora de la salud\\ny la calidad de vida.\\nEste m\u00e1ster oficial permite elegir entre 2 itinerarios diferentes.\\nUno con perfil netamente investigador y otro con un perfil\\norientado al mundo profesional. De este modo los estudiantes\\npueden elegir el itinerario que mejor se adapta a sus intereses\\ny a su necesidades profesionales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Actividad F\u00edsica y Salud<br \/>\nde la Escuela Universitaria Real Madrid &#8211; Universidad<br \/>\nEuropea est\u00e1 dise\u00f1ado para aportar a los estudiantes los<br \/>\nconocimientos necesarios que les permitan planificar y<br \/>\nprogramar entrenamientos orientados a la mejora de la salud<br \/>\ny la calidad de vida.<br \/>\nEste m\u00e1ster oficial permite elegir entre 2 itinerarios diferentes.<br \/>\nUno con perfil netamente investigador y otro con un perfil<br \/>\norientado al mundo profesional. De este modo los estudiantes<br \/>\npueden elegir el itinerario que mejor se adapta a sus intereses<br \/>\ny a su necesidades profesionales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 Graduados o licenciados en Ciencias de la Actividad\\nF\u00edsica y del Deporte.\\n\u2022 Licenciados en Educaci\u00f3n F\u00edsica.\\n\u2022 Graduados o licenciados en Magisterio con\\nespecialidad en Educaci\u00f3n F\u00edsica.\\n\u2022 Graduados o licenciados en Medicina.\\n\u2022 Graduados o diplomados en Enfermer\u00eda.\\n\u2022 Graduados o licenciados en Fisioterapia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">\u2022 Graduados o licenciados en Ciencias de la Actividad<br \/>\nF\u00edsica y del Deporte.<br \/>\n\u2022 Licenciados en Educaci\u00f3n F\u00edsica.<br \/>\n\u2022 Graduados o licenciados en Magisterio con<br \/>\nespecialidad en Educaci\u00f3n F\u00edsica.<br \/>\n\u2022 Graduados o licenciados en Medicina.<br \/>\n\u2022 Graduados o diplomados en Enfermer\u00eda.<br \/>\n\u2022 Graduados o licenciados en Fisioterapia.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1024px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[20]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:888.88}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">888,88 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8200}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">8.200 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9300}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.300,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Es el \u00fanico master oficial en Espa\u00f1a centrado en el tratamiento integral de los Trastornos del comportamiento alimentario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Es el \u00fanico master oficial en Espa\u00f1a centrado en el tratamiento integral de los Trastornos del comportamiento alimentario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad obtendr\u00e1s una formaci\u00f3n de primer nivel en el diagn\u00f3stico, el tratamiento y la investigaci\u00f3n de la anorexia nerviosa, el trastorno por atrac\u00f3n, el trastorno evitativo-restrictivo de la ingesta y la Obesidad.\\nEsta titulaci\u00f3n te dotar\u00e1 de los conocimientos te\u00f3rico-pr\u00e1cticos y las competencias profesionales requeridas en esta especializaci\u00f3n en los entornos sanitarios desde diferentes perspectivas cl\u00ednicas y de investigaci\u00f3n. Y lo har\u00e1s en contacto permanente con unidades hospitalarias especializadas en trastornos alimentarios y con la gu\u00eda de un tutor cl\u00ednico.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">Con el M\u00e1ster Universitario en Trastornos del Comportamiento Alimentario y Obesidad obtendr\u00e1s una formaci\u00f3n de primer nivel en el diagn\u00f3stico, el tratamiento y la investigaci\u00f3n de la anorexia nerviosa, el trastorno por atrac\u00f3n, el trastorno evitativo-restrictivo de la ingesta y la Obesidad.<br \/>\nEsta titulaci\u00f3n te dotar\u00e1 de los conocimientos te\u00f3rico-pr\u00e1cticos y las competencias profesionales requeridas en esta especializaci\u00f3n en los entornos sanitarios desde diferentes perspectivas cl\u00ednicas y de investigaci\u00f3n. Y lo har\u00e1s en contacto permanente con unidades hospitalarias especializadas en trastornos alimentarios y con la gu\u00eda de un tutor cl\u00ednico.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Licenciados\/Graduados en titulaciones en el \u00e1rea de la salud (Medicina, Nutrici\u00f3n, Psicolog\u00eda y otras titulaciones vinculadas a la profesi\u00f3n sanitaria) que quieran especializarse en los Trastornos del Comportamiento Alimentario y la Obesidad, preferiblemente con experiencia cl\u00ednica y\/o investigadora, que est\u00e9n interesados en formarse, especializarse y convertirse en profesionales expertos en este \u00e1rea.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Licenciados\/Graduados en titulaciones en el \u00e1rea de la salud (Medicina, Nutrici\u00f3n, Psicolog\u00eda y otras titulaciones vinculadas a la profesi\u00f3n sanitaria) que quieran especializarse en los Trastornos del Comportamiento Alimentario y la Obesidad, preferiblemente con experiencia cl\u00ednica y\/o investigadora, que est\u00e9n interesados en formarse, especializarse y convertirse en profesionales expertos en este \u00e1rea.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 784px;\" width=\"918\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"226\" \/>\n<col width=\"620\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Terapia Manual Ortopedica y Tratamiento del Dolor&quot;}\" data-sheets-formula=\"='UE - presencial'!R[21]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Terapia Manual Ortopedica y Tratamiento del Dolor<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00c1rea de Estudio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-2]C[1]\">\u00c1rea de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-3]C[2]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Presencial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;3;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-4]C[3]\">1 de marzo y 31 de marzo de 2022.Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Madrid&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;4;FALSO)\">Madrid<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-5]C[4]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44858}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;5;FALSO)\">24\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-7]C[6]\">Cuotas<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuota x monto&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-8]C[7]\">Cuota x monto<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:943.33}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;8;FALSO)\">943,33 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-9]C[8]\">Arancel<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8490}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;9;FALSO)\">8.490 \u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;10;FALSO)\">1.100,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9590}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;11;FALSO)\">9.590,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-13]C[11]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;15 horas semanales&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;12;FALSO)\">15 horas semanales<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Calendario acad\u00e9mico&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-14]C[12]\">Calendario acad\u00e9mico<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)\\n\\nLos ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;13;FALSO)\">\n<p style=\"text-align: left;\">El d\u00eda de inicio y los horarios aun no est\u00e1n disponibles para nuestros programas de oto\u00f1o. (En junio aproximadamente tendremos toda la informaci\u00f3n actualizada.)<\/p>\n<p style=\"text-align: left;\">Los ex\u00e1menes tienen fechas variadas dependiendo del master y contienen dos convocatorias (diciembre y junio). Para poder superar cada m\u00f3dulo de master es necesario tener una puntuaci\u00f3n igual o superior a 5 sobre 10.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-16]C[15]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Primer m\u00e1ster interdisciplinar en Espa\u00f1a en el \u00e1rea de la terapia manual ortop\u00e9dica, pioneros en abordar el dolor desde una esfera multimodal&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;16;FALSO)\">Primer m\u00e1ster interdisciplinar en Espa\u00f1a en el \u00e1rea de la terapia manual ortop\u00e9dica, pioneros en abordar el dolor desde una esfera multimodal<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-17]C[16]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Terapia Manual Ortop\u00e9dica en el Tratamiento del Dolor de la Universidad Europea presenta un\\nambicioso plan de estudios dentro de la teor\u00eda biopsicosocial, basado en los \u00faltimos m\u00e9todos terap\u00e9uticos manuales, control motor, ejercicios terap\u00e9uticos y m\u00e9todos cognitivos-conductuales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;17;FALSO)\">El M\u00e1ster Universitario en Terapia Manual Ortop\u00e9dica en el Tratamiento del Dolor de la Universidad Europea presenta un<br \/>\nambicioso plan de estudios dentro de la teor\u00eda biopsicosocial, basado en los \u00faltimos m\u00e9todos terap\u00e9uticos manuales, control motor, ejercicios terap\u00e9uticos y m\u00e9todos cognitivos-conductuales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-18]C[17]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dirigido a Diplomados y Graduados en Fisioterapia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;18;FALSO)\">Dirigido a Diplomados y Graduados en Fisioterapia.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-20]C[13]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;14;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - presencial'!R[-21]C[14]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - presencial'!C1:C18;15;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 700px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol 48&quot;}\" data-sheets-formula=\"='UE - Online'!R[27]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Deporte&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Deporte<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Presencial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44543}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">24\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:644}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">1.060 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">10.600 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">1.500 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">12.100 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Direcci\u00f3n de F\u00fatbol y Metodolog\u00edas de Juego es el \u00fanico m\u00e1ster online enfocado a mejorar las habilidades del entrenador de f\u00fatbol. Este programa te permitir\u00e1 mejorar tu desarrollo profesional y convertirte en un entrenador de \u00e9xito.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster en Direcci\u00f3n de F\u00fatbol y Metodolog\u00edas de Juego es el \u00fanico m\u00e1ster online enfocado a mejorar las habilidades del entrenador de f\u00fatbol. Este programa te permitir\u00e1 mejorar tu desarrollo profesional y convertirte en un entrenador de \u00e9xito.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1><strong>M\u00e1ster\u00a0 &#8211; Online<\/strong><\/h1>\n<table dir=\"ltr\" style=\"height: 1188px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Marketing 5&quot;}\" data-sheets-formula=\"='UE - Online'!R[1]C[0]\"><span style=\"color: #ff0000;\"><strong>Master Universitario en Marketing<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Marketing&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Marketing<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:469}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">469\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Impulsa tu carrera profesional en los puestos de trabajo que demanda la nueva Econom\u00eda Digital. &quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Impulsa tu carrera profesional en los puestos de trabajo que demanda la nueva Econom\u00eda Digital.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Marketing propone soluciones que supongan una alternativa a problemas planteados por la empresa en el aula, trabajando en grupos con metolog\u00edas activas y design thinking.\\nTe convertir\u00e1s en el profesional del marketing que buscan las empresas, porque ser\u00e1s capaz de elaborar una estrategia de marketing en un plan de marketing integral, combinando pensamiento creativo con el anal\u00edtico. Tambien estar\u00e1s capacitado para desarrollarte como director comercial, asaaegurando el logro de los objetivos de la empresa.\\nAprender\u00e1s a realizar investigaciones de mercado para detectar oportunidades de negocio, utilizando herramientas de an\u00e1lisis complejas para predecir, optimizar o testar resultados: t\u00e9cnicas para segmentaci\u00f3n de mercado, posicionamiento de productos, CRM, Google Analytics, etc.\\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio. Adem\u00e1s, tendr\u00e1s masterclass impartidas por profesionales de empresas innovadoras.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster Universitario en Marketing propone soluciones que supongan una alternativa a problemas planteados por la empresa en el aula, trabajando en grupos con metolog\u00edas activas y design thinking.<br \/>\nTe convertir\u00e1s en el profesional del marketing que buscan las empresas, porque ser\u00e1s capaz de elaborar una estrategia de marketing en un plan de marketing integral, combinando pensamiento creativo con el anal\u00edtico. Tambien estar\u00e1s capacitado para desarrollarte como director comercial, asaaegurando el logro de los objetivos de la empresa.<br \/>\nAprender\u00e1s a realizar investigaciones de mercado para detectar oportunidades de negocio, utilizando herramientas de an\u00e1lisis complejas para predecir, optimizar o testar resultados: t\u00e9cnicas para segmentaci\u00f3n de mercado, posicionamiento de productos, CRM, Google Analytics, etc.<br \/>\nDominar\u00e1s herramientas de planificaci\u00f3n o gesti\u00f3n que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio. Adem\u00e1s, tendr\u00e1s masterclass impartidas por profesionales de empresas innovadoras.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Si sientes pasi\u00f3n por el Marketing que se hace hoy y las nuevas t\u00e9cnicas de captaci\u00f3n comercial, este es tu M\u00e1ster.\\n\\nEl m\u00e1ster est\u00e1 dirigido a graduados en el \u00e1rea de empresa, marketing, turismo y comunicaci\u00f3n, as\u00ed como, en otras \u00e1reas de las Ciencias Sociales como sociolog\u00eda o psicolog\u00eda, sin descartar la posibilidad de acceso a graduados en otras \u00e1reas con inquietudes profesionales dirigidas hacia el campo de los negocios y la comunicaci\u00f3n. Profesionales del \u00e1mbito del Marketing con al menos un a\u00f1o de experiencia.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Si sientes pasi\u00f3n por el Marketing que se hace hoy y las nuevas t\u00e9cnicas de captaci\u00f3n comercial, este es tu M\u00e1ster.<\/p>\n<p>El m\u00e1ster est\u00e1 dirigido a graduados en el \u00e1rea de empresa, marketing, turismo y comunicaci\u00f3n, as\u00ed como, en otras \u00e1reas de las Ciencias Sociales como sociolog\u00eda o psicolog\u00eda, sin descartar la posibilidad de acceso a graduados en otras \u00e1reas con inquietudes profesionales dirigidas hacia el campo de los negocios y la comunicaci\u00f3n. Profesionales del \u00e1mbito del Marketing con al menos un a\u00f1o de experiencia.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Marketing-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Marketing-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Marketing-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Marketing-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1177px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Direcci\u00f3n de Protocolo y Organizacion de Eventos 23&quot;}\" data-sheets-formula=\"='UE - Online'!R[2]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster en Direcci\u00f3n de Protocolo y Organizaci\u00f3n de Eventos<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Marketing y Comunicaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Marketing y Comunicaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:566}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">566\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Direcci\u00f3n de Protocolo y Organizaci\u00f3n de Eventos es el \u00fanico m\u00e1ster 100% online en este campo que diferencia la organizaci\u00f3n de eventos y su protocolo espec\u00edfico en 20 pa\u00edses diferentes de los cinco continentes. \u00b7 Aprender\u00e1s los diferentes tipos de protocolo, como el oficial, social, militar y empresarial.\\nFormaci\u00f3n integral, que te capacitar\u00e1 para organizar eventos de diferentes naturalezas, desde galas y alianzas internacionales, un congreso, la fashion week o un festival de rock.\\nEl M\u00f3dulo 3 del plan de estudios est\u00e1 impartido por profesionales del Instituto Europeo de Estudios Internacionales (IEEI). Al finalizar el m\u00f3dulo, recibir\u00e1s un certificado en Protocolo Diplom\u00e1tico e Internacional expedido por el IEEI.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster en Direcci\u00f3n de Protocolo y Organizaci\u00f3n de Eventos es el \u00fanico m\u00e1ster 100% online en este campo que diferencia la organizaci\u00f3n de eventos y su protocolo espec\u00edfico en 20 pa\u00edses diferentes de los cinco continentes. \u00b7 Aprender\u00e1s los diferentes tipos de protocolo, como el oficial, social, militar y empresarial.<br \/>\nFormaci\u00f3n integral, que te capacitar\u00e1 para organizar eventos de diferentes naturalezas, desde galas y alianzas internacionales, un congreso, la fashion week o un festival de rock.<br \/>\nEl M\u00f3dulo 3 del plan de estudios est\u00e1 impartido por profesionales del Instituto Europeo de Estudios Internacionales (IEEI). Al finalizar el m\u00f3dulo, recibir\u00e1s un certificado en Protocolo Diplom\u00e1tico e Internacional expedido por el IEEI.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Personas que trabajan o desean hacerlo en los departamentos de Marketing y Comunicaci\u00f3n, que desean conocer c\u00f3mo se organiza cualquier evento empresarial u oficial.\\n\\n-Personas de la administraci\u00f3n p\u00fablica que necesitan conocer las normas de protocolo oficial, militar o corporativo, as\u00ed como organizar eventos oficiales. Empresas que quieren conocer c\u00f3mo financiar un evento y obtener patrocinadores.\\n\\n- Personas que se mueven en entornos internacionales y que requieren conocer el protocolo extranjero.\\n\\n- Graduados de cualquier \u00e1rea interesados en descubrir el mundo de los eventos y del protocolo en su dimensi\u00f3n m\u00e1s universal. - Profesionales del sector que necesitan refuerzo en protocolo y organizaci\u00f3n. de eventos.\\n\\n- Estudiantes y profesionales que no pueden desplazarse para realizar un m\u00e1ster.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">&#8211; Personas que trabajan o desean hacerlo en los departamentos de Marketing y Comunicaci\u00f3n, que desean conocer c\u00f3mo se organiza cualquier evento empresarial u oficial.<\/p>\n<p>-Personas de la administraci\u00f3n p\u00fablica que necesitan conocer las normas de protocolo oficial, militar o corporativo, as\u00ed como organizar eventos oficiales. Empresas que quieren conocer c\u00f3mo financiar un evento y obtener patrocinadores.<\/p>\n<p>&#8211; Personas que se mueven en entornos internacionales y que requieren conocer el protocolo extranjero.<\/p>\n<p>&#8211; Graduados de cualquier \u00e1rea interesados en descubrir el mundo de los eventos y del protocolo en su dimensi\u00f3n m\u00e1s universal. &#8211; Profesionales del sector que necesitan refuerzo en protocolo y organizaci\u00f3n. de eventos.<\/p>\n<p>&#8211; Estudiantes y profesionales que no pueden desplazarse para realizar un m\u00e1ster.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 868px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA 6&quot;}\" data-sheets-formula=\"='UE - Online'!R[3]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas MBA<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n y Deporte&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Gesti\u00f3n y Deporte<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44543}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">13\/12\/2021<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:739}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">739\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:9600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">9.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">1.000\u20ac<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:10600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">10.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Elegido entre los 10 mejores MBA en Gesti\u00f3n Deportiva a Nivel Mundial por SportBusiness Postgraduate Rankings 2020, TOP 3 en Europa y N\u00famero 1 en Espa\u00f1a.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Elegido entre los 10 mejores MBA en Gesti\u00f3n Deportiva a Nivel Mundial por SportBusiness Postgraduate Rankings 2020, TOP 3 en Europa y N\u00famero 1 en Espa\u00f1a.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas (MBA) es un programa pionero en Espa\u00f1a, desde 2006, en el que aprender\u00e1s los modelos de negocio m\u00e1s exitosos en la Industria Deportiva a Nivel Mundial gracias a un claustro compuesto por profesionales de reconocido prestigio y experiencias \u00fanicas (viajes internacionales, Networking, pr\u00e1cticas...)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster Universitario en Direcci\u00f3n de Entidades Deportivas (MBA) es un programa pionero en Espa\u00f1a, desde 2006, en el que aprender\u00e1s los modelos de negocio m\u00e1s exitosos en la Industria Deportiva a Nivel Mundial gracias a un claustro compuesto por profesionales de reconocido prestigio y experiencias \u00fanicas (viajes internacionales, Networking, pr\u00e1cticas&#8230;)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Para acceder a este m\u00e1ster deber\u00e1s: estar en posesi\u00f3n de un t\u00edtulo universitario oficial espa\u00f1ol u otro expedido por una instituci\u00f3n de Educaci\u00f3n Superior perteneciente a otro estado integrante del Espacio Europeo de Educaci\u00f3n Superior que faculte en el mismo para el acceso a ense\u00f1anzas de M\u00e1ster.\\n\\nTener un t\u00edtulo en las \u00e1reas de Matem\u00e1ticas, Estad\u00edstica o Ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Para acceder a este m\u00e1ster deber\u00e1s: estar en posesi\u00f3n de un t\u00edtulo universitario oficial espa\u00f1ol u otro expedido por una instituci\u00f3n de Educaci\u00f3n Superior perteneciente a otro estado integrante del Espacio Europeo de Educaci\u00f3n Superior que faculte en el mismo para el acceso a ense\u00f1anzas de M\u00e1ster.<\/p>\n<p>Tener un t\u00edtulo en las \u00e1reas de Matem\u00e1ticas, Estad\u00edstica o Ingenier\u00eda TIC (u otras ingenier\u00edas si se tiene experiencia de al menos 3 a\u00f1os en el sector TIC).<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-de-Entidades-Deportivas-online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-de-Entidades-Deportivas-online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-de-Entidades-Deportivas-online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-de-Entidades-Deportivas-online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1373px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA 12&quot;}\" data-sheets-formula=\"='UE - Online'!R[4]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Gesti\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:577}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">577\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:7500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">7.500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:8000}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">8.000\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Conoce las diferentes \u00e1reas de una compa\u00f1\u00eda y entiende su gesti\u00f3n con una visi\u00f3n global.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Conoce las diferentes \u00e1reas de una compa\u00f1\u00eda y entiende su gesti\u00f3n con una visi\u00f3n global.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA te permitir\u00e1 compatibilizar la actividad laboral con tu formaci\u00f3n de calidad en una de las profesiones de mayor proyecci\u00f3n.\\n\\nApenderas a procesar clusters para procesamiento de grandes vol\u00famenes de datos: Uno principal con m\u00e1s de 25 nodos homog\u00e9neos de proceso y 2TB de memoria ram, y otro secundario formado por 4 m\u00e1quinas servidoras con alta capacidades de procesamiento y memoria (multicore, +64GB por nodo). Ambos cuentan con Apache Hadoop, HDFS, Apache Spark, y lenguajes\/herramientas de acceso a bases de datos noSQL Hive o Impala.\\nAprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a simulaciones y role plays, te preparar\u00e1s para ser un profesional global en Big Data.\\nPodr\u00e1s conocer de primera mano y hacer networking con profesionales de reconocidas empresas que te presentar\u00e1n casos reales. Adem\u00e1s, tendr\u00e1s masterclasses impartidas por profesionales que est\u00e1n en contacto con esta tecnolog\u00eda en su d\u00eda a d\u00eda.\\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster Universitario en Direcci\u00f3n de Empresas MBA te permitir\u00e1 compatibilizar la actividad laboral con tu formaci\u00f3n de calidad en una de las profesiones de mayor proyecci\u00f3n.<\/p>\n<p>Apenderas a procesar clusters para procesamiento de grandes vol\u00famenes de datos: Uno principal con m\u00e1s de 25 nodos homog\u00e9neos de proceso y 2TB de memoria ram, y otro secundario formado por 4 m\u00e1quinas servidoras con alta capacidades de procesamiento y memoria (multicore, +64GB por nodo). Ambos cuentan con Apache Hadoop, HDFS, Apache Spark, y lenguajes\/herramientas de acceso a bases de datos noSQL Hive o Impala.<br \/>\nAprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel. Gracias a simulaciones y role plays, te preparar\u00e1s para ser un profesional global en Big Data.<br \/>\nPodr\u00e1s conocer de primera mano y hacer networking con profesionales de reconocidas empresas que te presentar\u00e1n casos reales. Adem\u00e1s, tendr\u00e1s masterclasses impartidas por profesionales que est\u00e1n en contacto con esta tecnolog\u00eda en su d\u00eda a d\u00eda.<br \/>\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a profesionales que deseen completar su formaci\u00f3n con un conocimiento completo y pr\u00e1ctico de las distintas \u00e1reas que componen el funcionamiento de una empresa.\\n\\nEste programa est\u00e1 especialmente dirigido a titulados universitarios de diversos \u00e1mbitos que tienen inter\u00e9s en conocer la gesti\u00f3n empresarial desde un punto de vista te\u00f3rico-pr\u00e1ctico o quieren desarrollar su esp\u00edritu emprendedor en el mundo de los negocios.\\n\\nTambi\u00e9n a aquellos profesionales que tengan inter\u00e9s por asumir retos de innovaci\u00f3n y por la formaci\u00f3n continua a lo largo de su vida profesional.\\n\\nNuestros alumnos provienen de titulaciones universitarias en Ingenier\u00edas, Derecho, Ciencias de la Salud, Administraci\u00f3n de Empresas, Econom\u00eda, as\u00ed como de otras titulaciones; y que quieren completar su formaci\u00f3n y\/o experiencia profesional para adquirir una visi\u00f3n global, integrada y estrat\u00e9gica de la empresa.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Es una titulaci\u00f3n oficial reconocida a nivel Europeo e Internacional que est\u00e1 dirigida a profesionales que deseen completar su formaci\u00f3n con un conocimiento completo y pr\u00e1ctico de las distintas \u00e1reas que componen el funcionamiento de una empresa.<\/p>\n<p>Este programa est\u00e1 especialmente dirigido a titulados universitarios de diversos \u00e1mbitos que tienen inter\u00e9s en conocer la gesti\u00f3n empresarial desde un punto de vista te\u00f3rico-pr\u00e1ctico o quieren desarrollar su esp\u00edritu emprendedor en el mundo de los negocios.<\/p>\n<p>Tambi\u00e9n a aquellos profesionales que tengan inter\u00e9s por asumir retos de innovaci\u00f3n y por la formaci\u00f3n continua a lo largo de su vida profesional.<\/p>\n<p>Nuestros alumnos provienen de titulaciones universitarias en Ingenier\u00edas, Derecho, Ciencias de la Salud, Administraci\u00f3n de Empresas, Econom\u00eda, as\u00ed como de otras titulaciones; y que quieren completar su formaci\u00f3n y\/o experiencia profesional para adquirir una visi\u00f3n global, integrada y estrat\u00e9gica de la empresa.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Administracion-y-Direccion-de-Empresas-online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Administracion-y-Direccion-de-Empresas-online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Administracion-y-Direccion-de-Empresas-online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Administracion-y-Direccion-de-Empresas-online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1052px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster en Business Analytics 33&quot;}\" data-sheets-formula=\"='UE - Online'!R[5]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster en Business Analytics<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">8 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">8 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:638}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">638\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Un M\u00e1ster \u00fanico, profesional y pr\u00e1ctico enfocado a la toma de decisiones en la empresa basada en anal\u00edtica de datos.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Un M\u00e1ster \u00fanico, profesional y pr\u00e1ctico enfocado a la toma de decisiones en la empresa basada en anal\u00edtica de datos.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el M\u00e1ster Universitario en Business Analytics aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas anal\u00edticas como SQL, Power BI, SAS, BigML, Apache Hadoop, Spark, Python, R Cognos y Tableau. Tambi\u00e9n utilizar\u00e1s t\u00e9cnicas anal\u00edticas a trav\u00e9s de Machine Learning, Inteligencia Artificial, Deep Learning, Cognitive Computing y Geolocalizaci\u00f3n.\\nLa titulaci\u00f3n cuenta con formaci\u00f3n desde cero. Contar\u00e1s con una formaci\u00f3n completa y global, eminentemente pr\u00e1ctica aplicada a la toma de decisiones basadas en grandes cantidades de datos.\\nDominar\u00e1s herramientas de obtenci\u00f3n de datos y de visualizaci\u00f3n de los mismos que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.\\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">En el M\u00e1ster Universitario en Business Analytics aprender\u00e1s a trav\u00e9s de casos reales de multinacionales de primer nivel, usando herramientas anal\u00edticas como SQL, Power BI, SAS, BigML, Apache Hadoop, Spark, Python, R Cognos y Tableau. Tambi\u00e9n utilizar\u00e1s t\u00e9cnicas anal\u00edticas a trav\u00e9s de Machine Learning, Inteligencia Artificial, Deep Learning, Cognitive Computing y Geolocalizaci\u00f3n.<br \/>\nLa titulaci\u00f3n cuenta con formaci\u00f3n desde cero. Contar\u00e1s con una formaci\u00f3n completa y global, eminentemente pr\u00e1ctica aplicada a la toma de decisiones basadas en grandes cantidades de datos.<br \/>\nDominar\u00e1s herramientas de obtenci\u00f3n de datos y de visualizaci\u00f3n de los mismos que usan las empresas en su actividad, y estar\u00e1s preparado para responder a las necesidades de su negocio.<br \/>\nTendr\u00e1s la oportunidad de tener acceso a una bolsa de empleo y de pr\u00e1cticas profesionales adecuada a tu perfil.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;A todo aquel profesional interesado en desarrollar unas competencias \u00fanicas y de gran demanda para el entorno empresarial actual y futuro. Los estudiantes del M\u00e1ster son:\\n\\nProfesionales graduados que desean profundizar y dar un salto cualitativo en su profesi\u00f3n, adentr\u00e1ndose en el mundo de Business Analytics. En algunos casos son profesionales que buscan obtener un M\u00e1ster y certificaciones para cambiar de empresa o sector, as\u00ed como para tambi\u00e9n obtener nuevas posiciones dentro de su empresa.\\nOtro perfil de nuestros estudiantes son reci\u00e9n graduados que quieren profundizar m\u00e1s en el \u00e1mbito de Business Analytics y mejorar su posicionamiento en el mercado laboral a trav\u00e9s del m\u00e1ster y las certificaciones profesionales que ofrecemos.\\nDirectivos de nivel medio que requieren de una formaci\u00f3n espec\u00edfica para dirigir a sus equipos en el entorno Big Data&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">A todo aquel profesional interesado en desarrollar unas competencias \u00fanicas y de gran demanda para el entorno empresarial actual y futuro. Los estudiantes del M\u00e1ster son:<\/p>\n<p>Profesionales graduados que desean profundizar y dar un salto cualitativo en su profesi\u00f3n, adentr\u00e1ndose en el mundo de Business Analytics. En algunos casos son profesionales que buscan obtener un M\u00e1ster y certificaciones para cambiar de empresa o sector, as\u00ed como para tambi\u00e9n obtener nuevas posiciones dentro de su empresa.<br \/>\nOtro perfil de nuestros estudiantes son reci\u00e9n graduados que quieren profundizar m\u00e1s en el \u00e1mbito de Business Analytics y mejorar su posicionamiento en el mercado laboral a trav\u00e9s del m\u00e1ster y las certificaciones profesionales que ofrecemos.<br \/>\nDirectivos de nivel medio que requieren de una formaci\u00f3n espec\u00edfica para dirigir a sus equipos en el entorno Big Data<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 880px;\" width=\"918\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Industria 4.0 28&quot;}\" data-sheets-formula=\"='UE - Online'!R[6]C[0]\"><strong><span style=\"color: #ff0000;\">Master Universitario en Industria 4.0\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">8 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">8 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:638}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">638\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Industria 4.0 est\u00e1 dise\u00f1ado para que vayas adquiriendo los conocimientos de forma progresiva c\u00f3mo si de una cadena de valor de un proceso de la Industria 4.0 se tratase, en un entorno multidisciplinar. Adem\u00e1s, te formar\u00e1s en las nueve tecnolog\u00edas avanzadas que habilitan la transformaci\u00f3n digital de procesos productivos: Simulaci\u00f3n; Integraci\u00f3n de sistemas horizontal y vertical; Industrial Internet de las cosas; Ciberseguridad; Cloud; Fabricaci\u00f3n aditiva; Realidad aumentada; Big Data &amp; Analitics; Robots aut\u00f3nomos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster Universitario en Industria 4.0 est\u00e1 dise\u00f1ado para que vayas adquiriendo los conocimientos de forma progresiva c\u00f3mo si de una cadena de valor de un proceso de la Industria 4.0 se tratase, en un entorno multidisciplinar. Adem\u00e1s, te formar\u00e1s en las nueve tecnolog\u00edas avanzadas que habilitan la transformaci\u00f3n digital de procesos productivos: Simulaci\u00f3n; Integraci\u00f3n de sistemas horizontal y vertical; Industrial Internet de las cosas; Ciberseguridad; Cloud; Fabricaci\u00f3n aditiva; Realidad aumentada; Big Data &amp; Analitics; Robots aut\u00f3nomos.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reci\u00e9n egresados y profesionales en activo interesados en conocer la transformaci\u00f3n digital en la industria actual, que busquen capacitarse en la denici\u00f3n, dise\u00f1o, desarrollo, an\u00e1lisis y gesti\u00f3n de la digitalizaci\u00f3n industrial a trav\u00e9s de sus tecnolog\u00edas y competencias digitales, adquiriendo la experiencia pr\u00e1ctica necesaria a trav\u00e9s de casos reales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Reci\u00e9n egresados y profesionales en activo interesados en conocer la transformaci\u00f3n digital en la industria actual, que busquen capacitarse en la denici\u00f3n, dise\u00f1o, desarrollo, an\u00e1lisis y gesti\u00f3n de la digitalizaci\u00f3n industrial a trav\u00e9s de sus tecnolog\u00edas y competencias digitales, adquiriendo la experiencia pr\u00e1ctica necesaria a trav\u00e9s de casos reales.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 975px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion y Gesti\u00f3n de Tecnologias de la Informacion. MBA TIC. 24&quot;}\" data-sheets-formula=\"='UE - Online'!R[7]C[0]\"><strong><span style=\"color: #ff0000;\">Master Universitario en Direccion y Gesti\u00f3n de Tecnologias de la Informacion. MBA TIC.\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44881}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">16\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:610}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">610\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el Master Universitario en Direccion y Gestion de Tecnologias de la Informacion. MBA TIC obtendr\u00e1s una titulaci\u00f3n oficial impartida con las garant\u00edas de una universidad de prestigio internacional como la Universidad Europea.\\nLa plataforma en la que se desarrolla el M\u00e1ster aporta las \u00faltimas innovaciones en docencia online, disponiendo de multitud de recursos para facilitar la experiencia educativa y proporcionando un seguimiento constante del estudiante.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">En el Master Universitario en Direccion y Gestion de Tecnologias de la Informacion. MBA TIC obtendr\u00e1s una titulaci\u00f3n oficial impartida con las garant\u00edas de una universidad de prestigio internacional como la Universidad Europea.<br \/>\nLa plataforma en la que se desarrolla el M\u00e1ster aporta las \u00faltimas innovaciones en docencia online, disponiendo de multitud de recursos para facilitar la experiencia educativa y proporcionando un seguimiento constante del estudiante.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 Ingenieros y estudiantes procedentes de carreras de ciencias (matem\u00e1ticas) y f\u00edsicos con experiencia en\\nlas TIC.\\n\\n\u2022 Ingenieros reci\u00e9n titulados en titulaciones anes a las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicacio-\\nnes (TIC).\\n\\n\u2022 Profesionales que ya hayan estudiado anteriormente un M\u00e1ster en Direcci\u00f3n o Gesti\u00f3n de las Tecnolo-\\ng\u00edas de la Informaci\u00f3n y Comunicaciones y quieran terminar de completar sus conocimientos en el con-\\ntexto del outsourcing.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">\u2022 Ingenieros y estudiantes procedentes de carreras de ciencias (matem\u00e1ticas) y f\u00edsicos con experiencia en<br \/>\nlas TIC.\u2022 Ingenieros reci\u00e9n titulados en titulaciones anes a las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicacio-<br \/>\nnes (TIC).\u2022 Profesionales que ya hayan estudiado anteriormente un M\u00e1ster en Direcci\u00f3n o Gesti\u00f3n de las Tecnolo-<br \/>\ng\u00edas de la Informaci\u00f3n y Comunicaciones y quieran terminar de completar sus conocimientos en el con-<br \/>\ntexto del outsourcing.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 869px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Inteligencia Artificial 29&quot;}\" data-sheets-formula=\"='UE - Online'!R[8]C[0]\"><strong><span style=\"color: #ff0000;\">Master en Inteligencia Artificial\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Gesti\u00f3n y Comercio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Gesti\u00f3n y Comercio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44881}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">16\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">6 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">6 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:633}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">633\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:3800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">3.800\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:4300}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">4.300\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster en Inteligencia Artificial y Data Science Online adquirir\u00e1s los conocimientos t\u00e9cnicos y pr\u00e1cticos necesarios para liderar proyectos basados en el aprendizaje autom\u00e1tico y los modelos de inteligencia de las m\u00e1quinas.\\n\\n\u2022 Adquirir\u00e1s una visi\u00f3n integradora de la Inteligencia Articial y dominio de t\u00e9cnicas avanzadas de Machine Learning y Optimizaci\u00f3n Computacional.\\n\\n\u2022 Dise\u00f1o, desarrollo e implementaci\u00f3n de sistemas inteligentes, mediante el uso de t\u00e9cnicas de inteligencia artificial, big data y computaci\u00f3n en la nube.\\n\\n\u2022 Te familiarizar\u00e1s con las herramientas y librer\u00edas de software utilizadas en la industria: Python, TensorFlow, Keras, SciPy (pandas, numpy, matplotlib, seaborn), Anaconda, Jupyter notebook.\\n\\n\u2022 Aprender\u00e1s qu\u00e9 es la inteligencia articial para formarte a trav\u00e9s de casos reales de multinacionales\\nde primer nivel, usando herramientas como Watson Studio, Open Scale y Cognos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">Con el M\u00e1ster en Inteligencia Artificial y Data Science Online adquirir\u00e1s los conocimientos t\u00e9cnicos y pr\u00e1cticos necesarios para liderar proyectos basados en el aprendizaje autom\u00e1tico y los modelos de inteligencia de las m\u00e1quinas.<\/p>\n<p>\u2022 Adquirir\u00e1s una visi\u00f3n integradora de la Inteligencia Articial y dominio de t\u00e9cnicas avanzadas de Machine Learning y Optimizaci\u00f3n Computacional.<\/p>\n<p>\u2022 Dise\u00f1o, desarrollo e implementaci\u00f3n de sistemas inteligentes, mediante el uso de t\u00e9cnicas de inteligencia artificial, big data y computaci\u00f3n en la nube.<\/p>\n<p>\u2022 Te familiarizar\u00e1s con las herramientas y librer\u00edas de software utilizadas en la industria: Python, TensorFlow, Keras, SciPy (pandas, numpy, matplotlib, seaborn), Anaconda, Jupyter notebook.<\/p>\n<p>\u2022 Aprender\u00e1s qu\u00e9 es la inteligencia articial para formarte a trav\u00e9s de casos reales de multinacionales<br \/>\nde primer nivel, usando herramientas como Watson Studio, Open Scale y Cognos.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El perfil recomendado para el m\u00e1ster es:\\n\u2022 Perles t\u00e9cnicos que quieran adaptar sus conocimientos a la actualidad de la inteligencia articial y conocer su uso para crear valor dentro de la empresa.\\n\u2022 Perles de negocio con experiencia profesional en tecnolog\u00eda que quieran experimentar de primera mano el proceso de desarrollo de un proyecto de Inteligencia Articial.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">El perfil recomendado para el m\u00e1ster es:<br \/>\n\u2022 Perles t\u00e9cnicos que quieran adaptar sus conocimientos a la actualidad de la inteligencia articial y conocer su uso para crear valor dentro de la empresa.<br \/>\n\u2022 Perles de negocio con experiencia profesional en tecnolog\u00eda que quieran experimentar de primera mano el proceso de desarrollo de un proyecto de Inteligencia Articial.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1104px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones 34&quot;}\" data-sheets-formula=\"='UE - Online'!R[9]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inform\u00e1tica&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Inform\u00e1tica<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44855}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">21\/10\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">9 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:644}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">644\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.800\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">1.000\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.800\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Estudia el m\u00e1ster online en Ciberseguridad que te especializar\u00e1 en seguridad inform\u00e1tica desde las vertientes t\u00e9cnica, t\u00e1ctica y estrat\u00e9gica.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Estudia el m\u00e1ster online en Ciberseguridad que te especializar\u00e1 en seguridad inform\u00e1tica desde las vertientes t\u00e9cnica, t\u00e1ctica y estrat\u00e9gica.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones obtendras Certificaciones CISSP y CISM\\nEste m\u00e1ster te prepara para la obtenci\u00f3n de dos de las certificaciones m\u00e1s importantes y reconocidas internacionalmente en el \u00e1mbito de la Seguridad Inform\u00e1tica, que muestran la madurez de los profesionales en seguridad digital. Dise\u00f1adas para alcanzar puestos de direcci\u00f3n.\\nEl M\u00e1ster Oficial en Seguridad de las TIC de la Universidad Europea est\u00e1 considerado entre los 5 mejores m\u00e1steres en inform\u00e1tica, seg\u00fan el ranking de El Mundo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">Con el M\u00e1ster Universitario en Seguridad de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones obtendras Certificaciones CISSP y CISM<br \/>\nEste m\u00e1ster te prepara para la obtenci\u00f3n de dos de las certificaciones m\u00e1s importantes y reconocidas internacionalmente en el \u00e1mbito de la Seguridad Inform\u00e1tica, que muestran la madurez de los profesionales en seguridad digital. Dise\u00f1adas para alcanzar puestos de direcci\u00f3n.<br \/>\nEl M\u00e1ster Oficial en Seguridad de las TIC de la Universidad Europea est\u00e1 considerado entre los 5 mejores m\u00e1steres en inform\u00e1tica, seg\u00fan el ranking de El Mundo.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Este M\u00e1ster est\u00e1 especialmente dise\u00f1ado para graduados, ingenieros inform\u00e1ticos, ingenieros de telecomunicaciones e ingenieros t\u00e9cnicos del \u00e1rea TIC, as\u00ed como profesionales del \u00e1rea de TI en cualquiera de sus sectores que posean una titulaci\u00f3n oficial universitaria y experiencia demostrada en el \u00e1rea TIC cubriendo todos los aspectos t\u00e9cnicos necesarios para cursar el m\u00e1ster con \u00e9xito.\\n\\nRequisitos de acceso: Disponer de un t\u00edtulo oficial universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo oficial universitario en un \u00e1rea t\u00e9cnica y contar con experiencia en Tecnolog\u00edas de la Informaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Este M\u00e1ster est\u00e1 especialmente dise\u00f1ado para graduados, ingenieros inform\u00e1ticos, ingenieros de telecomunicaciones e ingenieros t\u00e9cnicos del \u00e1rea TIC, as\u00ed como profesionales del \u00e1rea de TI en cualquiera de sus sectores que posean una titulaci\u00f3n oficial universitaria y experiencia demostrada en el \u00e1rea TIC cubriendo todos los aspectos t\u00e9cnicos necesarios para cursar el m\u00e1ster con \u00e9xito.<\/p>\n<p>Requisitos de acceso: Disponer de un t\u00edtulo oficial universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo oficial universitario en un \u00e1rea t\u00e9cnica y contar con experiencia en Tecnolog\u00edas de la Informaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;T\u00edtulo universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo universitario en un \u00e1rea t\u00e9cnica y experiencia probada en Tecnolog\u00edas de la Informaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">T\u00edtulo universitario en las \u00e1reas de Ingenier\u00eda Inform\u00e1tica o de las Telecomunicaciones, o tener un t\u00edtulo universitario en un \u00e1rea t\u00e9cnica y experiencia probada en Tecnolog\u00edas de la Informaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Seguridad-de-las-Tecnologias-de-la-Informacion-y-las-Comunicaciones-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Seguridad-de-las-Tecnologias-de-la-Informacion-y-las-Comunicaciones-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Seguridad-de-las-Tecnologias-de-la-Informacion-y-las-Comunicaciones-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Seguridad-de-las-Tecnologias-de-la-Informacion-y-las-Comunicaciones-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 757px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Gestion de Negocios Internacionales 27&quot;}\" data-sheets-formula=\"='UE - Online'!R[10]C[0]\"><strong><span style=\"color: #ff0000;\">M\u00e1ster Universitario en Gestion de Negocios Internacionales\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Ciencia de Datos<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">12 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:508}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">508\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el M\u00e1ster Universitario Online en Gesti\u00f3n de Negocios Internacionales resolver\u00e1s retos empresariales iguales a los que te encontrar\u00e1s en el mercado con la ayuda de tus profesores, profesionales en activo y expertos. El M\u00e1ster est\u00e1 avalado por la C\u00e1mara de Comercio de Valencia, la cual cuenta con la red m\u00e1s extensa de instituciones vinculadas al comercio internacional con un total de 8.000 c\u00e1maras en todo el mundo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">En el M\u00e1ster Universitario Online en Gesti\u00f3n de Negocios Internacionales resolver\u00e1s retos empresariales iguales a los que te encontrar\u00e1s en el mercado con la ayuda de tus profesores, profesionales en activo y expertos. El M\u00e1ster est\u00e1 avalado por la C\u00e1mara de Comercio de Valencia, la cual cuenta con la red m\u00e1s extensa de instituciones vinculadas al comercio internacional con un total de 8.000 c\u00e1maras en todo el mundo.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Profesionales que deseen dar un salto en su carrera profesional con un posicionamiento internacional, afrontando nuevos retos y aportando m\u00e1s valor a\u00f1adido a su empresa.\\n\\n- Todas aquellas personas interesadas en el mundo de la empresa, las operaciones comerciales internacionales y el global business.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">&#8211; Profesionales que deseen dar un salto en su carrera profesional con un posicionamiento internacional, afrontando nuevos retos y aportando m\u00e1s valor a\u00f1adido a su empresa.<\/p>\n<p>&#8211; Todas aquellas personas interesadas en el mundo de la empresa, las operaciones comerciales internacionales y el global business.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1222px;\" width=\"923\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master en Fintech y Blockchain 26&quot;}\" data-sheets-formula=\"='UE - Online'!R[11]C[0]\"><strong><span style=\"color: #ff0000;\">Master en Fintech y Blockchain\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Ciencia de Datos<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;entre el 9 y 20 de noviembre cada a\u00f1o&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">entre el 9 y 20 de noviembre cada a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">6 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">6 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:633}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">633\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:3800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">3.800\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:4300}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">4.300\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El primer M\u00e1ster Online en Fintech y Blockchain te permitir\u00e1 adquirir una visi\u00f3n global de los nuevos modelos digitales en el sector de los servicios nancieros y banca y convertirte en un profesional de la tecnolog\u00eda nanciera y los nuevos modelos de negocio del sector.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El primer M\u00e1ster Online en Fintech y Blockchain te permitir\u00e1 adquirir una visi\u00f3n global de los nuevos modelos digitales en el sector de los servicios nancieros y banca y convertirte en un profesional de la tecnolog\u00eda nanciera y los nuevos modelos de negocio del sector.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el Master en Fintech y Blockchain adquirir\u00e1s el perfil profesional en innovaci\u00f3n financiera y banca digital que demandan las empresas del sector. Podr\u00e1s liderar proyectos relacionados con big data y business intelligence aplicados al sector Fintech. Aprender\u00e1s los fundamentos del blockchain y de las distintas opciones que ofrece esta tecnolog\u00eda.\\nAdquirir\u00e1s una visi\u00f3n integral de las nanzas tecnol\u00f3gicas y el sector Fintech, mediante una formaci\u00f3n 100% online. Profundizar\u00e1s en los conceptos propios del sector en el \u00e1mbito de la tecnolog\u00eda Blockchain, PSD2 y los Smart Contracts.\\nObtendr\u00e1s una visi\u00f3n global e internacional del impacto que tienen los procesos tecnol\u00f3gicos en el sector nanciero. Y aprender\u00e1s c\u00f3mo es el nuevo Ecosistema Financiero a trav\u00e9s de casos reales de multinacionales de primer nivel, como Bankia, BBVA, Banco Sabadell, Softonic.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">En el Master en Fintech y Blockchain adquirir\u00e1s el perfil profesional en innovaci\u00f3n financiera y banca digital que demandan las empresas del sector. Podr\u00e1s liderar proyectos relacionados con big data y business intelligence aplicados al sector Fintech. Aprender\u00e1s los fundamentos del blockchain y de las distintas opciones que ofrece esta tecnolog\u00eda.<br \/>\nAdquirir\u00e1s una visi\u00f3n integral de las nanzas tecnol\u00f3gicas y el sector Fintech, mediante una formaci\u00f3n 100% online. Profundizar\u00e1s en los conceptos propios del sector en el \u00e1mbito de la tecnolog\u00eda Blockchain, PSD2 y los Smart Contracts.<br \/>\nObtendr\u00e1s una visi\u00f3n global e internacional del impacto que tienen los procesos tecnol\u00f3gicos en el sector nanciero. Y aprender\u00e1s c\u00f3mo es el nuevo Ecosistema Financiero a trav\u00e9s de casos reales de multinacionales de primer nivel, como Bankia, BBVA, Banco Sabadell, Softonic.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El perfil de ingreso recomendado es el de profesionales que aspiren a acelerar el desarrollo de su carrera profesional y entender el importante rol que est\u00e1 adquiriendo la tecnolog\u00eda en el sector financiero:\\n\\n\u2022 Responsables y jefes de proyecto que quieran ampliar su capacidad de gesti\u00f3n para acometer proyectos relacionados con Fintech.\\n\\n\u2022 Consultores y especialistas del sector financiero que quieran prepararse, actualizarse y completar su perfil profesional, forjando su posici\u00f3n competitiva en el mercado.\\n\\n\u2022 Personas con experiencia o vocaci\u00f3n en el \u00e1rea de Fintech, que deseen avanzar su preparaci\u00f3n acad\u00e9mica.\\n\\n\u2022 Graduados o licenciados en ingenier\u00edas t\u00e9cnicas, ADE, Finanzas o ciencias (matem\u00e1ticas, f\u00edsica o qu\u00edmica) que quieran encaminar su carrera profesional hacia las finanzas.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">El perfil de ingreso recomendado es el de profesionales que aspiren a acelerar el desarrollo de su carrera profesional y entender el importante rol que est\u00e1 adquiriendo la tecnolog\u00eda en el sector financiero:<\/p>\n<p>\u2022 Responsables y jefes de proyecto que quieran ampliar su capacidad de gesti\u00f3n para acometer proyectos relacionados con Fintech.<\/p>\n<p>\u2022 Consultores y especialistas del sector financiero que quieran prepararse, actualizarse y completar su perfil profesional, forjando su posici\u00f3n competitiva en el mercado.<\/p>\n<p>\u2022 Personas con experiencia o vocaci\u00f3n en el \u00e1rea de Fintech, que deseen avanzar su preparaci\u00f3n acad\u00e9mica.<\/p>\n<p>\u2022 Graduados o licenciados en ingenier\u00edas t\u00e9cnicas, ADE, Finanzas o ciencias (matem\u00e1ticas, f\u00edsica o qu\u00edmica) que quieran encaminar su carrera profesional hacia las finanzas.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1160px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion Comercial y Ventas 22&quot;}\" data-sheets-formula=\"='UE - Online'!R[12]C[0]\"><span style=\"color: #ff0000;\"><strong>Master Universitario en Direccion Comercial y Ventas\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencia de Datos&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Ciencia de Datos<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:610}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">610\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Al nalizar el M\u00e1ster Universitario en Direcci\u00f3n Comercial y Ventas, estar\u00e1s capacitado para dise\u00f1ar un modelo de direcci\u00f3n comercial, adaptado al plan estrat\u00e9gico y de transformaci\u00f3n digital de la compa\u00f1\u00eda, a partir del an\u00e1lisis de oportunidades en mercados tradicionales y emergentes, y la estrecha colaboraci\u00f3n con diferentes \u00e1reas claves dentro de la organizaci\u00f3n: desde marketing, an\u00e1lisis de datos, producto, log\u00edstica, entre otras, junto con la direcci\u00f3n y liderazgo de un equipo de personas, que te permitan implementar un plan comercial que asegure el alcance de los objetivos de la empresa.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Al nalizar el M\u00e1ster Universitario en Direcci\u00f3n Comercial y Ventas, estar\u00e1s capacitado para dise\u00f1ar un modelo de direcci\u00f3n comercial, adaptado al plan estrat\u00e9gico y de transformaci\u00f3n digital de la compa\u00f1\u00eda, a partir del an\u00e1lisis de oportunidades en mercados tradicionales y emergentes, y la estrecha colaboraci\u00f3n con diferentes \u00e1reas claves dentro de la organizaci\u00f3n: desde marketing, an\u00e1lisis de datos, producto, log\u00edstica, entre otras, junto con la direcci\u00f3n y liderazgo de un equipo de personas, que te permitan implementar un plan comercial que asegure el alcance de los objetivos de la empresa.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El Master Universitario en Direccion Comercial y Ventas Online es reconocido por el Ministerio de Educaci\u00f3n del Gobierno de Espa\u00f1a y avalado por su agencia de acreditaci\u00f3n, ANECA. Este M\u00e1ster est\u00e1 reconocido tanto en la Uni\u00f3n Europea como en Latino Am\u00e9rica.\\nEl \u00e1rea comercial es vital en el proceso de transformaci\u00f3n digital de las empresas, las nuevas tecnolog\u00edas han cambiado el comportamiento del consumidor, creando nuevos modelos de negocios y canales de ventas, lo cu\u00e1l hace imprescindible un equipo comercial especializado. Durante el 2020, los perfiles comerciales se posicionaron entre los 10 m\u00e1s demandados, seg\u00fan LinkedIn y Hays Recruiting.\\nEl m\u00e1ster te brindar\u00e1 una visi\u00f3n global donde los canales offine y online se combinan, centr\u00e1ndose en el usuario para brindarle una mejor experiencia de compra, atrayendo y delizando a clientes nuevos y recurrentes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El Master Universitario en Direccion Comercial y Ventas Online es reconocido por el Ministerio de Educaci\u00f3n del Gobierno de Espa\u00f1a y avalado por su agencia de acreditaci\u00f3n, ANECA. Este M\u00e1ster est\u00e1 reconocido tanto en la Uni\u00f3n Europea como en Latino Am\u00e9rica.<br \/>\nEl \u00e1rea comercial es vital en el proceso de transformaci\u00f3n digital de las empresas, las nuevas tecnolog\u00edas han cambiado el comportamiento del consumidor, creando nuevos modelos de negocios y canales de ventas, lo cu\u00e1l hace imprescindible un equipo comercial especializado. Durante el 2020, los perfiles comerciales se posicionaron entre los 10 m\u00e1s demandados, seg\u00fan LinkedIn y Hays Recruiting.<br \/>\nEl m\u00e1ster te brindar\u00e1 una visi\u00f3n global donde los canales offine y online se combinan, centr\u00e1ndose en el usuario para brindarle una mejor experiencia de compra, atrayendo y delizando a clientes nuevos y recurrentes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nuestro M\u00e1ster est\u00e1 dirigido a:\\n\u2022 Graduados en Administraci\u00f3n de empresa, marketing y negocios internacionales.\\n\u2022 Profesionales del \u00e1mbito comercial y ventas con al menos un a\u00f1o de experiencia en el departamento comercial o de ventas.\\n\u2022 Graduados en otras \u00e1reas con inquietudes profesionales de los negocios y las ventas.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Nuestro M\u00e1ster est\u00e1 dirigido a:<br \/>\n\u2022 Graduados en Administraci\u00f3n de empresa, marketing y negocios internacionales.<br \/>\n\u2022 Profesionales del \u00e1mbito comercial y ventas con al menos un a\u00f1o de experiencia en el departamento comercial o de ventas.<br \/>\n\u2022 Graduados en otras \u00e1reas con inquietudes profesionales de los negocios y las ventas.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1079px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Master Universitario en Direccion y Gestion Financiera 25&quot;}\" data-sheets-formula=\"='UE - Online'!R[13]C[0]\"><strong><span style=\"color: #ff0000;\">Master Universitario en Direccion y Gestion Financiera\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Gesti\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;10 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">10 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:470}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">470\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n Financiera tiene como objetivo formar profesionales altamente cualicados, con capacidad para la toma de decisiones nancieras, aplicando las tecnolog\u00edas nancieras (FinTech), las herramientas de visualizaci\u00f3n y extracci\u00f3n de datos (Cognos, Tableu, Big Data) y la relevancia de las normativas vigentes en los Mercados de Instrumentos Financieros (MiFDII), altamente valorados por empresas que demandan profesionales con formaci\u00f3n especializada en este sector.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n Financiera tiene como objetivo formar profesionales altamente cualicados, con capacidad para la toma de decisiones nancieras, aplicando las tecnolog\u00edas nancieras (FinTech), las herramientas de visualizaci\u00f3n y extracci\u00f3n de datos (Cognos, Tableu, Big Data) y la relevancia de las normativas vigentes en los Mercados de Instrumentos Financieros (MiFDII), altamente valorados por empresas que demandan profesionales con formaci\u00f3n especializada en este sector.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El Master Universitario en Direccion y Gestion Financiera es reconocido por el Ministerio de Educaci\u00f3n del Gobierno de Espa\u00f1a y avalado por su agencia de acreditaci\u00f3n, ANECA. Este M\u00e1ster est\u00e1 reconocido tanto en la Uni\u00f3n Europea como en Latino Am\u00e9rica.\\n\\nEn el actual marco econ\u00f3mico-empresarial donde se intensifica cada vez m\u00e1s, la competencia y la globalizaci\u00f3n, los profesionales y directivos financieros deben valorar riesgos, oportunidades y efectos, para establecer estrategias empresariales s\u00f3lidas, lo cu\u00e1l los convierte en perfiles altamente valorados.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El Master Universitario en Direccion y Gestion Financiera es reconocido por el Ministerio de Educaci\u00f3n del Gobierno de Espa\u00f1a y avalado por su agencia de acreditaci\u00f3n, ANECA. Este M\u00e1ster est\u00e1 reconocido tanto en la Uni\u00f3n Europea como en Latino Am\u00e9rica.<\/p>\n<p>En el actual marco econ\u00f3mico-empresarial donde se intensifica cada vez m\u00e1s, la competencia y la globalizaci\u00f3n, los profesionales y directivos financieros deben valorar riesgos, oportunidades y efectos, para establecer estrategias empresariales s\u00f3lidas, lo cu\u00e1l los convierte en perfiles altamente valorados.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2022 El M\u00e1ster est\u00e1 recomendado para profesionales con varios a\u00f1os de experiencia o Licenciados, Diplomados o Graduados en Administraci\u00f3n y Direcci\u00f3n de Empresas, en Econom\u00eda, en Ciencias Actuariales y Financieras, en Ciencias Empresariales, Contabilidad y Finanzas o sus equivalentes extranjeros.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">\u2022 El M\u00e1ster est\u00e1 recomendado para profesionales con varios a\u00f1os de experiencia o Licenciados, Diplomados o Graduados en Administraci\u00f3n y Direcci\u00f3n de Empresas, en Econom\u00eda, en Ciencias Actuariales y Financieras, en Ciencias Empresariales, Contabilidad y Finanzas o sus equivalentes extranjeros.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-y-Gestion-Financiera-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-y-Gestion-Financiera-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-y-Gestion-Financiera-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-y-Gestion-Financiera-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1136px;\" width=\"920\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos 10&quot;}\" data-sheets-formula=\"='UE - Online'!R[14]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Gesti\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Gesti\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">11 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;14 cuotas&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">14 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">400\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.600,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Desarrolla tus capacidades profesionales y de liderazgo, para lograr una influencia significativa en la direcci\u00f3n de personas y la gesti\u00f3n del cambio en las organizaciones.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Desarrolla tus capacidades profesionales y de liderazgo, para lograr una influencia significativa en la direcci\u00f3n de personas y la gesti\u00f3n del cambio en las organizaciones.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos proporciona las estrategias y las t\u00e9cnicas avanzadas para la funci\u00f3n de recursos humanos, y los elementos clave que marcar\u00e1n el futuro, basados en las organizaciones 2.0 y la tecnolog\u00eda digital.\\n\\nAdquirir\u00e1s habilidades y competencias para satisfacer la demanda de perfiles altamente cualificados en funciones relacionadas con el dise\u00f1o, desarrollo e implementaci\u00f3n de pol\u00edticas innovadoras de RR.HH.\\nAprende haciendo, una metodolog\u00eda basada en la resoluci\u00f3n de casos reales desde el primer d\u00eda con la gu\u00eda de un claustro compuesto por docentes expertos en el \u00e1rea y reputados profesionales en activo.\\nNuestro programa mejorar\u00e1 tu empleabilidad al participar en el aprendizaje de las \u00faltimas tendencias en gesti\u00f3n de los RR.HH. En colaboraci\u00f3n con Meta4, compa\u00f1\u00eda dedicada a ofrecer Soluciones Globales para la gesti\u00f3n de la N\u00f3mina y los RR.HH.; recibir\u00e1s formaci\u00f3n impartida por la propia empresa y obtendr\u00e1s la certificaci\u00f3n de \u201cUsuario en Gesti\u00f3n de RR.HH. en Meta4\u201d. Meta4 cuenta con una penetraci\u00f3n de mercado nacional del 55%, siendo referente entre las principales empresas y una penetraci\u00f3n del 25% en Latinoam\u00e9rica.\\nHorario en fin de semana compatible con tu actividad: Viernes de 17:30 a 21:30 y S\u00e1bados de 10:00 a 14:00 y de 15:00 a 19:00.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster en Direcci\u00f3n y Gesti\u00f3n de Recursos Humanos proporciona las estrategias y las t\u00e9cnicas avanzadas para la funci\u00f3n de recursos humanos, y los elementos clave que marcar\u00e1n el futuro, basados en las organizaciones 2.0 y la tecnolog\u00eda digital.<\/p>\n<p>Adquirir\u00e1s habilidades y competencias para satisfacer la demanda de perfiles altamente cualificados en funciones relacionadas con el dise\u00f1o, desarrollo e implementaci\u00f3n de pol\u00edticas innovadoras de RR.HH.<br \/>\nAprende haciendo, una metodolog\u00eda basada en la resoluci\u00f3n de casos reales desde el primer d\u00eda con la gu\u00eda de un claustro compuesto por docentes expertos en el \u00e1rea y reputados profesionales en activo.<br \/>\nNuestro programa mejorar\u00e1 tu empleabilidad al participar en el aprendizaje de las \u00faltimas tendencias en gesti\u00f3n de los RR.HH. En colaboraci\u00f3n con Meta4, compa\u00f1\u00eda dedicada a ofrecer Soluciones Globales para la gesti\u00f3n de la N\u00f3mina y los RR.HH.; recibir\u00e1s formaci\u00f3n impartida por la propia empresa y obtendr\u00e1s la certificaci\u00f3n de \u201cUsuario en Gesti\u00f3n de RR.HH. en Meta4\u201d. Meta4 cuenta con una penetraci\u00f3n de mercado nacional del 55%, siendo referente entre las principales empresas y una penetraci\u00f3n del 25% en Latinoam\u00e9rica.<br \/>\nHorario en fin de semana compatible con tu actividad: Viernes de 17:30 a 21:30 y S\u00e1bados de 10:00 a 14:00 y de 15:00 a 19:00.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Titulados universitarios que recientemente han finalizado su formaci\u00f3n que tienen inter\u00e9s por desarrollar su carrera profesional en el \u00e1mbito de la direcci\u00f3n y\/o gesti\u00f3n de recursos humanos. Titulados en Administraci\u00f3n y Direcci\u00f3n de Empresas, Derecho, Psicolog\u00eda, Ciencias Pol\u00edticas, Sociolog\u00eda o estudios afines del \u00e1mbito.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">Titulados universitarios que recientemente han finalizado su formaci\u00f3n que tienen inter\u00e9s por desarrollar su carrera profesional en el \u00e1mbito de la direcci\u00f3n y\/o gesti\u00f3n de recursos humanos. Titulados en Administraci\u00f3n y Direcci\u00f3n de Empresas, Derecho, Psicolog\u00eda, Ciencias Pol\u00edticas, Sociolog\u00eda o estudios afines del \u00e1mbito.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-Recursos-Humanos-online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-Recursos-Humanos-online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-Recursos-Humanos-online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Direccion-Recursos-Humanos-online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 886px;\" width=\"923\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;M\u00e1ster Universitario en Nutrici\u00f3n Clinica 36&quot;}\" data-sheets-formula=\"='UE - Online'!R[15]C[0]\"><span style=\"color: #ff0000;\"><strong>M\u00e1ster Universitario en Nutrici\u00f3n Clinica\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programas en Ciencias de la Salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Programas en Ciencias de la Salud<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">12 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:508}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">508\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">6.100,00 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.600\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Te formar\u00e1s con un profesorado multidisciplinar compuesto por dietistas-nutricionistas, m\u00e9dicos dedicados a la Nutrici\u00f3n Cl\u00ednica, con los que se tendr\u00e1s una formaci\u00f3n completa y de calidad.\\nRealizar\u00e1s las pr\u00e1cticas en hospitales, residencias de mayores y centros de salud como son el Hospital Moncloa, el Hospital de especializaci\u00f3n en C\u00e1ncer MD ANDERSON INTERNACIONAL ESPA\u00d1A, hospitales del SERMAS y residencias del grupo GERIAVI.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Te formar\u00e1s con un profesorado multidisciplinar compuesto por dietistas-nutricionistas, m\u00e9dicos dedicados a la Nutrici\u00f3n Cl\u00ednica, con los que se tendr\u00e1s una formaci\u00f3n completa y de calidad.<br \/>\nRealizar\u00e1s las pr\u00e1cticas en hospitales, residencias de mayores y centros de salud como son el Hospital Moncloa, el Hospital de especializaci\u00f3n en C\u00e1ncer MD ANDERSON INTERNACIONAL ESPA\u00d1A, hospitales del SERMAS y residencias del grupo GERIAVI.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster universitario en nutrici\u00f3n cl\u00ednica tiene como\\nfinalidad formar y especializar a profesionales de ciencias\\nde la salud en el dise\u00f1o de programas nutricionales,\\nvaloraci\u00f3n y seguimiento nutricional de patolog\u00edas;\\ncontando para todo ello, con un profesorado multidisciplinar,\\ncompuesto por Dietistas-Nutricionistas, m\u00e9dicos dedicados\\na la nutrici\u00f3n cl\u00ednica, con los que se dar\u00e1 una formaci\u00f3n\\ncompleta y de calidad.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\">El M\u00e1ster universitario en nutrici\u00f3n cl\u00ednica tiene como<br \/>\nfinalidad formar y especializar a profesionales de ciencias<br \/>\nde la salud en el dise\u00f1o de programas nutricionales,<br \/>\nvaloraci\u00f3n y seguimiento nutricional de patolog\u00edas;<br \/>\ncontando para todo ello, con un profesorado multidisciplinar,<br \/>\ncompuesto por Dietistas-Nutricionistas, m\u00e9dicos dedicados<br \/>\na la nutrici\u00f3n cl\u00ednica, con los que se dar\u00e1 una formaci\u00f3n<br \/>\ncompleta y de calidad.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster est\u00e1 enfocado a estudiantes con el siguiente\\nperfil de ingreso:\\n\u2666 Graduados\/ Diplomados en Nutrici\u00f3n Humana y Diet\u00e9tica.\\n\u2666 Graduados\/ Diplomados en Enfermer\u00eda.\\n\u2666 Graduados\/ Licenciados en Medicina.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\">El M\u00e1ster est\u00e1 enfocado a estudiantes con el siguiente<br \/>\nperfil de ingreso:<br \/>\n\u2666 Graduados\/ Diplomados en Nutrici\u00f3n Humana y Diet\u00e9tica.<br \/>\n\u2666 Graduados\/ Diplomados en Enfermer\u00eda.<br \/>\n\u2666 Graduados\/ Licenciados en Medicina.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Curriculum Vitae\\n- Pasaporte\\n- T\u00edtulo Universitario&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">&#8211; Curriculum Vitae<br \/>\n&#8211; Pasaporte<br \/>\n&#8211; T\u00edtulo Universitario<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<br \/>\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 670px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Prevenci\u00f3n Riesgos Laborales 37&quot;}\" data-sheets-formula=\"='UE - Online'!R[16]C[0]\"><strong><span style=\"color: #ff0000;\">Ma\u0301ster Universitario Prevenci\u00f3n Riesgos Laborales<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Arquitectura<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:330}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">330\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:4300}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">4.300,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:4800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">4.800,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Aprender\u00e1s a dise\u00f1ar e implantar planes de prevenci\u00f3n eficaces y a liderar la digitalizaci\u00f3n en seguridad y salud en el trabajo de sectores como ingenier\u00eda, salud, construcci\u00f3n, arquitectura, log\u00edstica y transporte, entre otros.\\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Aprender\u00e1s a dise\u00f1ar e implantar planes de prevenci\u00f3n eficaces y a liderar la digitalizaci\u00f3n en seguridad y salud en el trabajo de sectores como ingenier\u00eda, salud, construcci\u00f3n, arquitectura, log\u00edstica y transporte, entre otros.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Prevencion-Riesgos-Laborales-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Prevencion-Riesgos-Laborales-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Prevencion-Riesgos-Laborales-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Prevencion-Riesgos-Laborales-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 685px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Organizaci\u00f3n Direcci\u00f3n Centros Docentes 38&quot;}\" data-sheets-formula=\"='UE - Online'!R[17]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario Organizaci\u00f3n Direcci\u00f3n Centros Docentes<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Educaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:415}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">415\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con este programa te convertir\u00e1s en un l\u00edder educativo capaz de convertir el centro en una estructura educativa excelente, desarrollando una visi\u00f3n global de los aspectos econ\u00f3micos y financieros que te ayudar\u00e1n a desempe\u00f1ar de una manera exitosa la gesti\u00f3n directiva.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Con este programa te convertir\u00e1s en un l\u00edder educativo capaz de convertir el centro en una estructura educativa excelente, desarrollando una visi\u00f3n global de los aspectos econ\u00f3micos y financieros que te ayudar\u00e1n a desempe\u00f1ar de una manera exitosa la gesti\u00f3n directiva.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Organizacion-Direccion-Centros-Docentes-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Organizacion-Direccion-Centros-Docentes-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Organizacion-Direccion-Centros-Docentes-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Organizacion-Direccion-Centros-Docentes-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 761px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Gesti\u00f3n del Negocio Mar\u00edtimo y el Derecho Mar\u00edtimo 39&quot;}\" data-sheets-formula=\"='UE - Online'!R[18]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Gesti\u00f3n del Negocio Mar\u00edtimo y el Derecho Mar\u00edtimo<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">11 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:431}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">431\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.600,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Este programa es la oportunidad perfecta para convertirte en un profesional de la gesti\u00f3n, la log\u00edstica y el asesoramiento legal mar\u00edtimo. Te desarrollar\u00e1s profesionalmente para integrarte en un sector econ\u00f3mico en plena expansi\u00f3n, pieza clave en la econom\u00eda mundial.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Este programa es la oportunidad perfecta para convertirte en un profesional de la gesti\u00f3n, la log\u00edstica y el asesoramiento legal mar\u00edtimo. Te desarrollar\u00e1s profesionalmente para integrarte en un sector econ\u00f3mico en plena expansi\u00f3n, pieza clave en la econom\u00eda mundial.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Negocio-Maritimo-Online-1.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Negocio-Maritimo-Online-1.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Negocio-Maritimo-Online-1.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Negocio-Maritimo-Online-1.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 894px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Sistemas Integrados de Gestio\u0301n 40&quot;}\" data-sheets-formula=\"='UE - Online'!R[19]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Sistemas Integrados de Gestio\u0301n\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Ingenier\u00eda<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;14 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">14 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:386}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">386\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster en Sistemas Integrados de Gesti\u00f3n adquirir\u00e1s las competencias para trabajar en direcci\u00f3n, coordinaci\u00f3n, implementaci\u00f3n y auditor\u00eda de los sistemas integrales de gesti\u00f3n de Calidad, Medio Ambiente, PRL y Responsabilidad Social Corporativa.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Con el M\u00e1ster en Sistemas Integrados de Gesti\u00f3n adquirir\u00e1s las competencias para trabajar en direcci\u00f3n, coordinaci\u00f3n, implementaci\u00f3n y auditor\u00eda de los sistemas integrales de gesti\u00f3n de Calidad, Medio Ambiente, PRL y Responsabilidad Social Corporativa.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Sistemas-Integrados-de-Gestion-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Sistemas-Integrados-de-Gestion-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Sistemas-Integrados-de-Gestion-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Sistemas-Integrados-de-Gestion-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 740px;\" width=\"918\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Psicopedagogi\u0301a 41&quot;}\" data-sheets-formula=\"='UE - Online'!R[20]C[0]\"><strong><span style=\"color: #ff0000;\">Ma\u0301ster Universitario en Psicopedagogi\u0301a\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Educaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:415}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">415\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Oficial en Psicopedagog\u00eda te permitir\u00e1 detectar, diagnosticar, intervenir y evaluar las diferentes dificultades o situaciones que surjan en todas las etapas del desarrollo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster Oficial en Psicopedagog\u00eda te permitir\u00e1 detectar, diagnosticar, intervenir y evaluar las diferentes dificultades o situaciones que surjan en todas las etapas del desarrollo.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Psicopedagogia-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Psicopedagogia-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Psicopedagogia-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Psicopedagogia-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 668px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Logi\u0301stica 42&quot;}\" data-sheets-formula=\"='UE - Online'!R[21]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Logi\u0301stica\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Ingenier\u00eda<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;14 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">14 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">400\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.600,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.100\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con el M\u00e1ster en Log\u00edstica Online dominar\u00e1s los procesos de supply chain management y aprender\u00e1s a generar modelos de negocio disruptivos en empresas de log\u00edstica y transporte.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Con el M\u00e1ster en Log\u00edstica Online dominar\u00e1s los procesos de supply chain management y aprender\u00e1s a generar modelos de negocio disruptivos en empresas de log\u00edstica y transporte.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Logistica-ONline.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Logistica-ONline.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Logistica-ONline.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Logistica-ONline.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 731px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Ingenieri\u0301a de Organizacio\u0301n, Direccio\u0301n de Proyectos y Empresas 43&quot;}\" data-sheets-formula=\"='UE - Online'!R[22]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Ingenieri\u0301a de Organizacio\u0301n, Direccio\u0301n de Proyectos y Empresas\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ingenier\u00eda&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Ingenier\u00eda<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:553}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">553\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:7200}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">7.200,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:7700}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">7.700,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Oficial en Ingenier\u00eda de la Organizaci\u00f3n, Direcci\u00f3n de Empresas y Proyectos de la Universidad Europea, te forma para liderar la innovaci\u00f3n empresarial desde la direcci\u00f3n de operaciones, ingenier\u00eda de procesos y gesti\u00f3n de proyectos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster Oficial en Ingenier\u00eda de la Organizaci\u00f3n, Direcci\u00f3n de Empresas y Proyectos de la Universidad Europea, te forma para liderar la innovaci\u00f3n empresarial desde la direcci\u00f3n de operaciones, ingenier\u00eda de procesos y gesti\u00f3n de proyectos.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Ingenieria-de-Organizacion-Direccion-de-Proyectos-y-Empresas-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Ingenieria-de-Organizacion-Direccion-de-Proyectos-y-Empresas-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Ingenieria-de-Organizacion-Direccion-de-Proyectos-y-Empresas-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Ingenieria-de-Organizacion-Direccion-de-Proyectos-y-Empresas-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 651px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Energi\u0301as Renovables 44&quot;}\" data-sheets-formula=\"='UE - Online'!R[23]C[0]\"><strong><span style=\"color: #ff0000;\">Ma\u0301ster Universitario en Energi\u0301as Renovables\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Arquitectura<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:415}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">415\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster Online en Energ\u00edas Renovables de la Universidad Europea es el primer m\u00e1ster oficial que te prepara para dise\u00f1ar, gestionar y dirigir proyectos de generaci\u00f3n el\u00e9ctrica basados en las energ\u00edas limpias m\u00e1s actuales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster Online en Energ\u00edas Renovables de la Universidad Europea es el primer m\u00e1ster oficial que te prepara para dise\u00f1ar, gestionar y dirigir proyectos de generaci\u00f3n el\u00e9ctrica basados en las energ\u00edas limpias m\u00e1s actuales.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Energias-Renovables-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Energias-Renovables-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Energias-Renovables-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Energias-Renovables-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 772px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Derechos Humanos 45&quot;}\" data-sheets-formula=\"='UE - Online'!R[24]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Derechos Humanos<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Derecho&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Derecho<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;11 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">11 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:415}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">415\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Este programa es la oportunidad perfecta para especializarte en un \u00e1rea legal de importancia internacional y adquirir las aptitudes necesaria para trabajar en la protecci\u00f3n y defensa de los derechos humanos y en la lucha contra todas aquellas situaciones o procesos que los pongan en riesgo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Este programa es la oportunidad perfecta para especializarte en un \u00e1rea legal de importancia internacional y adquirir las aptitudes necesaria para trabajar en la protecci\u00f3n y defensa de los derechos humanos y en la lucha contra todas aquellas situaciones o procesos que los pongan en riesgo.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Derechos-Humanos-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Derechos-Humanos-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Derechos-Humanos-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Derechos-Humanos-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 700px;\" width=\"922\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario en Atencio\u0301n Temprana 46&quot;}\" data-sheets-formula=\"='UE - Online'!R[25]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario en Atencio\u0301n Temprana<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Educaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44677}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/MM\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">26\/04\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:430}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">430\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5600}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.600,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6100}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">6.100,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Atenci\u00f3n Temprana te permitir\u00e1 diagnosticar, analizar e intervenir de manera precoz, los posibles trastornos o alteraciones que puedan afectar a la evoluci\u00f3n durante los primeros cinco a\u00f1os de vida. Una etapa apasionante y decisiva para el desarrollo del lenguaje y habilidades.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster en Atenci\u00f3n Temprana te permitir\u00e1 diagnosticar, analizar e intervenir de manera precoz, los posibles trastornos o alteraciones que puedan afectar a la evoluci\u00f3n durante los primeros cinco a\u00f1os de vida. Una etapa apasionante y decisiva para el desarrollo del lenguaje y habilidades.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Atencion-Temprana-en-el-Contexto-Educativo.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Atencion-Temprana-en-el-Contexto-Educativo.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Atencion-Temprana-en-el-Contexto-Educativo.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-en-Atencion-Temprana-en-el-Contexto-Educativo.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 677px;\" width=\"923\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster Universitario Educaci\u00f3n Especial 47&quot;}\" data-sheets-formula=\"='UE - Online'!R[26]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster Universitario Educaci\u00f3n Especial\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Educaci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Educaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;oficial&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">oficial<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44880}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;13 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">13 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:415}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">415\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5400}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">5.400,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5900}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">5.900,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Destinado a aquellos profesionales que busquen especializarse en la atenci\u00f3n interdisciplinaria de las necesidades espec\u00edficas de apoyo educativo (NEAE), que presenta el ni\u00f1o durante el aprendizaje, con el fin de alcanzar su m\u00e1ximo desarrollo personal, intelectual, social y emocional.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Destinado a aquellos profesionales que busquen especializarse en la atenci\u00f3n interdisciplinaria de las necesidades espec\u00edficas de apoyo educativo (NEAE), que presenta el ni\u00f1o durante el aprendizaje, con el fin de alcanzar su m\u00e1ximo desarrollo personal, intelectual, social y emocional.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Educacion-Especial-Online.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Educacion-Especial-Online.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Educacion-Especial-Online.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-Universitario-Educacion-Especial-Online.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 700px;\" width=\"921\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol 48&quot;}\" data-sheets-formula=\"='UE - Online'!R[27]C[0]\"><span style=\"color: #ff0000;\"><strong>Ma\u0301ster en Direccio\u0301n de Fu\u0301tbol\u00a0<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Deporte&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Deporte<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44543}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\/m\/yyyy&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">15\/11\/2022<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">9 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;9 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">10 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:644}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">1.060 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:5800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">10.600 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:1000}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">1.500 \u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:6800}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">12.100 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El M\u00e1ster en Direcci\u00f3n de F\u00fatbol y Metodolog\u00edas de Juego es el \u00fanico m\u00e1ster online enfocado a mejorar las habilidades del entrenador de f\u00fatbol. Este programa te permitir\u00e1 mejorar tu desarrollo profesional y convertirte en un entrenador de \u00e9xito.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">El M\u00e1ster en Direcci\u00f3n de F\u00fatbol y Metodolog\u00edas de Juego es el \u00fanico m\u00e1ster online enfocado a mejorar las habilidades del entrenador de f\u00fatbol. Este programa te permitir\u00e1 mejorar tu desarrollo profesional y convertirte en un entrenador de \u00e9xito.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Direccion-de-Futbol.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 801px;\" width=\"919\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"206\" \/>\n<col width=\"598\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Ma\u0301ster en Arquitectura Sostenible y Bioconstruccio\u0301n 49&quot;}\" data-sheets-formula=\"='UE - Online'!R[28]C[0]\"><strong><span style=\"color: #ff0000;\">Ma\u0301ster en Arquitectura Sostenible y Bioconstruccio\u0301n\u00a0<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Area de Estudio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-2]C[1]\">Area de Estudio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arquitectura&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;2;FALSO)\">Arquitectura<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Tutilos Propios u Oficiales&quot;}\" data-sheets-formula=\"='UE - Online'!R[-3]C[2]\">Tutilos Propios u Oficiales<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;propio&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;3;FALSO)\">propio<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='UE - Online'!R[-4]C[3]\">Modalidad<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Online&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;4;FALSO)\">Online<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de Inicio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-5]C[4]\">Fecha de Inicio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;entre el 9 y 20 de noviembre cada a\u00f1o&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;5;FALSO)\">entre el 9 y 20 de noviembre cada a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n de Programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-6]C[5]\">Duraci\u00f3n de Programa<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;6;FALSO)\">6 meses<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Inversion&quot;}\" data-sheets-formula=\"='UE - Online'!R[-7]C[6]\">Inversion<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;8 cuotas&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;7;FALSO)\">8 cuotas<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Monto x cuota&quot;}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\\\ [$\u20ac-1]&quot;}\" data-sheets-formula=\"='UE - Online'!R[-8]C[7]\">Monto x cuota<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:463}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;8;FALSO)\">463\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio&quot;}\" data-sheets-formula=\"='UE - Online'!R[-9]C[8]\">Precio<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:3700}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;9;FALSO)\">3.700,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Reserva de plaza&quot;}\" data-sheets-formula=\"='UE - Online'!R[-10]C[9]\">Reserva de plaza<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:500}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;10;FALSO)\">500\u20ac<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Total&quot;}\" data-sheets-formula=\"='UE - Online'!R[-11]C[10]\">Total<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:4200}\" data-sheets-numberformat=\"{&quot;1&quot;:4,&quot;2&quot;:&quot;#,##0.00\\&quot;\u20ac\\&quot;&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;11;FALSO)\">4.200,00\u20ac<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga horaria&quot;}\" data-sheets-formula=\"='UE - Online'!R[-13]C[11]\">Carga horaria<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;12;FALSO)\">alrededor de 8h de clases semanales + 10h de estudio extra para entregar actividades y ex\u00e1menes.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma&quot;}\" data-sheets-formula=\"='UE - Online'!R[-14]C[12]\">Plataforma<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Blackboard&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;13;FALSO)\">Blackboard<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada&quot;}\" data-sheets-formula=\"='UE - Online'!R[-16]C[13]\">Bajada<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con este m\u00e1ster adquirir\u00e1s los conocimientos necesarios para ser un experto en materiales, dise\u00f1o pasivo, integraci\u00f3n de energ\u00edas renovables y soluciones que equilibren la construcci\u00f3n con el entorno natural.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;14;FALSO)\">Con este m\u00e1ster adquirir\u00e1s los conocimientos necesarios para ser un experto en materiales, dise\u00f1o pasivo, integraci\u00f3n de energ\u00edas renovables y soluciones que equilibren la construcci\u00f3n con el entorno natural.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='UE - Online'!R[-17]C[14]\">Descripci\u00f3n del programa<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Perfil profesional&quot;}\" data-sheets-formula=\"='UE - Online'!R[-18]C[15]\">Perfil profesional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='UE - Online'!R[-19]C[16]\">Requisitos<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;CV, Pasaporte y T\u00edtulo Universitario.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;17;FALSO)\">CV, Pasaporte y T\u00edtulo Universitario.<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Formas de pago&quot;}\" data-sheets-formula=\"='UE - Online'!R[-20]C[17]\">Formas de pago<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.\\n\\nUna vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago: \\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses. \\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware \\n \\nUna vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual. \\n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;18;FALSO)\">El pago de la reserva de plaza es solo con tarjeta de cr\u00e9dito, y debe realizarse en un solo pago.<\/p>\n<p>Una vez abonada la reserva de plaza, deber\u00e1s optar por una modalidad de pago:<br \/>\n1. Tarjeta de cr\u00e9dito o d\u00e9bito de la cual se debitar\u00e1 la cuota todos los meses.<br \/>\n2. O a trav\u00e9s de un link de pago online de la plataforma Flyware<\/p>\n<p>Una vez instalado en Espa\u00f1a, deber\u00e1s crear una cuenta bancaria para estudiante donde se debitar\u00e1 la cuota de manera mensual.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Link de brochure&quot;}\" data-sheets-formula=\"='UE - Online'!R[-21]C[18]\">Link de brochure<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Arquitectura-Sostenible-y-Bioconstruccion.pdf&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'UE - Online'!C1:C19;19;FALSO)\" data-sheets-hyperlink=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Arquitectura-Sostenible-y-Bioconstruccion.pdf\"><a class=\"in-cell-link\" href=\"https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Arquitectura-Sostenible-y-Bioconstruccion.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/nodsglobal.org\/wp-content\/uploads\/2021\/12\/Master-en-Arquitectura-Sostenible-y-Bioconstruccion.pdf<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PORTAFOLIO UNIVERSIDAD EUROPEA \u00bfPor qu\u00e9 estudiar en la Universidad Europea? Universidad referente en Europa con m\u00e1s prestigio. Tercera mejor universidad privada de Espa\u00f1a seg\u00fan THE World University Rankings 2021. M\u00e1s de 20 a\u00f1os ofertando los Programas de educaci\u00f3n superior. M\u00e1sters con gran experiencia y alto&#8230;<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1464","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":106,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1464\/revisions"}],"predecessor-version":[{"id":2673,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/1464\/revisions\/2673"}],"wp:attachment":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media?parent=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}