
{"id":3135,"date":"2022-08-24T20:38:06","date_gmt":"2022-08-24T20:38:06","guid":{"rendered":"https:\/\/sic.nodscloud.com\/nodsglobal\/?page_id=3135"},"modified":"2022-09-06T19:52:36","modified_gmt":"2022-09-06T19:52:36","slug":"eco-coaching-portfolio","status":"publish","type":"page","link":"https:\/\/sic.nodscloud.com\/nodsglobal\/eco-coaching-portfolio\/","title":{"rendered":"ECO COACHING &#8211; Portfolio"},"content":{"rendered":"<h1 style=\"text-align: center;\"><strong>Portfolio<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong>ECO COACHING<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff6600;\"><strong>Sobre nosotros<\/strong><\/span><\/h4>\n<p><b>ECO <\/b><span style=\"font-weight: 400;\">deriva de pensar el mundo y sus acciones de manera ecol\u00f3gica y de multiplicar un nuevo ECO de Liderazgo Consciente basado en la disciplina del Coaching Ontol\u00f3gico, logrando resultados extraordinarios en el desarrollo personal y Organizacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nuestra Propuesta es para todo aquel que quiera entrenarse para Ser un Humano diferente. Lograr mejorar resultados laborales, personales, de conciencia social y responsabilidad frente a los sue\u00f1os, metas y objetivos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estamos comprometidos a ser agentes de cambio eficaces para que las personas logren, mediante nuestros entrenamientos, potenciar su SER generando bienestar en los sistemas a los cuales pertenecen.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>El Buho:<\/b><span style=\"font-weight: 400;\"> Es la representaci\u00f3n de la trascendencia y simboliza la sabidur\u00eda y la destreza que creemos nosotros necesitan los l\u00edderes de este presente. Adem\u00e1s significa para nosotros, la quietud y el movimiento, la reflexi\u00f3n y la acci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Creemos que el mundo necesita un cambio de paradigma respecto al tipo de conversaciones tanto las que generamos como las que no somos capaces, ya que los resultados se encuentran \u00edntimamente ligados al tipo de relaciones que cultivamos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por lo anterior es que vinculamos nuestro nombre a la imagen del b\u00faho. Representaci\u00f3n de la trascendencia al mismo tiempo que simboliza la sabidur\u00eda y la destreza que consideramos, necesitan los l\u00edderes de este presente en donde tanto la quietud como el movimiento, la reflexi\u00f3n y la acci\u00f3n son fundamentales.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff6600;\"><strong>Valores<\/strong><\/span><\/h4>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Responsabilidad Social<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Confianza,\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Amorosidad<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0Alegr\u00eda\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Creatividad<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pasi\u00f3n<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><strong><span style=\"color: #ff6600;\">Misi\u00f3n<\/span><\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">Entrenar personas y empresas en su SER \u2013 HACER, a partir del aprendizaje transformacional.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff6600;\"><strong>Visi\u00f3n<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Ofrecer propuestas, desde la disciplina del coaching, con excelencia e innovaci\u00f3n colaborando con personas y organizaciones para potenciar su SER generando bienestar en los sistemas a los cuales pertenecen.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Certificaciones AEAPRO de ECO Coaching &#8211; <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.aeapro.eu\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.aeapro.eu\/<\/a><\/span><\/strong><\/h4>\n<p>La Asociaci\u00f3n Euroamericana de Profesionales en Ciencias Humanas y Sociales &#8211; AEAPro es una entidad sin \u00e1nimo de lucro fundada en el Reino de Espa\u00f1a en el a\u00f1o 2012 en calidad de organismo privado de verificaci\u00f3n y certificaci\u00f3n de competencias profesionales, tanto para individuos como para centros de formaci\u00f3n a nivel internacional en las \u00e1reas y disciplinas de las Ciencias Humanas y Sociales, Coaching, Counseling, Terapias Breves, Programaci\u00f3n Neuroling\u00fc\u00edstica, Hipnosis, Hipnosis Eriksoniana, Psicoterapia, etc., velando por un ejercicio profesional de calidad, \u00e9tico y responsable, con el fin de promover el fortalecimiento de las profesiones, los valores humanos, la cooperaci\u00f3n internacional y el intercambio de conocimiento.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Prestigio internacional de AEAPRO<\/strong><\/h4>\n<p>Pertenecer a AEAPro significa formar parte de la construcci\u00f3n profesional y \u00e9tica de las Ciencias Humanas y Sociales a nivel internacional, es ser parte de un proyecto global com\u00fan que aporta valor a su propia carrera profesional, a sus marcas y a sus emprendimientos.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Centros acreditados por AEAPRO &#8211;<span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/www.aeapro.eu\/centrosacreditados\" target=\"_blank\" rel=\"noopener\">https:\/\/www.aeapro.eu\/centrosacreditados<\/a><\/span><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4><strong><span style=\"color: #ff6600;\">Programas<\/span><\/strong><\/h4>\n<p><span style=\"font-weight: 400;\">1- Coaching Ontol\u00f3gico\/ Aval Inter. (CCO)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">2- Diplomatura en Inteligencia emocional (DIE)<\/span><\/p>\n<p>3- Diplomatura Metodolog\u00edas \u00c1giles<\/p>\n<p>4- Diplomatura en Nociones de Psicolog\u00eda para agentes de salud<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 982px;\" border=\"1\" width=\"1205\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"373\" \/>\n<col width=\"510\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Coaching Ontol\u00f3gico \/ Coaching Profesional con Aval Internacional (CCO)&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[1]C[0]\">\n<h4><strong><span style=\"color: #ff6600;\">Coaching Ontol\u00f3gico \/ Coaching Profesional con Aval Internacional (CCO)<\/span><\/strong><\/h4>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-2]C[1]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Virtual y sincr\u00f3nico&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;2;FALSO)\">Virtual y sincr\u00f3nico<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus &quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-3]C[2]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COUCHING&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;3;FALSO)\">Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COACHING<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n del Programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-4]C[3]\">Duraci\u00f3n del Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;12 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;4;FALSO)\">12 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-5]C[4]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Clases de 3 hs.\\nClases semanales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;5;FALSO)\">Clases de 3 hs.<br \/>\nClases semanales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-6]C[5]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44796}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\\&quot; de \\&quot;mmmm&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;6;FALSO)\">23 de agosto<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Horario de cursado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-7]C[6]\">Horario de cursado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;de 19 a 22 hs (ARG)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;7;FALSO)\">de 19 a 22 hs (ARG)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-8]C[7]\">Matricula en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;8;FALSO)\">65 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-9]C[8]\">Arancel en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;900 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;9;FALSO)\">900 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas en dolares&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-10]C[9]\"><\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;10;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-11]C[10]\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El certificado como COACH ONTOL\u00d3GICO PROFESIONAL es emitido por la\\nConsultora Eco Coaching SAS y el Aval Internacional por la Asociaci\u00f3n Euroamericana\\nde Profesionales en Ciencias Humanas y Sociales (AEAPro),\\nla cual es fundadora de FICOP.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;11;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-12]C[10]\">Diploma otorgado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nuestro programa avalado internacionalmente busca\\nampliar la capacidad del participante en su escucha y su\\nasertividad, permiti\u00e9ndole ser una persona m\u00e1s abierta,\\nm\u00e1s inclusiva y m\u00e1s consciente del otro, generando una\\nconciencia social que lo lleve a ser un agente de cambio\\ny transformaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;12;FALSO)\">El certificado como COACH ONTOL\u00d3GICO PROFESIONAL es emitido por la<br \/>\nConsultora Eco Coaching SAS y el Aval Internacional por la Asociaci\u00f3n Euroamericana<br \/>\nde Profesionales en Ciencias Humanas y Sociales (AEAPro),<br \/>\nla cual es fundadora de FICOP.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00bfPara qu\u00e9 sirve?&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-13]C[11]\">\u00bfPara qu\u00e9 sirve?<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;En el ejercicio profesional como Coach Ontol\u00f3gico podr\u00e1s asistir a individuos y\\nempresas, realizar capacitaciones, liderar espacios conversacionales y entrenar equipos para que mejoren su performance.\\n\\nTrabajar\u00e1s interviniendo en los dominios del lenguaje, el cuerpo y las emociones, con\\ncompetencias espec\u00edficas y gen\u00e9ricas orientadas a la concreci\u00f3n de los objetivos que\\nestos propongan.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;13;FALSO)\">Nuestro programa avalado internacionalmente busca ampliar la capacidad del participante en su escucha y su asertividad, permiti\u00e9ndole ser una persona m\u00e1s abierta,<br \/>\nm\u00e1s inclusiva y m\u00e1s consciente del otro, generando una conciencia social que lo lleve a ser un agente de cambio y transformaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-14]C[12]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;El espacio de coaching se da en sesiones acotadas en un per\u00edodo de tiempo establecido previamente entre las partes. \\nEl Coaching, como disciplina se emplea para acompa\u00f1ar a los individuos a funcionar en un nuevo entorno, mejorar sus competencias, desarrollar habilidades cognitivas, evolucionar a nivel de identidad y crecer. Es, por tanto, una herramienta para la transformaci\u00f3n.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;14;FALSO)\">En el ejercicio profesional como Coach Ontol\u00f3gico podr\u00e1s asistir a individuos y<br \/>\nempresas, realizar capacitaciones, liderar espacios conversacionales y entrenar equipos para que mejoren su performance.Trabajar\u00e1s interviniendo en los dominios del lenguaje, el cuerpo y las emociones, con competencias espec\u00edficas y gen\u00e9ricas orientadas a la concreci\u00f3n de los objetivos que estos propongan.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-15]C[13]\">Bajada del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;15;FALSO)\">El espacio de coaching se da en sesiones acotadas en un per\u00edodo de tiempo establecido previamente entre las partes.<br \/>\nEl Coaching, como disciplina se emplea para acompa\u00f1ar a los individuos a funcionar en un nuevo entorno, mejorar sus competencias, desarrollar habilidades cognitivas, evolucionar a nivel de identidad y crecer. Es, por tanto, una herramienta para la transformaci\u00f3n.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Temario&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-16]C[14]\">Temario<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.\\n- Estudios requeridos: Secundario completo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-17]C[15]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Mercado Pago\\n- Visa\\n-MasterCard\\n- UAL\u00c1\\n- PayPal\\n- Western Union&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;17;FALSO)\">&#8211; Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.<br \/>\n&#8211; Titulo Secundario<br \/>\n&#8211; Formulario de inscripci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Medios de Pagos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-18]C[16]\">Medios de Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;18;FALSO)\">Plataforma de pagos Flywire<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nota Adicional&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-19]C[17]\">Nota Adicional<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;19;FALSO)\">En Coaching Ontologico hay 4 seminarios gratuitos. Estos seminarios son a lo largo de los 12 meses y se va informando durante el cursado los d\u00edas y horarios (suelen ser al mismo horario que las clases semanales)<br \/>\n&#8211; 1re seminario: BRANDING<br \/>\n&#8211; 2do seminario: Neagrama PNL<br \/>\n&#8211; 3re seminario: Psicologia aplicada al coaching<br \/>\n&#8211; 4to seminario: Coaching Organizaviconal<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ul>\n<li>Las clases grabadas aparecen en la app al otro dia de la clase virtual (seria los mi\u00e9rcoles).<\/li>\n<li>Las clases son de aproximadamente 30 a 40 personas, pero luego est\u00e1n organizados en TRIBUS, que son mini grupos de 5\/6 personas donde tienen un coaching lider que los acompa\u00f1a personalizadamente en su formaci\u00f3n.<\/li>\n<li>En Coaching Ontologico hay MEDICIONES DE ENTENDIMIENTO (ex\u00e1menes). Son 3 en total durante la formaci\u00f3n, hay recuperatorios y se aprueban con 6:<br \/>\n&#8211; La 1ra es a los 6 meses y es multiple opci\u00f3n,<br \/>\n&#8211; La 2a a los 10 meses con el mismo formato,<br \/>\n&#8211; Y un examen final al finalizar la formaci\u00f3n que es oral.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"343\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matr\u00edcula&quot;}\"><strong>Matr\u00edcula<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa&quot;}\"><strong>Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio Inflado&quot;}\"><strong>Precio Inflado<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa Coaching Ontol\u00f3gico&quot;}\"><span style=\"color: #ff6600;\"><strong>Programa Coaching Ontol\u00f3gico<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;900 USD&quot;}\">900 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1250 USD&quot;}\">1250 USD<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Inteligencia Emocional&quot;}\"><\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\"><\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\"><\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;260 USD&quot;}\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 178px;\" width=\"1035\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"343\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/>\n<col width=\"115\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa Coaching Ontol\u00f3gico&quot;}\"><span style=\"color: #ff6600;\"><strong>Programa Coaching Ontol\u00f3gico<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valor del Programa&quot;}\"><strong>Valor del Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;900 USD&quot;}\"><strong>900 USD<\/strong><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 1&quot;}\"><strong>Opci\u00f3n 1<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;3 Pagos&quot;}\">3 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Peru\/Mexico)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:22,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Peru\/Mexico)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;900 USD&quot;}\">900 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;925 USD (462,5 c\/u)&quot;}\">925 USD (462,5 c\/u)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;960 USD (320 c\/u)&quot;}\">960 USD (320 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Chile)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:22,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Chile)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;75 USD&quot;}\">75 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;925 USD&quot;}\">925 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;950 USD (475 c\/u)&quot;}\">950 USD (475 c\/u)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;975 USD (325 c\/u)&quot;}\">975 USD (325 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 2&quot;}\"><b>Opci\u00f3n 2<\/b><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;3 Pagos&quot;}\">3 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con Tarjeta de Cr\u00e9dito&quot;}\"><strong>Pago con Tarjeta de Cr\u00e9dito<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;900 USD&quot;}\">900 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;925 USD (462,5 c\/u)&quot;}\">925 USD (462,5 c\/u)<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;960 USD (320 c\/u)&quot;}\">960 USD (320 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;*Todos los valores incluyen los 25 USD de la plataforma&quot;}\">*Todos los valores incluyen los 25 USD de la plataforma<\/td>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1120px;\" border=\"1\" width=\"1249\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"373\" \/>\n<col width=\"510\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Inteligencia emocional (DIE)&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[2]C[0]\">\n<h4><strong><span style=\"color: #ff6600;\">Diplomatura en Inteligencia Emocional (DIE)<\/span><\/strong><\/h4>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-2]C[1]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Virtual y sincr\u00f3nico&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;2;FALSO)\">Virtual y sincr\u00f3nico<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus &quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-3]C[2]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COUCHING&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;3;FALSO)\">Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COACHING<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n del Programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-4]C[3]\">Duraci\u00f3n del Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;5 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;4;FALSO)\">5 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-5]C[4]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Clases de 3 hs. \\nQuincenales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;5;FALSO)\">Clases de 3 hs.<br \/>\nQuincenales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-6]C[5]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44791}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\\&quot; de \\&quot;mmmm&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;6;FALSO)\">18 de agosto<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Horario de cursado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-7]C[6]\">Horario de cursado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\\nde 18 a 21hs (ARG)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;7;FALSO)\">de 18 a 21hs (ARG)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-8]C[7]\">Matricula en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;8;FALSO)\">65 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-9]C[8]\">Arancel en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;9;FALSO)\">195 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Cuotas en dolares&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-10]C[9]\"><\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;10;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-11]C[10]\"><\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;11;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-12]C[10]\">Diploma otorgado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Esta Diplomatura te permitir\u00e1 desarrollar un modelo de observaci\u00f3n emocional que permita ser m\u00e1s efectivos como personas y como profesionales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;12;FALSO)\">Esta Diplomatura te permitir\u00e1 desarrollar un modelo de observaci\u00f3n emocional que permita ser m\u00e1s efectivos como personas y como profesionales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00bfPara qu\u00e9 sirve?&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-13]C[11]\">\u00bfPara qu\u00e9 sirve?<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La presente Diplomatura de Inteligencia Emocional tiene como objetivo el desarrollo de habilidades que van m\u00e1s all\u00e1 de la inteligencia cognitiva y las habilidades t\u00e9cnicas de los l\u00edderes.\\nEst\u00e1 dise\u00f1ada para que aprendas sobre Inteligencia\\nemocional y puedas aplicarla en tu vida personal con la finalidad de aumentar tu salud emocional, impactando adem\u00e1s en todas aquellas personas que te rodean.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;13;FALSO)\">La presente Diplomatura de Inteligencia Emocional tiene como objetivo el desarrollo de habilidades que van m\u00e1s all\u00e1 de la inteligencia cognitiva y las habilidades t\u00e9cnicas de los l\u00edderes.<br \/>\nEst\u00e1 dise\u00f1ada para que aprendas sobre Inteligencia<br \/>\nemocional y puedas aplicarla en tu vida personal con la finalidad de aumentar tu salud emocional, impactando adem\u00e1s en todas aquellas personas que te rodean.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-14]C[12]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Luego del cursado podr\u00e1s:\\n\\n- Comprender qu\u00e9 es y por qu\u00e9 es importante la inteligencia emocional, la autenticidad y el liderazgo para alcanzar la plenitud.\\nIdentificar, gestionar y elegir desde qu\u00e9 emocionalidad comunicarte con vos mismo\/a.\\n- Mejorar tus v\u00ednculos a partir de intervenir la manera en que te comunicas con quienes te rodean.\\n- Distinguir y entender qu\u00e9 son las emociones para empatizar con tu entorno.\\n- Gestionar la incertidumbre.\\n- Contar con herramientas de auto observaci\u00f3n para desarrollar el liderazgo y autogesti\u00f3n emocional.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;14;FALSO)\">Luego del cursado podr\u00e1s:<\/p>\n<p>&#8211; Comprender qu\u00e9 es y por qu\u00e9 es importante la inteligencia emocional, la autenticidad y el liderazgo para alcanzar la plenitud.<br \/>\nIdentificar, gestionar y elegir desde qu\u00e9 emocionalidad comunicarte con vos mismo\/a.<br \/>\n&#8211; Mejorar tus v\u00ednculos a partir de intervenir la manera en que te comunicas con quienes te rodean.<br \/>\n&#8211; Distinguir y entender qu\u00e9 son las emociones para empatizar con tu entorno.<br \/>\n&#8211; Gestionar la incertidumbre.<br \/>\n&#8211; Contar con herramientas de auto observaci\u00f3n para desarrollar el liderazgo y autogesti\u00f3n emocional.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-15]C[13]\">Bajada del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Educaci\u00f3n de las Emociones.\\n- Significado.\\n- Emocionalidad.\\n- Tipos de emociones\\n- Alfabetizaci\u00f3n emocional para las relaciones. Inteligencia Emocional y sus aplicaciones. Estados de \u00c1nimo.\\n- Reconocimiento.\\n- Creencias, paradigmas y emociones en la actualidad. Comunicaci\u00f3n interior y empat\u00eda.\\n- CNV (Comunicaci\u00f3n No Violenta)\\n- El Estr\u00e9s y sus implicancias.\\n- Aprendizaje social y emocional.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;15;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Temario&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-16]C[14]\">Temario<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.\\n- Estudios requeridos: Secundario completo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;16;FALSO)\">&#8211; Educaci\u00f3n de las Emociones.<br \/>\n&#8211; Significado.<br \/>\n&#8211; Emocionalidad.<br \/>\n&#8211; Tipos de emociones<br \/>\n&#8211; Alfabetizaci\u00f3n emocional para las relaciones. Inteligencia Emocional y sus aplicaciones. Estados de \u00c1nimo.<br \/>\n&#8211; Reconocimiento.<br \/>\n&#8211; Creencias, paradigmas y emociones en la actualidad. Comunicaci\u00f3n interior y empat\u00eda.<br \/>\n&#8211; CNV (Comunicaci\u00f3n No Violenta)<br \/>\n&#8211; El Estr\u00e9s y sus implicancias.<br \/>\n&#8211; Aprendizaje social y emocional.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-17]C[15]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Mercado Pago\\n- Visa\\n-MasterCard\\n- UAL\u00c1\\n- PayPal\\n- Western Union&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;17;FALSO)\">\u00a0<span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.\\n- Titulo Secundario\u00a0\\n- Formulario de inscripci\u00f3n&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:897,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0}\">&#8211; Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.<br \/>\n&#8211; Formulario de inscripci\u00f3n<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Medios de Pagos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-18]C[16]\">Medios de Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;18;FALSO)\">\u00a0Plataforma de pagos Flywire<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nota Adicional&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-19]C[17]\">Nota Adicional<\/td>\n<td data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;19;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ul>\n<li>Las clases grabadas aparecen en la app al otro dia de la clase virtual (seria los mi\u00e9rcoles).<\/li>\n<li>Las clases son de aproximadamente 30 a 40 personas, pero luego est\u00e1n organizados en TRIBUS, que son mini grupos de 5\/6 personas donde tienen un coaching lider que los acompa\u00f1a personalizadamente en su formaci\u00f3n.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"343\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matr\u00edcula&quot;}\"><strong>Matr\u00edcula<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa&quot;}\"><strong>Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio Inflado&quot;}\"><strong>Precio Inflado<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Inteligencia Emocional&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura en Inteligencia Emocional<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;260 USD&quot;}\">260 USD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 171px;\" width=\"1095\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"343\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Inteligencia Emocional&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura en Inteligencia Emocional<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valor del Programa&quot;}\"><strong>Valor del Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\"><strong>195 USD<\/strong><\/td>\n<td style=\"text-align: left;\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 1&quot;}\"><strong>Opci\u00f3n 1<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Peru\/Mexico)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:22,&quot;2&quot;:{&quot;5&quot;:1}}\"><b>Pago con transferencia (Peru\/Mexico)<\/b><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD (110 c\/u)&quot;}\">220 USD (110 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Chile)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:21,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Chile)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;75 USD&quot;}\">75 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD&quot;}\">220 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;250 USD (125 c\/u)&quot;}\">250 USD (125 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 2&quot;}\"><strong>Opci\u00f3n 2<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con Tarjeta de Cr\u00e9dito&quot;}\"><strong>Pago con Tarjeta de Cr\u00e9dito<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD (110 c\/u)&quot;}\">220 USD (110 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;*Todos los valores incluyen los 25 USD de la plataforma&quot;}\">*Todos los valores incluyen los 25 USD de la plataforma<\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 1177px;\" border=\"1\" width=\"1021\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"373\" \/>\n<col width=\"510\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Metodolog\u00edas \u00c1giles&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[3]C[0]\">\n<h4><span style=\"color: #ff6600;\"><strong>Diplomatura en Metodolog\u00edas \u00c1giles<\/strong><\/span><\/h4>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-2]C[1]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Virtual y sincr\u00f3nico&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;2;FALSO)\">Virtual y sincr\u00f3nico<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus &quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-3]C[2]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COUCHING&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;3;FALSO)\">Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COACHING<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n del Programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-4]C[3]\">Duraci\u00f3n del Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;4 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;4;FALSO)\">4 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-5]C[4]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Clases de 3 hs. \\nQuincenales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;5;FALSO)\">Clases de 3 hs. Quincenales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-6]C[5]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44805}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\\&quot; de \\&quot;mmmm&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;6;FALSO)\">1 de septiembre<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Horario de cursado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-7]C[6]\">Horario de cursado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;de 19 a 21 hs (ARG)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;7;FALSO)\">de 19 a 21 hs (ARG)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-8]C[7]\">Matricula en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; 65 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;8;FALSO)\">65 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-9]C[8]\">Arancel en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;9;FALSO)\">195 USD<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-11]C[9]\">Diploma otorgado<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;10;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00bfPara qu\u00e9 sirve?&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-12]C[10]\">\u00bfPara qu\u00e9 sirve?<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Transitamos momentos de muchos cambios y con ello, las necesidades de las organizaciones van cambiando\\npermanentemente. La Gesti\u00f3n \u00c1gil de Proyectos permite, a trav\u00e9s del uso de diferentes herramientas, la repetici\u00f3n\\nde procesos y etapas del proyecto apuntando a obtener los mejores resultados optimizando recursos y tiempos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;11;FALSO)\">Transitamos momentos de muchos cambios y con ello, las necesidades de las organizaciones van cambiando permanentemente. La Gesti\u00f3n \u00c1gil de Proyectos permite, a trav\u00e9s del uso de diferentes herramientas, la repetici\u00f3n de procesos y etapas del proyecto apuntando a obtener los mejores resultados optimizando recursos y tiempos.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-13]C[11]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Enfrentar los contextos cambiantes con herramientas de gesti\u00f3n, de modo tal que ello permita afrontar los\\ndesaf\u00edos adecuadamente y obtener los mejores resultados.\\nResponder r\u00e1pidamente a los problemas que puedan surgir en el transcurso de un proyecto; ahorrando\\nrecursos, culminando a tiempo y cuidando el presupuesto.\\nVincular la estrategia de negocio con la ejecuci\u00f3n y la entrega de los proyectos necesarios para concretarla.\\nAplicar los contenidos y guiar a los equipos en el camino hacia lograr una agilidad autosuficiente y a su\\nautoorganizaci\u00f3n.\\nIdentificar la forma y elaborar el correcto plan de implementaci\u00f3n pr\u00e1ctica, de acuerdo a las iteraciones,\\npara ofrecer un valor \u00f3ptimo con bajo riesgo.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;12;FALSO)\">Enfrentar los contextos cambiantes con herramientas de gesti\u00f3n, de modo tal que ello permita afrontar los desaf\u00edos adecuadamente y obtener los mejores resultados.<br \/>\nResponder r\u00e1pidamente a los problemas que puedan surgir en el transcurso de un proyecto; ahorrando recursos, culminando a tiempo y cuidando el presupuesto.<br \/>\nVincular la estrategia de negocio con la ejecuci\u00f3n y la entrega de los proyectos necesarios para concretarla.<br \/>\nAplicar los contenidos y guiar a los equipos en el camino hacia lograr una agilidad autosuficiente y a su autoorganizaci\u00f3n.<br \/>\nIdentificar la forma y elaborar el correcto plan de implementaci\u00f3n pr\u00e1ctica, de acuerdo a las iteraciones, para ofrecer un valor \u00f3ptimo con bajo riesgo.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-14]C[12]\">Bajada del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Las necesidades de un proyecto cambian permanentemente. As\u00ed como tambi\u00e9n la realidad del contexto en el\\nque se desarrolla el mismo, la cual se modifica a gran velocidad y en forma permanente. La Gesti\u00f3n \u00c1gil de\\nProyectos permite, a trav\u00e9s del uso de diferentes herramientas, la repetici\u00f3n de procesos y etapas del proyecto\\napuntando a obtener los mejores resultados.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;13;FALSO)\">Las necesidades de un proyecto cambian permanentemente. As\u00ed como tambi\u00e9n la realidad del contexto en el que se desarrolla el mismo, la cual se modifica a gran velocidad y en forma permanente. La Gesti\u00f3n \u00c1gil de Proyectos permite, a trav\u00e9s del uso de diferentes herramientas, la repetici\u00f3n de procesos y etapas del proyecto<br \/>\napuntando a obtener los mejores resultados.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Temario&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-15]C[13]\">Temario<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Unidad 1: \u00bfQu\u00e9 es una metodolog\u00eda \u00e1gil? \u00bfCu\u00e1ndo y c\u00f3mo\\naplicarla?\\n\\nUnidad 2: \u00bfA qu\u00e9 llamamos un marco de trabajo SCRUM?\\n\\nUnidad 3: Eventos o ceremonias de SCRUM.\\n\\nUnidad 4: Trabajando en los requerimientos del usuario.\\n\\nUnidad 5: KANBAN.\\n\\nUnidad 6: DESIGN THINKING.\\n\\nUnidad 7: Estructuras liberadoras.\\n\\nEvaluaci\u00f3n final.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;14;FALSO)\">Unidad 1: \u00bfQu\u00e9 es una metodolog\u00eda \u00e1gil? \u00bfCu\u00e1ndo y c\u00f3mo<br \/>\naplicarla?<br \/>\nUnidad 2: \u00bfA qu\u00e9 llamamos un marco de trabajo SCRUM?<br \/>\nUnidad 3: Eventos o ceremonias de SCRUM.<br \/>\nUnidad 4: Trabajando en los requerimientos del usuario.<br \/>\nUnidad 5: KANBAN.<br \/>\nUnidad 6: DESIGN THINKING.<br \/>\nUnidad 7: Estructuras liberadoras.<br \/>\nEvaluaci\u00f3n final.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-16]C[14]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.\\n- Titulo Secundario\u00a0\\n- Formulario de inscripci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;15;FALSO)\">&#8211; Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.<br \/>\n&#8211; Titulo Secundario<br \/>\n&#8211; Formulario de inscripci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Medios de Pagos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-17]C[15]\">Medios de Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nota Adicional&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-18]C[16]\">Nota Adicional<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;17;FALSO)\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"379\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matr\u00edcula&quot;}\"><strong>Matr\u00edcula<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa&quot;}\"><strong>Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio Inflado&quot;}\"><strong>Precio Inflado<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura Metodolog\u00edas \u00c1giles&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura Metodolog\u00edas \u00c1giles<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;260 USD&quot;}\">260 USD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 135px;\" width=\"1195\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"379\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura Metodolog\u00edas \u00c1giles&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura Metodolog\u00edas \u00c1giles<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valor del Programa&quot;}\"><strong>Valor del Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\"><strong>195 USD<\/strong><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 1&quot;}\"><b>Opci\u00f3n 1<\/b><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Peru\/Mexico)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:22,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Peru\/Mexico)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD (110 c\/u)&quot;}\">220 USD (110 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Chile)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:21,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Chile)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;75 USD&quot;}\">75 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD&quot;}\">220 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;250 USD (125 c\/u)&quot;}\">250 USD (125 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 2&quot;}\"><b>Opci\u00f3n 2<\/b><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con Tarjeta de Cr\u00e9dito&quot;}\"><strong>Pago con Tarjeta de Cr\u00e9dito<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\">195 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;220 USD (110 c\/u)&quot;}\">220 USD (110 c\/u)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 703px;\" border=\"1\" width=\"1074\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"373\" \/>\n<col width=\"510\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" colspan=\"2\" rowspan=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Nociones de Psicolog\u00eda&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[4]C[0]\">\n<h4><span style=\"color: #ff6600;\"><strong>Diplomatura en Nociones de Psicolog\u00eda<\/strong><\/span><\/h4>\n<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Modalidad&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-2]C[1]\">Modalidad<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Virtual y sincr\u00f3nico&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;2;FALSO)\">Virtual y sincr\u00f3nico<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Campus &quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-3]C[2]\">Campus<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COUCHING&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;3;FALSO)\">Plataforma ZOOM, mas la Aplicaci\u00f3n de ECO COACHING<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Duraci\u00f3n del Programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-4]C[3]\">Duraci\u00f3n del Programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;4 meses&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;4;FALSO)\">4 meses<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Carga Horaria&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-5]C[4]\">Carga Horaria<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Clases de 2 hs.\\nClases semanales.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;5;FALSO)\">Clases de 2 hs. Clases semanales.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Fecha de inicio&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-6]C[5]\">Fecha de inicio<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:3,&quot;3&quot;:44810}\" data-sheets-numberformat=\"{&quot;1&quot;:5,&quot;2&quot;:&quot;d\\&quot; de \\&quot;mmmm&quot;,&quot;3&quot;:1}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;6;FALSO)\">6 de septiembre<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Horario de cursado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-7]C[6]\">Horario de cursado<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;de 19 a 21 hs (ARG)&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;7;FALSO)\">de 19 a 21 hs (ARG)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-8]C[7]\">Matricula en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot; 65 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;8;FALSO)\">65 USD<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Arancel en DOLARES&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-9]C[8]\">Arancel en DOLARES<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;210 USD&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;9;FALSO)\">210 USD<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diploma otorgado&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-11]C[9]\">Diploma otorgado<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;10;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u00bfPara qu\u00e9 sirve?&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-12]C[10]\">\u00bfPara qu\u00e9 sirve?<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Esta Diplomatura tiene por finalidad, brindar herramientas pr\u00e1cticas y nociones te\u00f3ricas desde la Psicolog\u00eda, abordar y\\ndar cuenta de la eficacia del trabajo interdisciplinario, y el efecto potenciador que brinda el nutrirse de otras disciplinas.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;11;FALSO)\">Esta Diplomatura tiene por finalidad, brindar herramientas pr\u00e1cticas y nociones te\u00f3ricas desde la Psicolog\u00eda, abordar ydar cuenta de la eficacia del trabajo interdisciplinario, y el efecto potenciador que brinda el nutrirse de otras disciplinas.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Descripci\u00f3n del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-13]C[11]\">Descripci\u00f3n del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;La presente Diplomatura tiene como objetivo el desarrollo de habilidades y\/o competencias para poder advertir\\naquellas conductas presentes en las personas que podr\u00edan hablarnos de alg\u00fan tipo de cuadro que lleva a que la\\npersona no se desarrolle adecuadamente o pueda explotar al m\u00e1ximo sus potencialidades. Aprender el potencial\\nque tiene nuestro cerebro para cambiar, y la capacidad que tenemos para ser nosotros mismos protagonistas de ese\\ncambio.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;12;FALSO)\">La presente Diplomatura tiene como objetivo el desarrollo de habilidades y\/o competencias para poder advertir aquellas conductas presentes en las personas que podr\u00edan hablarnos de alg\u00fan tipo de cuadro que lleva a que la persona no se desarrolle adecuadamente o pueda explotar al m\u00e1ximo sus potencialidades. Aprender el potencial<br \/>\nque tiene nuestro cerebro para cambiar, y la capacidad que tenemos para ser nosotros mismos protagonistas de ese cambio.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bajada del programa&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-14]C[12]\">Bajada del programa<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dada la complejidad del ser humano, de los contextos y sistemas por los que atraviesa, consideramos fundamental el\\nentrenamiento integral de los profesionales de salud, dentro de los cuales hoy nos encontramos con acompa\u00f1antes\\nterap\u00e9uticos, terapistas, m\u00e9dicos, fonoaudi\u00f3logos, kinesi\u00f3logos, solo por nombrar a alguno de ellos.&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;13;FALSO)\">Dada la complejidad del ser humano, de los contextos y sistemas por los que atraviesa, consideramos fundamental el entrenamiento integral de los profesionales de salud, dentro de los cuales hoy nos encontramos con acompa\u00f1antes terap\u00e9uticos, terapistas, m\u00e9dicos, fonoaudi\u00f3logos, kinesi\u00f3logos, solo por nombrar a alguno de ellos.<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Temario&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-15]C[13]\">Temario<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;14;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Requisitos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-16]C[14]\">Requisitos<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;- Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.\\n- Titulo Secundario\u00a0\\n- Formulario de inscripci\u00f3n&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;15;FALSO)\">&#8211; Edad m\u00ednima: 18 a\u00f1os al finalizar la cursada.<br \/>\n&#8211; Titulo Secundario<br \/>\n&#8211; Formulario de inscripci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Medios de Pagos&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-17]C[15]\">Medios de Pagos<\/td>\n<td style=\"text-align: left;\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C18;16;FALSO)\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Nota Adicional&quot;}\" data-sheets-formula=\"='portfolio ECO'!R[-18]C[16]\">Nota Adicional<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Dirigido m\u00e1s que nada para agentes de salud&quot;}\" data-sheets-formula=\"=BUSCARV(R1C1;'portfolio ECO'!C1:C19;17;FALSO)\">Dirigido m\u00e1s que nada para agentes de salud<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 67px;\" width=\"913\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"379\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\"><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matr\u00edcula&quot;}\"><strong>Matr\u00edcula<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Programa&quot;}\"><strong>Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Precio Inflado&quot;}\"><strong>Precio Inflado<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Nociones de Psicolog\u00eda para agentes de salud&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura en Nociones de Psicolog\u00eda para agentes de salud<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;210 USD&quot;}\">210 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;300 USD&quot;}\">300 USD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table dir=\"ltr\" style=\"height: 107px;\" width=\"1128\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"379\" \/>\n<col width=\"120\" \/>\n<col width=\"147\" \/>\n<col width=\"130\" \/><\/colgroup>\n<tbody>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Diplomatura en Nociones de Psicolog\u00eda para agentes de salud&quot;}\"><span style=\"color: #ff6600;\"><strong>Diplomatura en Nociones de Psicolog\u00eda para agentes de salud<\/strong><\/span><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Valor del Programa&quot;}\"><strong>Valor del Programa<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;195 USD&quot;}\"><strong>195 USD<\/strong><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 1&quot;}\"><b>Opci\u00f3n 1<\/b><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Peru\/Mexico)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:22,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Peru\/Mexico)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;210 USD&quot;}\">210 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;230 USD (115 c\/u)&quot;}\">230 USD (115 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con tranferencia (Chile)&quot;}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:21,&quot;2&quot;:{&quot;5&quot;:1}}\"><strong>Pago con transferencia (Chile)<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;75 USD&quot;}\">75 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;235 USD&quot;}\">235 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;260 USD (125 c\/u)&quot;}\">260 USD (125 c\/u)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Opcion 2&quot;}\"><strong>Opci\u00f3n 2<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Matricula&quot;}\">Matricula<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;1 Pago&quot;}\">1 Pago<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2 Pagos&quot;}\">2 Pagos<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Pago con Tarjeta de Cr\u00e9dito&quot;}\"><strong>Pago con Tarjeta de Cr\u00e9dito<\/strong><\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;65 USD&quot;}\">65 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;210 USD&quot;}\">210 USD<\/td>\n<td style=\"text-align: left;\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;230 USD (115 c\/u)&quot;}\">230 USD (115 c\/u)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portfolio ECO COACHING &nbsp; &nbsp; &nbsp; Sobre nosotros ECO deriva de pensar el mundo y sus acciones de manera ecol\u00f3gica y de multiplicar un nuevo ECO de Liderazgo Consciente basado en la disciplina del Coaching Ontol\u00f3gico, logrando resultados extraordinarios en el desarrollo personal y Organizacional&#8230;.<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3135","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/3135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/comments?post=3135"}],"version-history":[{"count":10,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/3135\/revisions"}],"predecessor-version":[{"id":3188,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/pages\/3135\/revisions\/3188"}],"wp:attachment":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media?parent=3135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}