
{"id":2575,"date":"2021-12-17T11:45:11","date_gmt":"2021-12-17T11:45:11","guid":{"rendered":"https:\/\/sic.nodscloud.com\/nodsglobal\/?p=2575"},"modified":"2021-12-17T12:54:29","modified_gmt":"2021-12-17T12:54:29","slug":"eobs-proxima-convocatoria-febrero-2022","status":"publish","type":"post","link":"https:\/\/sic.nodscloud.com\/nodsglobal\/2021\/12\/17\/eobs-proxima-convocatoria-febrero-2022\/","title":{"rendered":"EOBS &#8211; Proxima convocatoria Febrero 2022"},"content":{"rendered":"<h4><strong>Proxima convocatoria Febrero 2022<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<div class=\"gmail_default\"><b>PROMOCIONES<\/b><\/div>\n<div class=\"gmail_default\"><b>Seguimos hasta el 31 de diciembre 2021:<\/b><\/div>\n<div class=\"gmail_default\">BECA HASTA EL 75% &#8211;\u00a0 con UNIVERSIDAD o con EOBS, y de regalo: especializaci\u00f3n o programa de idiomas<\/div>\n<div class=\"gmail_default\">BECA 80% &#8211; tanto con Universidad como con EOBS, no hay regalo.<\/div>\n<div class=\"gmail_default\"><\/div>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Con la idea de que un mayor n\u00famero de alumnos opten por el pago completo al inicio del m\u00e1ster, a partir de ahora se va a ofrecer el 15% de descuento al inicio por pago completo, y el 10% si abona completo despu\u00e9s de haber abonado la reserva.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:6659,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16777215},&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:2236962},&quot;15&quot;:&quot;verdana, sans-serif&quot;}\">Con la idea de que un mayor n\u00famero de alumnos opten por el pago completo al inicio del m\u00e1ster, a partir de ahora se va a ofrecer el <strong>15% de descuento al inicio por pago completo<\/strong>, y el <strong>10% si abona completo despu\u00e9s de haber abonado la reserva de plaza<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Las clases comienzan el 07 de febrero de 2022.<\/p>\n<p>La segunda convocatoria es el 9 de mayo de 2022.<\/p>\n<p>&nbsp;<\/p>\n<p>La Universidad EOBS ha cambiado de universidad y ya NO mantiene convenio con Universidad AVILA.<br \/>\nAhora es <b>Centro Colaborador de La Universidad Cat\u00f3lica San Antonio de Murcia (UCAM).<\/b> Esta universidad est\u00e1 mejor rankeada. Dejo los links donde podr\u00e1n informarse: <a href=\"https:\/\/www.ucam.edu\/universidad\/transparencia\/rankings-academicos\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.ucam.edu\/universidad\/transparencia\/rankings-academicos&amp;source=gmail&amp;ust=1639827132834000&amp;usg=AOvVaw2fXnaBF9l3O-vHlHbquwNj\">https:\/\/www.ucam.edu\/<wbr \/>universidad\/transparencia\/<wbr \/>rankings-academicos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proxima convocatoria Febrero 2022 &nbsp; PROMOCIONES Seguimos hasta el 31 de diciembre 2021: BECA HASTA EL 75% &#8211;\u00a0 con UNIVERSIDAD o con EOBS, y de regalo: especializaci\u00f3n o programa de idiomas BECA 80% &#8211; tanto con Universidad como con EOBS, no hay regalo. Con la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-matricula"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/posts\/2575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/comments?post=2575"}],"version-history":[{"count":3,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/posts\/2575\/revisions"}],"predecessor-version":[{"id":2579,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/posts\/2575\/revisions\/2579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media\/2576"}],"wp:attachment":[{"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/media?parent=2575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/categories?post=2575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sic.nodscloud.com\/nodsglobal\/wp-json\/wp\/v2\/tags?post=2575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}